{"id":139279,"date":"2016-07-12T17:41:49","date_gmt":"2016-07-12T20:41:49","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2.jpg"},"modified":"2016-07-12T17:41:49","modified_gmt":"2016-07-12T20:41:49","slug":"sobradinho-oposicao2","status":"inherit","type":"attachment","link":"https:\/\/acaopopular.net\/jornal\/presidente-do-pt-da-bahia-confirma-candidatura-de-tiziu\/sobradinho-oposicao2\/","title":{"rendered":"sobradinho oposicao2"},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-139279","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2-300x225.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2-768x576.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2-620x465.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2-1024x768.jpg 1024w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":960,"file":"2016\/07\/sobradinho-oposicao2.jpg","sizes":{"thumbnail":{"file":"sobradinho-oposicao2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2-150x150.jpg"},"medium":{"file":"sobradinho-oposicao2-300x225.jpg","width":300,"height":225,"width_query":"300","height_query":"300","mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2-300x225.jpg"},"medium_large":{"file":"sobradinho-oposicao2-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2-768x576.jpg"},"large":{"file":"sobradinho-oposicao2-620x465.jpg","width":620,"height":465,"width_query":"620","height_query":"500","mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2-620x465.jpg"},"post-thumbnail":{"file":"sobradinho-oposicao2-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2-50x50.jpg"},"gabfire":{"file":"sobradinho-oposicao2-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2-1024x768.jpg"},"wp_rp_thumbnail":{"file":"sobradinho-oposicao2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2-150x150.jpg"},"1200x1200":{"file":"sobradinho-oposicao2-1200x960.jpg","width":1200,"height":960,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2-1200x960.jpg"},"cd-defaultloop":{"file":"sobradinho-oposicao2-160x106.jpg","width":160,"height":106,"width_query":160,"height_query":106,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2-160x106.jpg"},"600x99999":{"file":"sobradinho-oposicao2-600x960.jpg","width":600,"height":960,"filesize":57143,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2-600x960.jpg"},"full":{"file":"sobradinho-oposicao2.jpg","width":1280,"height":960,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":139277,"source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/sobradinho-oposicao2.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/139279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=139279"}]}}