{"id":139459,"date":"2016-07-13T14:27:17","date_gmt":"2016-07-13T17:27:17","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa.jpg"},"modified":"2016-07-13T14:27:17","modified_gmt":"2016-07-13T17:27:17","slug":"marcos-e-o-governador-rui-costa","status":"inherit","type":"attachment","link":"https:\/\/acaopopular.net\/jornal\/remanso-tera-prioridade-nos-investimentos-que-impulsionam-o-desenvolvimento\/marcos-e-o-governador-rui-costa\/","title":{"rendered":"Marcos e o governador Rui Costa"},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-139459","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"201\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa-300x201.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa-300x201.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa-620x416.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa-160x106.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa.jpg 670w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":670,"height":450,"file":"2016\/07\/Marcos-e-o-governador-Rui-Costa.jpg","sizes":{"thumbnail":{"file":"Marcos-e-o-governador-Rui-Costa-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa-150x150.jpg"},"medium":{"file":"Marcos-e-o-governador-Rui-Costa-300x201.jpg","width":300,"height":201,"width_query":"300","height_query":"300","mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa-300x201.jpg"},"large":{"file":"Marcos-e-o-governador-Rui-Costa-620x416.jpg","width":620,"height":416,"width_query":"620","height_query":"500","mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa-620x416.jpg"},"post-thumbnail":{"file":"Marcos-e-o-governador-Rui-Costa-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa-50x50.jpg"},"wp_rp_thumbnail":{"file":"Marcos-e-o-governador-Rui-Costa-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa-150x150.jpg"},"cd-defaultloop":{"file":"Marcos-e-o-governador-Rui-Costa-160x106.jpg","width":160,"height":106,"width_query":160,"height_query":106,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa-160x106.jpg"},"266x266":{"file":"Marcos-e-o-governador-Rui-Costa-266x266.jpg","width":266,"height":266,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa-266x266.jpg"},"cd-fea2_left2":{"file":"Marcos-e-o-governador-Rui-Costa-70x50.jpg","width":70,"height":50,"width_query":70,"height_query":50,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa-70x50.jpg"},"cd-featured_big":{"file":"Marcos-e-o-governador-Rui-Costa-670x380.jpg","width":670,"height":380,"width_query":938,"height_query":380,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa-670x380.jpg"},"cd-feathumb_big":{"file":"Marcos-e-o-governador-Rui-Costa-93x50.jpg","width":93,"height":50,"width_query":93,"height_query":50,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa-93x50.jpg"},"cd-subfea_mid2":{"file":"Marcos-e-o-governador-Rui-Costa-90x83.jpg","width":90,"height":83,"filesize":3276,"width_query":90,"height_query":83,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa-90x83.jpg"},"600x99999":{"file":"Marcos-e-o-governador-Rui-Costa-600x450.jpg","width":600,"height":450,"filesize":48762,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa-600x450.jpg"},"full":{"file":"Marcos-e-o-governador-Rui-Costa.jpg","width":670,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":139458,"source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Marcos-e-o-governador-Rui-Costa.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/139459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=139459"}]}}