{"id":140067,"date":"2016-07-18T17:56:40","date_gmt":"2016-07-18T20:56:40","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160715_110636693.jpg"},"modified":"2016-07-18T17:56:40","modified_gmt":"2016-07-18T20:56:40","slug":"img_20160715_110636693","status":"inherit","type":"attachment","link":"https:\/\/acaopopular.net\/jornal\/descaso-municipio-de-remanso-recebe-recursos-do-governo-federal-e-obras-nao-sao-entregues\/img_20160715_110636693\/","title":{"rendered":"IMG_20160715_110636693"},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-140067","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160715_110636693.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160715_110636693-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160715_110636693-300x169.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160715_110636693-768x432.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160715_110636693-620x349.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160715_110636693-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":3264,"height":1836,"file":"2016\/07\/IMG_20160715_110636693.jpg","sizes":{"thumbnail":{"file":"IMG_20160715_110636693-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160715_110636693-150x150.jpg"},"medium":{"file":"IMG_20160715_110636693-300x169.jpg","width":300,"height":169,"filesize":12440,"width_query":"300","height_query":"300","mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160715_110636693-300x169.jpg"},"medium_large":{"file":"IMG_20160715_110636693-768x432.jpg","width":768,"height":432,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160715_110636693-768x432.jpg"},"large":{"file":"IMG_20160715_110636693-620x349.jpg","width":620,"height":349,"width_query":"620","height_query":"500","mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160715_110636693-620x349.jpg"},"post-thumbnail":{"file":"IMG_20160715_110636693-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160715_110636693-50x50.jpg"},"gabfire":{"file":"IMG_20160715_110636693-1024x576.jpg","width":1024,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160715_110636693-1024x576.jpg"},"wp_rp_thumbnail":{"file":"IMG_20160715_110636693-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160715_110636693-150x150.jpg"},"600x99999":{"file":"IMG_20160715_110636693-600x1836.jpg","width":600,"height":1836,"filesize":229641,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160715_110636693-600x1836.jpg"},"full":{"file":"IMG_20160715_110636693.jpg","width":3264,"height":1836,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160715_110636693.jpg"}},"image_meta":{"aperture":"2","credit":"","camera":"XT1068","caption":"","created_timestamp":"1468580797","copyright":"","focal_length":"3.54","iso":"80","shutter_speed":"0.00017","title":"","orientation":"0","keywords":[]}},"post":140064,"source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160715_110636693.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/140067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=140067"}]}}