{"id":142843,"date":"2016-08-04T06:14:27","date_gmt":"2016-08-04T09:14:27","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/pdt-e-isaac.jpg"},"modified":"2016-08-04T06:14:27","modified_gmt":"2016-08-04T09:14:27","slug":"pdt-e-isaac","status":"inherit","type":"attachment","link":"https:\/\/acaopopular.net\/jornal\/deputado-roberto-carlos-e-pre-candidatos-a-vereador-do-pdt-se-reunem-com-paulo-bomfim\/pdt-e-isaac\/","title":{"rendered":"pdt e isaac"},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-142843","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/pdt-e-isaac.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"229\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/pdt-e-isaac-300x229.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/pdt-e-isaac-300x229.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/pdt-e-isaac-768x587.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/pdt-e-isaac-620x474.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/pdt-e-isaac.jpg 1005w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1005,"height":768,"file":"2016\/08\/pdt-e-isaac.jpg","sizes":{"thumbnail":{"file":"pdt-e-isaac-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/pdt-e-isaac-150x150.jpg"},"medium":{"file":"pdt-e-isaac-300x229.jpg","width":300,"height":229,"width_query":"300","height_query":"300","mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/pdt-e-isaac-300x229.jpg"},"medium_large":{"file":"pdt-e-isaac-768x587.jpg","width":768,"height":587,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/pdt-e-isaac-768x587.jpg"},"large":{"file":"pdt-e-isaac-620x474.jpg","width":620,"height":474,"width_query":"620","height_query":"500","mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/pdt-e-isaac-620x474.jpg"},"post-thumbnail":{"file":"pdt-e-isaac-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/pdt-e-isaac-50x50.jpg"},"600x99999":{"file":"pdt-e-isaac-600x768.jpg","width":600,"height":768,"filesize":98122,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/pdt-e-isaac-600x768.jpg"},"full":{"file":"pdt-e-isaac.jpg","width":1005,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/pdt-e-isaac.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":142841,"source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/pdt-e-isaac.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/142843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=142843"}]}}