{"id":143368,"date":"2016-08-07T09:52:00","date_gmt":"2016-08-07T12:52:00","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/carlos-sebastiao.jpg"},"modified":"2016-08-07T09:52:00","modified_gmt":"2016-08-07T12:52:00","slug":"carlos-sebastiao","status":"inherit","type":"attachment","link":"https:\/\/acaopopular.net\/jornal\/presidente-do-pt-em-uaua-sofre-atentado-politico\/carlos-sebastiao\/","title":{"rendered":"carlos sebastiao"},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-143368","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/carlos-sebastiao.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"203\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/carlos-sebastiao-300x203.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/carlos-sebastiao-300x203.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/carlos-sebastiao-768x520.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/carlos-sebastiao-620x420.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/carlos-sebastiao.jpg 935w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":935,"height":633,"file":"2016\/08\/carlos-sebastiao.jpg","sizes":{"thumbnail":{"file":"carlos-sebastiao-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/carlos-sebastiao-150x150.jpg"},"medium":{"file":"carlos-sebastiao-300x203.jpg","width":300,"height":203,"width_query":"300","height_query":"300","mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/carlos-sebastiao-300x203.jpg"},"medium_large":{"file":"carlos-sebastiao-768x520.jpg","width":768,"height":520,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/carlos-sebastiao-768x520.jpg"},"large":{"file":"carlos-sebastiao-620x420.jpg","width":620,"height":420,"width_query":"620","height_query":"500","mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/carlos-sebastiao-620x420.jpg"},"post-thumbnail":{"file":"carlos-sebastiao-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/carlos-sebastiao-50x50.jpg"},"cd-defaultloop":{"file":"carlos-sebastiao-160x106.jpg","width":160,"height":106,"width_query":160,"height_query":106,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/carlos-sebastiao-160x106.jpg"},"600x99999":{"file":"carlos-sebastiao-600x633.jpg","width":600,"height":633,"filesize":35923,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/carlos-sebastiao-600x633.jpg"},"full":{"file":"carlos-sebastiao.jpg","width":935,"height":633,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/carlos-sebastiao.jpg"}},"image_meta":{"aperture":"2","credit":"","camera":"XT1068","caption":"","created_timestamp":"1470238610","copyright":"","focal_length":"3.54","iso":"80","shutter_speed":"0.01552","title":"","orientation":"0","keywords":[]}},"post":143367,"source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/carlos-sebastiao.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/143368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=143368"}]}}