{"id":144162,"date":"2016-08-11T08:33:17","date_gmt":"2016-08-11T11:33:17","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3.jpg"},"modified":"2016-08-11T08:33:17","modified_gmt":"2016-08-11T11:33:17","slug":"escuro3","status":"inherit","type":"attachment","link":"https:\/\/acaopopular.net\/jornal\/escuridao-toma-conta-do-municipio-de-pilao-arcado\/escuro3\/","title":{"rendered":"escuro3"},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-144162","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-225x300.jpg 225w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-230x307.jpg 230w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-160x213.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3.jpg 360w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":360,"height":480,"file":"2016\/08\/escuro3.jpg","sizes":{"thumbnail":{"file":"escuro3-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-150x150.jpg"},"medium":{"file":"escuro3-225x300.jpg","width":225,"height":300,"width_query":"300","height_query":"300","mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-225x300.jpg"},"large":{"file":"escuro3-230x307.jpg","width":230,"height":307,"width_query":"464","height_query":"307","mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-230x307.jpg"},"cd-teaser1":{"file":"escuro3-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-80x60.jpg"},"cd-teaser2":{"file":"escuro3-118x88.jpg","width":118,"height":88,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-118x88.jpg"},"cd-featured_big":{"file":"escuro3-360x380.jpg","width":360,"height":380,"width_query":938,"height_query":380,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-360x380.jpg"},"cd-feathumb_big":{"file":"escuro3-93x50.jpg","width":93,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-93x50.jpg"},"cd-fea2_left1":{"file":"escuro3-360x300.jpg","width":360,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-360x300.jpg"},"cd-fea2_left2":{"file":"escuro3-70x50.jpg","width":70,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-70x50.jpg"},"cd-fea2_right":{"file":"escuro3-70x45.jpg","width":70,"height":45,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-70x45.jpg"},"cd-subfea_left":{"file":"escuro3-160x213.jpg","width":160,"height":213,"width_query":160,"height_query":999,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-160x213.jpg"},"cd-subfea_mid1":{"file":"escuro3-360x300.jpg","width":360,"height":300,"width_query":450,"height_query":300,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-360x300.jpg"},"cd-subfea_mid2":{"file":"escuro3-90x83.jpg","width":90,"height":83,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-90x83.jpg"},"cd-subfea_right":{"file":"escuro3-70x45.jpg","width":70,"height":45,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-70x45.jpg"},"cd-subfea_bottom":{"file":"escuro3-200x145.jpg","width":200,"height":145,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-200x145.jpg"},"cd-secondary_left1":{"file":"escuro3-90x83.jpg","width":90,"height":83,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-90x83.jpg"},"cd-secondary_left2":{"file":"escuro3-200x145.jpg","width":200,"height":145,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-200x145.jpg"},"cd-secondary_right":{"file":"escuro3-360x270.jpg","width":360,"height":270,"width_query":480,"height_query":270,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-360x270.jpg"},"cd-subnews":{"file":"escuro3-225x123.jpg","width":225,"height":123,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-225x123.jpg"},"cd-defaultloop":{"file":"escuro3-160x106.jpg","width":160,"height":106,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-160x106.jpg"},"cd-2colloop":{"file":"escuro3-310x200.jpg","width":310,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-310x200.jpg"},"cd-medialoop":{"file":"escuro3-290x200.jpg","width":290,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-290x200.jpg"},"cd-mag1":{"file":"escuro3-360x290.jpg","width":360,"height":290,"width_query":630,"height_query":290,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-360x290.jpg"},"cd-mag2":{"file":"escuro3-305x150.jpg","width":305,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-305x150.jpg"},"ajaxtabs":{"file":"escuro3-30x30.jpg","width":30,"height":30,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3-30x30.jpg"},"600x99999":{"source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3.jpg"},"full":{"file":"escuro3.jpg","width":360,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":144160,"source_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/escuro3.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/144162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=144162"}]}}