{"id":140402,"date":"2016-07-20T08:22:34","date_gmt":"2016-07-20T11:22:34","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=140402"},"modified":"2016-07-20T08:22:35","modified_gmt":"2016-07-20T11:22:35","slug":"delegado-charles-leao-agradece-empenho-dos-policiais-na-apreensao-de-acusado-que-furtou-a-sua-residencia","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/delegado-charles-leao-agradece-empenho-dos-policiais-na-apreensao-de-acusado-que-furtou-a-sua-residencia\/","title":{"rendered":"Delegado Charles Le\u00e3o agradece empenho dos policiais na apreens\u00e3o de acusado que furtou a sua resid\u00eancia"},"content":{"rendered":"<p class=\"x_MsoNormal\" style=\"text-align: justify;\">\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Em nota, a assessoria informa que o Delegado tomou conhecimento sobre a pris\u00e3o do acusado de furto a sua resid\u00eancia, e informa ainda que Giltean j\u00e1 foi apreendido pelo delegado Charles Le\u00e3o h\u00e1 seis anos, quando este era menor e usu\u00e1rio de drogas.<\/p>\n<figure id=\"attachment_140403\" aria-describedby=\"caption-attachment-140403\" style=\"width: 464px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/acaopopular.net\/jornal\/delegado-charles-leao-agradece-empenho-dos-policiais-na-apreensao-de-acusado-que-furtou-a-sua-residencia\/img_20160630_102051612\/\" rel=\"attachment wp-att-140403\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-140403 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160630_102051612-464x261.jpg\" alt=\"IMG_20160630_102051612\" width=\"464\" height=\"261\" \/><\/a><figcaption id=\"caption-attachment-140403\" class=\"wp-caption-text\">Charles Le\u00e3o<\/figcaption><\/figure>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">O Delegado agradece o empenho dos Policiais Militares pelo excelente trabalho efetuado. Ressalta ainda que toda a a\u00e7\u00e3o foi acompanhada pela 76 CIPM sob o comando de Souza Junior. Agradece tamb\u00e9m o empenho dos Policiais Jos\u00e9 Diego\u00a0 e David Manoel Batata, al\u00e9m do apoio de todos da\u00a0 guarni\u00e7\u00e3o da Peto,\u00a0 da Rondesp Norte e CIPE Caatinga (CEPAC),\u00a0 assim como a participa\u00e7\u00e3o dos guerreiros da seguran\u00e7a que Tamb\u00e9m contribu\u00edram com informa\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Em nota, a assessoria informa que o Delegado tomou conhecimento sobre a pris\u00e3o do acusado de furto a sua resid\u00eancia, e informa ainda que Giltea<\/p>\n","protected":false},"author":5,"featured_media":140403,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4,6],"tags":[],"class_list":["post-140402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/IMG_20160630_102051612.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/140402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=140402"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/140402\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/140403"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=140402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=140402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=140402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}