{"id":140835,"date":"2016-07-22T04:48:27","date_gmt":"2016-07-22T07:48:27","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=140835"},"modified":"2016-07-22T04:48:27","modified_gmt":"2016-07-22T07:48:27","slug":"ivete-sangalo-aparece-a-vontade-em-ensaio-para-a-gravacao-do-dvd","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/ivete-sangalo-aparece-a-vontade-em-ensaio-para-a-gravacao-do-dvd\/","title":{"rendered":"Ivete Sangalo aparece \u00e0 vontade em ensaio para a grava\u00e7\u00e3o do DVD"},"content":{"rendered":"<header>\n<h1><\/h1>\n<\/header>\n<div class=\"story\">\n<div class=\"header\">\n<figure class=\"vertical_inline\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/extra.globo.com\/incoming\/19762854-017-900\/w448h673-PROP\/ivete02.jpg\" width=\"448\" height=\"673\" \/><figcaption>Ivete de short e camiseta no ensaio Foto: Reprodu\u00e7\u00e3o do Instagram<\/figcaption><\/figure>\n<\/div>\n<p>Aos poucos, <a class=\"tv\" href=\"http:\/\/extra.globo.com\/tv-e-lazer\/ivete-sangalo\/\" rel=\"follow\">Ivete Sangalo<\/a> come\u00e7a a mostrar o que os f\u00e3s encontrar\u00e3o no DVD gravado em Trancoso, que ser\u00e1 lan\u00e7ado na pr\u00f3xima quarta-feira, em S\u00e3o Paulo. No v\u00eddeo que postou em seu canal do Youtube, a cantora aparece bem \u00e0 vontade, de short e camiseta, tocando viol\u00e3o na m\u00fasica \u201cDeixo\u201d. As imagens do ensaio s\u00e3o intercaladas pelas da grava\u00e7\u00e3o oficial.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=YVRDeiTMWhA\" target=\"_blank\">Clique aqui e veja o v\u00eddeo.<\/a><\/p>\n<p>Al\u00e9m disso, o v\u00eddeo tamb\u00e9m traz o depoimento de uma f\u00e3 sobre Ivete e a cantora reconhecendo que este trabalho \u00e9 diferente dos outros que j\u00e1 fez.<\/p>\n<figure><img decoding=\"async\" class=\"inline\" src=\"http:\/\/extra.globo.com\/incoming\/19762813-34f-de9\/w448\/ivete-sangalo.jpg\" alt=\"Ivete ensaiando a m\u00fasica \" \/><figcaption>Ivete ensaiando a m\u00fasica &#8220;Deixo&#8221; Foto: Reprodu\u00e7\u00e3o de v\u00eddeo<\/figcaption><\/figure>\n<p>\u201c\u00c9 um disco mais autoral, eu tenho mais m\u00fasicas nesse disco. Estou tocando mais instrumentos nesse show, me jogando totalmente\u201d, explica a baiana.<\/p>\n<div class=\"embeddedInstagramInline\" align=\"center\">\n<div class=\"instagram-19762863\"><iframe loading=\"lazy\" id=\"instagram-embed-0\" class=\"instagram-media instagram-media-rendered\" src=\"https:\/\/www.instagram.com\/p\/BIGlFmDgCQX\/embed\/captioned\/?v=7\" width=\"300\" height=\"414\" frameborder=\"0\" scrolling=\"no\" data-instgrm-payload-id=\"instagram-media-payload-0\"><\/iframe><\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aos poucos, Ivete Sangalo come\u00e7a a mostrar o que os f\u00e3s encontrar\u00e3o no DVD gravado em Trancoso, que ser\u00e1 lan\u00e7ado na pr\u00f3xima qua<\/p>\n","protected":false},"author":5,"featured_media":140836,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-140835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/ivete02.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/140835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=140835"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/140835\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/140836"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=140835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=140835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=140835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}