{"id":140915,"date":"2016-07-23T08:25:16","date_gmt":"2016-07-23T11:25:16","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=140915"},"modified":"2016-07-23T08:25:16","modified_gmt":"2016-07-23T11:25:16","slug":"remanso-vereador-doutor-faz-opcao-por-marcos-palmeira-e-agita-cenario-politico","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/remanso-vereador-doutor-faz-opcao-por-marcos-palmeira-e-agita-cenario-politico\/","title":{"rendered":"Remanso: Vereador Doutor faz op\u00e7\u00e3o por Marcos Palmeira e agita cen\u00e1rio pol\u00edtico"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-140916\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/doutormarcos-remanso-409x307.jpg\" alt=\"doutormarcos-remanso\" width=\"409\" height=\"307\" \/><\/p>\n<p style=\"text-align: justify;\">Na manh\u00e3 de ontem (22), o Presidente da C\u00e2mara de Vereadores, Jos\u00e9 Ailton Rodrigues da Silva (Doutor \u2013 PTC), que j\u00e1 tem tr\u00eas mandatos consecutivos e foi eleito em 2012 com 1.200 votos, lideran\u00e7a em dezenas de povoados do munic\u00edpio, que \u00e9 predominantemente rural, fez p\u00fablica a sua op\u00e7\u00e3o pela pr\u00e9-candidatura de Marcos Palmeira (PC do B) que tem como vice o Professor Fl\u00e1vio da UNIFAN.<\/p>\n<p style=\"text-align: justify;\">Fiel ao seu estilo, o Vereador Doutor preparou uma festa que reuniu mais de quinhentas pessoas vindas dos diversos recantos do munic\u00edpio, e fez um discurso declara\u00e7\u00e3o que empolgou o plen\u00e1rio lotado da C\u00e2mara de Vereadores: \u201cSei que me elejo, mas para mim o importante \u00e9 eleger Marcos Palmeira. Chega de tanto descaso, chega de cuidar de poucos, chega de prefeitura para o mesmo grupo\u201d.<\/p>\n<p style=\"text-align: justify;\">Em plena manh\u00e3 de sexta-feira, \u201cpara mostrar que quem est\u00e1 aqui veio para atender meu pedido\u201d, com a C\u00e2mara e as ruas adjacentes lotadas de gente do interior, Doutor deu um recado, quase uma senten\u00e7a final para o advers\u00e1rio de Marcos Palmeira\u201d \u201cVamos ganhar no interior todo e levar respeito \u00e0s pessoas do campo. Vamos fazer diferente e quero garantir, porque voc\u00eas me conhecem, que vou cobrar do Dr. Marcos trabalho e mais trabalho\u201d.<\/p>\n<p style=\"text-align: justify;\">Um dos mais aplaudidos dos presentes \u00e0 Mesa foi o ex-prefeito Renato Rosal, que juntamente com os presidentes dos partidos PV, presidente do PC do B, PPS, participaram do ato de apoio e alian\u00e7a entre o PC do B e o PTC. Estavam presentes pr\u00e9-candidatos a vereador, o Vereador Humberto e presidentes de associa\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">Para Marcos Palmeira \u201cDoutor \u00e9 um dos vereadores que n\u00e3o fogem do povo, ao contr\u00e1rio, ele insiste, fala, senta \u00e0 mesa, caminha junto, divide as preocupa\u00e7\u00f5es das comunidades e cobra\u201d, considerando seu apoio \u201cum dos mais importantes nessa caminhada da pr\u00e9-campanha\u201d.<\/p>\n<p style=\"text-align: justify;\">O apoio do Presidente da C\u00e2mara estilha\u00e7a a base de apoio do advers\u00e1rio de Marcos Palmeira e \u00e9 o \u00e1pice de uma sequ\u00eancia de golpes pol\u00edticos que vem sofrendo na \u00faltima semana: problemas na Justi\u00e7a e indefini\u00e7\u00e3o sobre se \u00e9 ou n\u00e3o candidato; falta de sucesso em se desligar da imagem do atual prefeito, que pelo visto, ser\u00e1 seu \u00faltimo aliado e o envio de diversas representa\u00e7\u00f5es \u00e0 Justi\u00e7a Eleitoral local por estar utilizando as redes sociais em campanha antecipada e pagando para impulsionar curtidas no Facebook.<\/p>\n<p style=\"text-align: justify;\">As ruas da cidade refletem esta agita\u00e7\u00e3o. Em Remanso a campanha est\u00e1 a pleno vapor, tocada pelo desespero de quem n\u00e3o quer deixar o poder que det\u00e9m h\u00e1 12 anos ininterruptos, mas, para Clementino as coisas n\u00e3o andam boas.<\/p>\n<p style=\"text-align: justify;\">Manoel Le\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 de ontem (22), o Presidente da C\u00e2mara de Vereadores, Jos\u00e9 Ailton Rodrigues da Silva (Doutor \u2013 PTC), que j\u00e1 tem tr\u00eas mandatos consecutivos e foi eleito em 2012 com 1.200 votos, lideran\u00e7a em dezenas de povoados do munic\u00edpio, que \u00e9 predominantemente rural, fez p\u00fablica a sua op\u00e7\u00e3o pela pr\u00e9-candidatura de Marcos Palmeira (PC [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":140916,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4,6],"tags":[],"class_list":["post-140915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/doutormarcos-remanso.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/140915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=140915"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/140915\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/140916"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=140915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=140915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=140915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}