{"id":140954,"date":"2016-07-24T15:07:58","date_gmt":"2016-07-24T18:07:58","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=140954"},"modified":"2016-07-24T15:07:59","modified_gmt":"2016-07-24T18:07:59","slug":"convencao-do-pmdb-homologa-edinaldo-lima-como-candidato-em-petrolina-veja-as-imagens","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/convencao-do-pmdb-homologa-edinaldo-lima-como-candidato-em-petrolina-veja-as-imagens\/","title":{"rendered":"Conven\u00e7\u00e3o do PMDB homologa Edinaldo Lima como candidato, em Petrolina; veja as imagens"},"content":{"rendered":"<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><strong>A\u00e7\u00e3o Popular (AP)<\/strong><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">O PMDB homologou ontem (23) a candidatura de prefeito do ex-secret\u00e1rio de Habita\u00e7\u00e3o, Edinaldo Lima (PMDB), e o do seu vice, Newton Matsumoto (PMDB). O evento foi realizado no Centro de Conven\u00e7\u00f5es de Petrolina e contou com a participa\u00e7\u00e3o da popula\u00e7\u00e3o, lideran\u00e7as pol\u00edticas, pr\u00e9-candidatos a vereadores, entre outros.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/convencao-do-pmdb-homologa-edinaldo-lima-como-candidato-em-petrolina-veja-as-imagens\/convencao-pmdb13\/\" rel=\"attachment wp-att-140960\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-140960 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao-pmdb13-464x261.jpg\" alt=\"convencao pmdb13\" width=\"464\" height=\"261\" \/><\/a><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Na coliga\u00e7\u00e3o \u201cPra continuar avan\u00e7ando\u201d, o PMDB conta com os partidos PSL, PHS e PPS. Nos discursos feitos durante o ato pol\u00edtico o que n\u00e3o faltou foi recados para o deputado federal Guilherme Coelho (PSDB) e o senador Fernando Bezerra (PSB), que anunciaram na \u00faltima quarta-feira (20) a reunifica\u00e7\u00e3o pol\u00edtica da Fam\u00edlia Coelho.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/convencao-do-pmdb-homologa-edinaldo-lima-como-candidato-em-petrolina-veja-as-imagens\/convencao-pmdb3\/\" rel=\"attachment wp-att-140963\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-140963 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao-pmdb3-409x307.jpg\" alt=\"convencao pmdb3\" width=\"409\" height=\"307\" \/><\/a><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">O presidente do PMDB Jovem, J\u00falio L\u00f3ssio Filho, abriu os discursos e rebateu as declara\u00e7\u00f5es Guilherme que revogou uma filia\u00e7\u00e3o afetiva de Oswaldo Coelho (DEM) com o prefeito da cidade.<span class=\"x_apple-converted-space\">\u00a0<\/span>\u201cQuem quiser pode ficar com a heran\u00e7a de Dr. Oswaldo porque ela foi feita para ser dividida e aqui a gente s\u00f3 soma e multiplica. J\u00e1 temos o legado dele e estamos aqui hoje porque esse sonho Dr. Oswaldo que o prefeito Lossio come\u00e7ou a realizar com a Nova Semente, as Ames, com o Minha Casa, Minha Vida. Enquanto muitos pol\u00edticos decepcionam e fazem a gente perder a esperan\u00e7a, \u00e9 gente como Ednaldo Lima, como o prefeito J\u00falio L\u00f3ssio, Oswaldo Coelho que nos davam esperan\u00e7a porque no lugar de Lava a Jato a gente lava a alma das pessoas com mais educa\u00e7\u00e3o, dando oportunidade, dando emprego e dando renda\u201d, alfinetou.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/convencao-do-pmdb-homologa-edinaldo-lima-como-candidato-em-petrolina-veja-as-imagens\/convencao-pmdb8\/\" rel=\"attachment wp-att-140968\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-140968 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao-pmdb8-464x261.jpg\" alt=\"convencao pmdb8\" width=\"464\" height=\"261\" \/><\/a><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Por sua vez, o vice-prefeito Newton Matsumoto, falou sobre os motivos que o levaram a aceitar o convite para assumir a vice na chapa. \u201cEu recebi o convite de Ednaldo e do prefeito J\u00falio e resolvi aceitar. Entrei nesta luta por essa filosofia que J\u00falio ensinou a todos n\u00f3s que a sociedade, o bem p\u00fablico est\u00e1 acima, que uma pessoa n\u00e3o \u00e9 eleita para se beneficiar pessoalmente, mas sim para beneficiar aquela parcela da popula\u00e7\u00e3o mais necessitada. N\u00f3s vamos vencer, pois os nossos cora\u00e7\u00f5es s\u00e3o verdes e esperamos contar com o apoio de todos voc\u00eas\u201d.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/convencao-do-pmdb-homologa-edinaldo-lima-como-candidato-em-petrolina-veja-as-imagens\/convencao-pmdb6\/\" rel=\"attachment wp-att-140966\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-140966 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao-pmdb6-464x261.jpg\" alt=\"convencao pmdb6\" width=\"464\" height=\"261\" \/><\/a><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Ao discursar, o prefeito Julio Lossio, agradeceu a presen\u00e7a de todos e enalteceu Edinaldo por sua honestidade. \u201cEdinaldo administrou R$ 1 bilh\u00e3o que foram investidos nas 10 mil moradias e n\u00e3o houve uma den\u00fancia sequer de irregularidades contra ele. A gente deixa de heran\u00e7a o patrim\u00f4nio que a gente faz. Voc\u00eas n\u00e3o s\u00e3o propriedades para ser herdada por ningu\u00e9m. Tem gente que diz &#8216;ama Petrolina&#8217;, mas n\u00e3o mora aqui. Gente que ama esta cidade mas n\u00e3o vota aqui. E o projeto? Ednaldo foi o escolhido porque ele ama voc\u00eas, tenham cuidado quando voc\u00eas forem votar\u201d, alertou.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/convencao-do-pmdb-homologa-edinaldo-lima-como-candidato-em-petrolina-veja-as-imagens\/convencao-pmdb7\/\" rel=\"attachment wp-att-140967\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-140967 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao-pmdb7-464x261.jpg\" alt=\"convencao pmdb7\" width=\"464\" height=\"261\" \/><\/a><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">O candidato a prefeito Ednaldo lembrou a import\u00e2ncia de manter os investimentos da atual gest\u00e3o e agradeceu a Lossio pela oportunidade. \u201cObrigado ao prefeito Lossio pelas experi\u00eancias e por ter constru\u00eddo a nossa chapa, as primeiras caminhadas n\u00e3o foram f\u00e1ceis, muitos chegavam e diziam que era para eu desistir, mas eu acreditei neste governo. O sonho precisa continuar e a esperan\u00e7a n\u00e3o pode morrer. Estamos aqui para convidar voc\u00eas para uma grande caminhada e voc\u00eas precisam acreditar, n\u00f3s vamos vencer\u201d, concluiu.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">\u00a0\u00a0<a href=\"https:\/\/acaopopular.net\/jornal\/convencao-do-pmdb-homologa-edinaldo-lima-como-candidato-em-petrolina-veja-as-imagens\/convencao-pmdb-10\/\" rel=\"attachment wp-att-140957\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-140957 size-large alignleft\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao-pmdb-10-464x261.jpg\" alt=\"convencao pmdb 10\" width=\"464\" height=\"261\" \/><\/a> <a href=\"https:\/\/acaopopular.net\/jornal\/convencao-do-pmdb-homologa-edinaldo-lima-como-candidato-em-petrolina-veja-as-imagens\/convencao-pmdb11\/\" rel=\"attachment wp-att-140958\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-140958 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao-pmdb11-464x261.jpg\" alt=\"convencao pmdb11\" width=\"464\" height=\"261\" \/><\/a> <a href=\"https:\/\/acaopopular.net\/jornal\/convencao-do-pmdb-homologa-edinaldo-lima-como-candidato-em-petrolina-veja-as-imagens\/convencao-pmdb12\/\" rel=\"attachment wp-att-140959\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-140959 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao-pmdb12-464x261.jpg\" alt=\"convencao pmdb12\" width=\"464\" height=\"261\" \/><\/a> <a href=\"https:\/\/acaopopular.net\/jornal\/convencao-do-pmdb-homologa-edinaldo-lima-como-candidato-em-petrolina-veja-as-imagens\/convencao-pmdb13\/\" rel=\"attachment wp-att-140960\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-140960 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao-pmdb13-464x261.jpg\" alt=\"convencao pmdb13\" width=\"464\" height=\"261\" \/><\/a>\u00a0\u00a0\u00a0\u00a0<a href=\"https:\/\/acaopopular.net\/jornal\/convencao-do-pmdb-homologa-edinaldo-lima-como-candidato-em-petrolina-veja-as-imagens\/convencao-pmdb4\/\" rel=\"attachment wp-att-140964\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-140964 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao-pmdb4-464x261.jpg\" alt=\"convencao pmdb4\" width=\"464\" height=\"261\" \/><\/a> \u00a0<a href=\"https:\/\/acaopopular.net\/jornal\/convencao-do-pmdb-homologa-edinaldo-lima-como-candidato-em-petrolina-veja-as-imagens\/convencao-pmdb6\/\" rel=\"attachment wp-att-140966\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-140966 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao-pmdb6-464x261.jpg\" alt=\"convencao pmdb6\" width=\"464\" height=\"261\" \/><\/a>\u00a0\u00a0<a href=\"https:\/\/acaopopular.net\/jornal\/convencao-do-pmdb-homologa-edinaldo-lima-como-candidato-em-petrolina-veja-as-imagens\/convencao-pmdb8\/\" rel=\"attachment wp-att-140968\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-140968 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao-pmdb8-464x261.jpg\" alt=\"convencao pmdb8\" width=\"464\" height=\"261\" \/><\/a> <a href=\"https:\/\/acaopopular.net\/jornal\/convencao-do-pmdb-homologa-edinaldo-lima-como-candidato-em-petrolina-veja-as-imagens\/convencao-pmdb9\/\" rel=\"attachment wp-att-140969\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-140969 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao-pmdb9-464x261.jpg\" alt=\"convencao pmdb9\" width=\"464\" height=\"261\" \/><\/a><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>O PMDB homologou ontem (23) a candidatura de prefeito do ex-secret\u00e1rio de Habita\u00e7\u00e3o, Edinaldo Lima (PMDB), e o do seu vice, Newton Matsumoto (PMDB)<\/p>\n","protected":false},"author":5,"featured_media":140965,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4,6],"tags":[],"class_list":["post-140954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao-pmdb5-capa-1.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/140954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=140954"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/140954\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/140965"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=140954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=140954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=140954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}