{"id":141028,"date":"2016-07-25T02:49:25","date_gmt":"2016-07-25T05:49:25","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=141028"},"modified":"2016-07-25T02:49:25","modified_gmt":"2016-07-25T05:49:25","slug":"em-convencao-pmdb-oficializa-edinaldo-lima-e-newton-matsumoto","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/em-convencao-pmdb-oficializa-edinaldo-lima-e-newton-matsumoto\/","title":{"rendered":"Em conven\u00e7\u00e3o PMDB oficializa Edinaldo Lima e Newton Matsumoto"},"content":{"rendered":"<p dir=\"ltr\" style=\"text-align: justify;\"><b>\u00a0<\/b><\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Foi dada a largada para as elei\u00e7\u00f5es municipais em Petrolina. Nesta s\u00e1bado (23)\u00a0 aconteceu a conven\u00e7\u00e3o que oficializou a uni\u00e3o do PMDB, PSL, PPS e PHS para compor a coliga\u00e7\u00e3o \u201cPra continuar avan\u00e7ando\u201d. O evento lan\u00e7ou, oficialmente, as candidaturas dos peemedebistas Edinaldo Lima e Newton Matsumoto (Newtinho) para concorrer aos cargos de prefeito e vice-prefeito de Petrolina nas elei\u00e7\u00f5es de outubro. Al\u00e9m dos candidatos ao executivo municipal, o evento apresentou os 39 postulantes ao legislativo do munic\u00edpio, que fazem parte dos partidos que comp\u00f5em o bloco.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/em-convencao-pmdb-oficializa-edinaldo-lima-e-newton-matsumoto\/convencao5\/\" rel=\"attachment wp-att-141033\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-141033\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao5-300x199.jpg\" alt=\"convencao5\" width=\"300\" height=\"199\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao5-300x199.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao5-768x511.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao5-620x412.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao5-1024x681.jpg 1024w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao5.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">O prefeito de Petrolina, Julio Lossio, foi o anfitri\u00e3o da festa que contou com uma presen\u00e7a muito grande de correligion\u00e1rios que lotaram o p\u00e1tio de feiras do Centro de Conven\u00e7\u00f5es. Al\u00e9m dos candidatos petrolinenses, estiveram presentes o pr\u00e9-candidatos a prefeito de Santa Cruz da Venerada, Pe. Paulo S\u00e9rgio; de Lagoa Grande, Vilmar Cappellaro, e de Afr\u00e2nio, Rafael Peron, al\u00e9m dos presidentes municipais do PSL, PPS e PHS.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/em-convencao-pmdb-oficializa-edinaldo-lima-e-newton-matsumoto\/convencao3-2\/\" rel=\"attachment wp-att-141031\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-141031 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao3-430x307.jpg\" alt=\"convencao3\" width=\"430\" height=\"307\" \/><\/a> <a href=\"https:\/\/acaopopular.net\/jornal\/em-convencao-pmdb-oficializa-edinaldo-lima-e-newton-matsumoto\/convencao2-2\/\" rel=\"attachment wp-att-141030\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-141030 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao2-430x307.jpg\" alt=\"convencao2\" width=\"430\" height=\"307\" \/><\/a> <a href=\"https:\/\/acaopopular.net\/jornal\/em-convencao-pmdb-oficializa-edinaldo-lima-e-newton-matsumoto\/convencao1-2\/\" rel=\"attachment wp-att-141029\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-141029 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao1-460x307.jpg\" alt=\"convencao1\" width=\"460\" height=\"307\" \/><\/a><\/p>\n<div style=\"text-align: justify;\"><b>ASCOM PMDB PETROLINA<\/b><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foi dada a largada para as elei\u00e7\u00f5es municipais em Petrolina. Nesta s\u00e1bado (23)  aconteceu a conven\u00e7\u00e3o que oficializou a uni\u00e3o do PMDB, PSL, PPS e PHS p<\/p>\n","protected":false},"author":5,"featured_media":141032,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-141028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/convencao4.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/141028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=141028"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/141028\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/141032"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=141028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=141028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=141028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}