{"id":141732,"date":"2016-07-28T08:12:52","date_gmt":"2016-07-28T11:12:52","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=141732"},"modified":"2016-07-28T08:12:52","modified_gmt":"2016-07-28T11:12:52","slug":"o-preco-da-chatice-agenda-de-paula-fernandes-diminui-mesmo-com-caches-pela-metade-de-r-250-mil-para-r-120-mil","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/o-preco-da-chatice-agenda-de-paula-fernandes-diminui-mesmo-com-caches-pela-metade-de-r-250-mil-para-r-120-mil\/","title":{"rendered":"O pre\u00e7o da chatice: Agenda de Paula Fernandes diminui mesmo com cach\u00eas pela metade: de R$ 250 mil para R$ 120 mil"},"content":{"rendered":"<header>\n<h1 style=\"text-align: justify;\"><\/h1>\n<\/header>\n<div class=\"story\">\n<div class=\"header\" style=\"text-align: justify;\">\n<figure class=\"vertical_inline\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/extra.globo.com\/incoming\/19798548-f93-99c\/w448h673-PROP\/2013-676319611-paula-fernandes_20131231.jpg\" width=\"448\" height=\"673\" \/><figcaption>Paula Fernandes: menos shows\u00a0<\/figcaption><\/figure>\n<\/div>\n<p style=\"text-align: justify;\">As coisas n\u00e3o v\u00e3o bem para Paula Fernandes. A cantora, que j\u00e1 foi um fen\u00f4meno da m\u00fasica sertaneja, n\u00e3o faz mais tantos shows como no passado. Para se ter ideia, Paula tem entre os dias 30 deste m\u00eas e 18 de setembro apenas nove apresenta\u00e7\u00f5es marcadas. Uma delas numa exposi\u00e7\u00e3o agropecu\u00e1ria no interior de Goi\u00e1s cujo valor do ingresso n\u00e3o ultrapassa R$ 40.<\/p>\n<p style=\"text-align: justify;\">Paula Fernandes teve recentemente tr\u00eas shows cancelados por falta de p\u00fablico. O cach\u00ea despencou de R$ 250 mil para R$ 120 mil. A raz\u00e3o, segundo os contratantes, pode estar na antipatia de Paula: \u201cEla n\u00e3o recebe os prefeitos da cidade, n\u00e3o quer tirar foto. Parece estar sempre de m\u00e1 vontade\u201d.<\/p>\n<p style=\"text-align: justify;\">Em quase todos os lugares por onde passa, Paula Fernanda tem aprontado, a exemplo do que aconteceu durante o S\u00e3o do Vale, em Petrolina, no ano de 2012. Na \u00e9poca ela deixou o prefeito J\u00falio Lossio numa saia justa. Diante de sua arrog\u00e2ncia, empresas p\u00fablicas e privadas tem rejeitado a sua presen\u00e7a.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>As coisas n\u00e3o v\u00e3o bem para Paula Fernandes. A cantora, que j\u00e1 foi um fen\u00f4meno da m\u00fasica sertaneja, n\u00e3o faz mais tantos shows como no passado. Para se ter ideia, Paula tem entre os dias 30 deste m\u00eas e 18 de setembro apenas nove apres<\/p>\n","protected":false},"author":5,"featured_media":84564,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-141732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/09\/paula-fernandes.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/141732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=141732"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/141732\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/84564"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=141732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=141732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=141732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}