{"id":142047,"date":"2016-07-30T15:08:05","date_gmt":"2016-07-30T18:08:05","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=142047"},"modified":"2016-07-30T17:24:39","modified_gmt":"2016-07-30T20:24:39","slug":"deputado-desabafa-e-pede-fim-da-justica-do-trabalho","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/deputado-desabafa-e-pede-fim-da-justica-do-trabalho\/","title":{"rendered":"Deputado desabafa e pede fim da Justi\u00e7a do Trabalho"},"content":{"rendered":"<div class=\"font_b font_tt\" style=\"text-align: justify;\"><\/div>\n<div class=\"font_a font_jjj\" style=\"text-align: justify;\">Marchezan Jr critica oportunismo de sindicato e o Congresso<\/div>\n<div class=\"font_a font_jjj\" style=\"text-align: justify;\"><\/div>\n<div class=\"font_a\" style=\"text-align: justify;\"><\/div>\n<div class=\"row change_font\">\n<div class=\"col-md-12 popup-gallery\" style=\"text-align: justify;\">\n<p><a title=\"Nelson Marchezan Jr critica o parlamento e os sindicatos e lembra que todos s\u00e3o sustentados pelos trabakhadores. (Foto: Ag. C\u00e2mara)\" href=\"http:\/\/www.diariodopoder.com.br\/style\/images\/images\/dep%20nelson%20marchezan%20jr.jpg\"><img decoding=\"async\" class=\"img-responsive\" src=\"http:\/\/www.diariodopoder.com.br\/style\/images\/images\/dep%20nelson%20marchezan%20jr.jpg\" \/><\/a><\/p>\n<div>NELSON MARCHEZAN JR CRITICA O PARLAMENTO E OS SINDICATOS E LEMBRA QUE TODOS S\u00c3O SUSTENTADOS PELOS TRABAKHADORES.<\/div>\n<\/div>\n<div class=\"col-md-12 font_a popup-gallery\">\n<p>Em corajoso pronunciamento na Comiss\u00e3o de Trabalho da C\u00e2mara, o deputado Nelson Marchezan Jr. (PSDB-RS) defendeu o fechamento da Justi\u00e7a do Trabalho como solu\u00e7\u00e3o para a gera\u00e7\u00e3o de emprego para o trabalhador brasileiro, sufocado pela crise econ\u00f4mica. Uma das poucas vozes contr\u00e1ria aos aumentos do funcionalismo aprovados antes do recesso parlamentar, Marchezan Jr. criticou o excesso de regalias da chamada elite do funcionalismo p\u00fablico, os sindicados, o excesso de burocracia e a extors\u00e3o de empres\u00e1rios.<\/p>\n<p style=\"text-align: justify;\">\u201cA justi\u00e7a do Trabalho, no ano passado, conseguiu entregar aos reclamantes R$ 8,5 bilh\u00f5es, mas custou R$ 17 bilh\u00f5es. Vamos fechar a Justi\u00e7a do Trabalho e dar o dobro do que os trabalhadores est\u00e3o pedindo. Essa \u00e9 uma regra matem\u00e1tica b\u00e1sica\u201d, disparou.<\/p>\n<p style=\"text-align: justify;\">No discurso, o deputado federal questiona: \u201cPor acaso \u00e9 sindicato que garante emprego, \u00e9 justi\u00e7a do trabalho, \u00e9 este Parlamento?\u201d<\/p>\n<p style=\"text-align: justify;\">\u201cQuem garante emprego \u00e9 empreendedor, \u00e9 quem bota sua iniciativa, seu dinheiro, sua for\u00e7a de trabalho. Isso garante emprego\u201d, disse. Candidato \u00e0 Prefeitura de Porto Alegre, Marchezan Jr. criticou os altos sal\u00e1rios dos servidores, definindo a estrutura p\u00fablica como arcaica. Segundo ele, n\u00e3o h\u00e1 interesse do trabalhador no atual sistema.<\/p>\n<p style=\"text-align: justify;\">\u201cAqui, na C\u00e2mara, geramos 16 mil (empregos), sem mencionar o Senado. Nosso trabalhador, que ganha at\u00e9 R$ 30 mil por m\u00eas, tem aux\u00edlio refei\u00e7\u00e3o de R$ 800 por m\u00eas, enquanto temos analfabetos espalhados por todo o Brasil. A cobertura do ensino infantil \u00e9 quase uma vergonha. Mas quem ganha R$ 30 mil por m\u00eas tem aux\u00edlio-creche. Isso \u00e9 em todo o judici\u00e1rio, em todo o Minist\u00e9rio P\u00fablico\u201d, disse.<\/p>\n<p style=\"text-align: justify;\">Sobre a Justi\u00e7a, o deputado lembrou que um juiz do trabalho tem 20 dias de recesso e 60 dias de f\u00e9rias. Al\u00e9m disso, vende as f\u00e9rias e ganha R$ 5 mil de aux\u00edlio moradia por m\u00eas, sem gerar uma \u00fanica vaga de emprego.<\/p>\n<p style=\"text-align: justify;\">\u201cQuem garante o emprego no Brasil n\u00e3o \u00e9 a Justi\u00e7a do Trabalho, o Parlamento, e os sindicados que querem aumentar a sua contribui\u00e7\u00e3o. \u00c9 importante que a gente comece a defender os interesses de quem paga nosso sal\u00e1rio, que \u00e9 o trabalhador\u201d, disse.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Em corajoso pronunciamento na Comiss\u00e3o de Trabalho da C\u00e2mara, o deputado Nelson Marchezan Jr. (PSDB-RS) defendeu o fechamento da Justi\u00e7a do Trabalho como solu\u00e7\u00e3o para a gera\u00e7\u00e3o de emprego para o trabalhador brasilei<\/p>\n","protected":false},"author":5,"featured_media":142048,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[27,6],"tags":[],"class_list":["post-142047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-justica","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/nelson-marchezan-jr.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/142047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=142047"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/142047\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/142048"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=142047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=142047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=142047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}