{"id":142144,"date":"2016-07-30T08:56:48","date_gmt":"2016-07-30T11:56:48","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=142144"},"modified":"2016-07-30T08:56:48","modified_gmt":"2016-07-30T11:56:48","slug":"sofri-preconceito-no-inicio-da-carreira","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/sofri-preconceito-no-inicio-da-carreira\/","title":{"rendered":"&#8220;Sofri preconceito no in\u00edcio da carreira&#8221;"},"content":{"rendered":"<header>\n<h1><\/h1>\n<\/header>\n<div class=\"story\">\n<div class=\"header\">\n<figure class=\"vertical_inline\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/extra.globo.com\/incoming\/19815507-aa0-a96\/w448h673-PROP\/001-2016_08_estilo_agosto_anahickmann.jpg\" width=\"448\" height=\"673\" \/><figcaption>Ana Hickamnn mostra sensualidade Foto: Renam Christofoletti\/ Estilo<\/figcaption><\/figure>\n<\/div>\n<div class=\"header\">\n<div class=\"credits info\"><\/div>\n<\/div>\n<p><a class=\"tv\" href=\"http:\/\/extra.globo.com\/tv-e-lazer\/ana-hickmann\/\" rel=\"follow\">Ana Hickmann<\/a> relembrou os tempos de modelo ao posar para a revista \u201cEstilo\u201d e o preconceito que sentiu ao entrar na TV: \u201cOuvia as pessoas falando \u2018carinha bonita, cabe\u00e7a vazia\u2019\u201d, conta. De boba a mo\u00e7a n\u00e3o tem nada. S\u00f3 no mercado, ela tem 15 produtos licenciados com seu nome. \u201cJ\u00e1 escutei que sou muito ambiciosa, mas acho que as pessoas precisam ter ambi\u00e7\u00e3o. No meu caso, n\u00e3o \u00e9 por mais dinheiro. Sou impulsionada por emo\u00e7\u00e3o. Fa\u00e7o o que me d\u00e1 prazer\u201d.<\/p>\n<figure><img decoding=\"async\" class=\"inline\" src=\"http:\/\/extra.globo.com\/incoming\/19815510-f38-7d3\/w448\/2016_08_estilo_agosto_anahickmann4.jpg\" alt=\"Ana Hickmann tem 15 produtos licenciados com seu nome\" \/><figcaption>Ana Hickmann tem 15 produtos licenciados com seu nome Foto: Renam Christofoletti\/ Estilo<\/figcaption><\/figure>\n<p>E se o assunto \u00e9 Ana Hickmann, n\u00e3o d\u00e1 para deixar de lembrar o epis\u00f3dio que aconteceu em Belo Horizonte, quando um homem armado invadiu seu quarto de hotel em Belo Horizonte, fez disparos que atingiram sua assessora e acabou sendo morto. \u201cNunca achei que fiz algo errado na internet. Nem dar aten\u00e7\u00e3o de menos nem em demasia. Mas alguns cuidados eu j\u00e1 tomava, como n\u00e3o taguear minha localiza\u00e7\u00e3o\u201d, comenta ela, sobre a exposi\u00e7\u00e3o nas redes sociais.<\/p>\n<p>Com isso, Ana Hickmann acabou deixando transparecer um lado seu mais fr\u00e1gil. \u201cN\u00e3o tenho mais medo de deixar as pessoas me verem chorar. Nunca contive as l\u00e1grimas quando via, por exemplo, uma reportagem comovente. Mas, com coisas minhas, sempre me guardei. Essa parte fr\u00e1gil, nunca deixei ningu\u00e9m enxergar. Agora, n\u00e3o mais\u201d.<\/p>\n<p>Fonte: Extra<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Com isso, Ana Hickmann acabou deixando transparecer um lado seu mais fr\u00e1gil. \u201cN\u00e3o tenho mais medo de deixar as pessoas me v<\/p>\n","protected":false},"author":5,"featured_media":142145,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-142144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/ana-hi.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/142144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=142144"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/142144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/142145"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=142144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=142144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=142144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}