{"id":142256,"date":"2016-07-31T10:56:52","date_gmt":"2016-07-31T13:56:52","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=142256"},"modified":"2016-07-31T11:05:54","modified_gmt":"2016-07-31T14:05:54","slug":"direito-de-resposta-ex-prefeito-de-remanso-rebate-acusacoes","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/direito-de-resposta-ex-prefeito-de-remanso-rebate-acusacoes\/","title":{"rendered":"Direito de resposta: Ex-prefeito de Remanso rebate acusa\u00e7\u00f5es"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Da Reda\u00e7\u00e3o<\/strong><\/p>\n<p style=\"text-align: justify;\">Em nota enviada nesta manh\u00e3 (31) ao <em><strong>AP<\/strong><\/em>, por parte de uma das pessoas ligada ao grupo pol\u00edtico comandado pelo ex-prefeito de Remanso, Z\u00e9 Filho (PSD), rebate as informa\u00e7\u00f5es destacadas por seus opositores na imprensa.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/processo-que-torna-ze-filho-de-remanso-inelegivel-foi-proposto-pelo-prefeito-celso\/ze-filho1\/\" rel=\"attachment wp-att-126955\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-126955\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/05\/ze-filho1-300x220.jpg\" alt=\"ze filho1\" width=\"300\" height=\"220\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/05\/ze-filho1-300x220.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/05\/ze-filho1-418x307.jpg 418w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/05\/ze-filho1-70x50.jpg 70w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/05\/ze-filho1.jpg 447w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><em><strong>Confira: \u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">1 &#8211; Total desespero da oposi\u00e7\u00e3o;<\/p>\n<p style=\"text-align: justify;\">2 &#8211; Depois que uma pesquisa do PCdoB vazou em que o candidato da oposi\u00e7\u00e3o se encontra com menos de 20% da inten\u00e7\u00e3o de voto;<\/p>\n<p style=\"text-align: justify;\">3 &#8211; Percebendo que n\u00e3o ganham nas urnas resolveram fazer uma campanha para denegrir a imagem do pr\u00e9 canditado do PSD;<\/p>\n<p style=\"text-align: justify;\">4 &#8211; A adesao popular \u00e9 imensa, como tamb\u00e9m diversos apoios importantes sairam da oposi\u00e7\u00e3o para se juntar ao pr\u00e9 candidato Z\u00e9 Filho;<\/p>\n<p style=\"text-align: justify;\">5 &#8211; Num ato de desespero resolveram emplacar ataques pessoais ao pr\u00e9 candidato, inclusive com entrevistas falsas;<\/p>\n<p style=\"text-align: justify;\">6 &#8211; Utilizando- se de artimanhas da pior especie para confundir o eleitorado e trazer panico a cidade;<\/p>\n<p style=\"text-align: justify;\">7 &#8211; Que pessoas que tem coragem de fazer esse tipo de a\u00e7\u00e3o s\u00e3o inescrupulosas;<\/p>\n<p style=\"text-align: justify;\">8 &#8211; Que n\u00e3o passa de mentira e engodo para enganar o povo;<\/p>\n<p style=\"text-align: justify;\">9 &#8211; Que o pr\u00e9 candidato Z\u00e9 Filho somente n\u00e3o ser\u00e1 eleito, e se essa for a vontade de Deus ou do povo;<\/p>\n<p style=\"text-align: justify;\">10 &#8211; Que a justi\u00e7a se incumbir\u00e1 de julgar e punir a deslealdade dos advers\u00e1rios.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em nota enviada nesta manh\u00e3 (31) ao AP, por parte de uma das pessoas ligada ao grupo pol\u00edtico comandado pelo ex-prefeito de <\/p>\n","protected":false},"author":5,"featured_media":126955,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4,6],"tags":[],"class_list":["post-142256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/05\/ze-filho1.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/142256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=142256"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/142256\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/126955"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=142256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=142256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=142256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}