{"id":142286,"date":"2016-07-31T13:25:21","date_gmt":"2016-07-31T16:25:21","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=142286"},"modified":"2016-07-31T13:25:21","modified_gmt":"2016-07-31T16:25:21","slug":"beldades-do-jornalismo-da-globo-nao-ligam-para-o-titulo-de-musas","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/beldades-do-jornalismo-da-globo-nao-ligam-para-o-titulo-de-musas\/","title":{"rendered":"Beldades do jornalismo da Globo n\u00e3o ligam para o t\u00edtulo de musas"},"content":{"rendered":"<header>\n<h1><\/h1>\n<\/header>\n<figure class=\"horizontal\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/extra.globo.com\/incoming\/19806535-964-b2e\/w640h360-PROP\/apresentadoras.jpg\" alt=\"Cristiane Dias, Glenda Koslowski, Carol Barcellos e Fernanda Gentil falam sobre expectativa para a Olimp\u00edada\" width=\"640\" height=\"360\" \/><figcaption><span class=\"credit\">Cristiane Dias, Glenda Koslowski, Carol Barcellos e Fernanda Gentil falam sobre expectativa para a Olimp\u00edada Foto: Rafael Moraes<\/span><\/figcaption><\/figure>\n<div class=\"story\">\n<div class=\"header\">\n<div class=\"credits info\"><span class=\"author\">Fl\u00e1via Muniz<\/span><\/div>\n<\/div>\n<p>Como diria Jorge Ben Jor, \u201ceu vou torcer pela paz, pela alegria, pelo amor, pelas mo\u00e7as bonitas\u201d. \u00c9 nesse embalo otimista que o quarteto de ouro da transmiss\u00e3o dos Jogos Ol\u00edmpicos da Globo, formado por Fernanda Gentil, Glenda Kozlowski, Cristiane Dias e Carol Barcellos, vai encarar um dos maiores desafios de suas carreiras: a cobertura, in loco, do evento esportivo mais importante do mundo.<\/p>\n<p>Beleza, neste caso, \u00e9 mero detalhe. Na hora do \u201cvalendo\u201d, o que vai contar mesmo \u00e9 a experi\u00eancia e o talento para sacar a informa\u00e7\u00e3o e pontuar com a not\u00edcia fresquinha. O t\u00edtulo de musas, elas n\u00e3o rejeitam e s\u00e3o un\u00e2nimes em afirmar \u201cque \u00e9 melhor do que serem chamadas de barangas\u201d.<\/p>\n<p>\u2014 \u00c9 l\u00f3gico que n\u00e3o vou reclamar. Elogio \u00e9 legal, mas morre ali. Tenho que entrar ao vivo, n\u00e3o posso gaguejar, n\u00e3o posso esquecer&#8230; E a musa n\u00e3o me ajuda a fazer isso. Quem faz \u00e9 a jornalista. Agrade\u00e7o o carinho do p\u00fablico, mas penso \u00e9 na boa cobertura \u2014 deixa claro Fernanda Gentil, \u00e2ncora do \u201cGlobo esporte\u201d, que, a partir de amanh\u00e3, passa a entrar ao vivo durante a programa\u00e7\u00e3o, do \u201cBom dia Brasil\u201d at\u00e9 o \u201cJornal hoje\u201d, direto do Parque Ol\u00edmpico, na Barra.<\/p>\n<figure><img decoding=\"async\" class=\"inline\" src=\"http:\/\/extra.globo.com\/incoming\/19806545-536-c6c\/w448\/fernanda-gentil.jpg\" alt=\"Fernanda Gentil diz que o corpo reage ao nervosismo que antecede \u00e0 Olimp\u00edada\" \/><figcaption>Fernanda Gentil diz que o corpo reage ao nervosismo que antecede \u00e0 Olimp\u00edada Foto: Rafael Moraes<\/figcaption><\/figure>\n<p>Al\u00e9m dos belos tra\u00e7os e da boa forma, elas t\u00eam em comum a ansiedade.<\/p>\n<p>\u2014 Eu sou do tipo que tem herpes (risos). Fico nervosa, me preparo, estudo. Minha rela\u00e7\u00e3o com o \u201cao vivo\u201d \u00e9 de adrenalina, um tes\u00e3o absurdo, quase uma droga. Gosto de fazer TV de um jeito bem natural. N\u00e3o vou para o ar vestindo uma personagem \u2014 refor\u00e7a Fernanda.<\/p>\n<p>Cristiane Dias \u00e9 outra que anda \u00e0 flor da pele com a fun\u00e7\u00e3o de atualizar o espectador sobre as competi\u00e7\u00f5es, no \u201cJornal da Globo\u201d:<\/p>\n<p>\u2014 Tem aquele friozinho na barriga e, ao mesmo tempo, medo e excita\u00e7\u00e3o de estar cobrindo o maior evento do esporte mundial, na nossa casa. \u00c9 felicidade, receio e a vontade de come\u00e7ar logo. No \u201cao vivo\u201d, a gente sabe que n\u00e3o pode desmontar, tem que ter jogo de cintura, saber se zoar \u2014 frisa Cris.<\/p>\n<p>Desencanada, Carol Barcellos n\u00e3o somatiza no corpo a expectativa. Est\u00e1 habituada a explorar seus limites:<\/p>\n<p>\u2014 Meu hor\u00e1rio vai ser o da madrugada (ela vai apresentar diariamente o \u201cBalada ol\u00edmpica\u201d com Fl\u00e1vio Canto, substituindo o \u201cPrograma do J\u00f4\u201d). \u00c9 bem diferente, mas eu tenho facilidade para me adaptar, j\u00e1 trabalhei virada algumas vezes. \u00c9 uma oportunidade incr\u00edvel, fora que \u00e9 um baita desafio passar duas horas no ar \u2014 destaca.<\/p>\n<figure><img decoding=\"async\" class=\"inline\" src=\"http:\/\/extra.globo.com\/incoming\/19806537-56b-0d0\/w448\/carol-carbcellos.jpg\" alt=\"Carol Barcellos est\u00e1 acostumada a explorar seus limites como no quadro \u201cPlaneta Extremo\u201d\" \/><figcaption>Carol Barcellos est\u00e1 acostumada a explorar seus limites como no quadro \u201cPlaneta Extremo\u201d Foto: Rafael Moraes<\/figcaption><\/figure>\n<p>A mais experiente, j\u00e1 tendo participado da cobertura dos Jogos de Atenas (2004), e de Pequim (2008), Glenda Kozlowski estreia como narradora. \u00c9 ela quem vai apresentar a gin\u00e1stica art\u00edstica.<\/p>\n<p>\u2014 Minha adrenalina \u00e9 maior a\u00ed, porque \u00e9 outra pegada. Estou estudando pra caramba. Passei dois dias em S\u00e3o Paulo com a delega\u00e7\u00e3o brasileira para entrar nesse mundo. Mais do que narrar, vou contar a hist\u00f3ria das pessoas. Tamb\u00e9m estou muito feliz de vivenciar um evento desse porte, com essa atmosfera, em casa, falando a minha l\u00edngua.<\/p>\n<p>\u00c0s v\u00e9speras da Rio-2016, elas entraram no clima das competi\u00e7\u00f5es para a Canal Extra, nas cores dos an\u00e9is ol\u00edmpicos, bem mulherzinhas (de vestido, salto alto, maquiagem), estilo que n\u00e3o costumam explorar no dia a dia por conta da praticidade que a profiss\u00e3o exige.<\/p>\n<p>Mas o papo com essas jornalistas que despontaram numa \u00e1rea dominada por homens vai al\u00e9m das regras do jogo. De cara, elas afastam qualquer possibilidade de disputa nos bastidores.<\/p>\n<p>\u2014 Entre dizer que \u00e9 tudo falsidade ou reconhecer que a gente se d\u00e1 bem, \u00e9 mais f\u00e1cil falar mal, n\u00e9? \u2014 avalia Fernanda.<\/p>\n<figure><img decoding=\"async\" class=\"inline\" src=\"http:\/\/extra.globo.com\/incoming\/19806540-8e5-a17\/w448\/crisdias.jpg\" alt=\"Acostumada a apresentar o Globo Esporte, Cristiane Dias diz que tem frio na barriga antes dos Jogos\" \/><figcaption>Acostumada a apresentar o Globo Esporte, Cristiane Dias diz que tem frio na barriga antes dos Jogos Foto: Rafael Moraes \/ Ag\u00c3\u00aancia O Globo<\/figcaption><\/figure>\n<p>Cristiane faz coro:<\/p>\n<p>\u2014 Muita gente pode achar que rola competi\u00e7\u00e3o, que uma puxa o tapete da outra, mas \u00e9 a maior farra. A gente se ajuda e se diverte.<\/p>\n<p>O ass\u00e9dio \u00e9 o lado B de se destacarem como especialistas esportivas e ainda carregarem o DNA da beleza. Cristiane admite que \u00e9 comum ouvir gracinhas. Mas sua t\u00e1tica infal\u00edvel afasta os mais atrevidos:<\/p>\n<p>\u2014 Eu me fa\u00e7o de louca at\u00e9 onde d\u00e1. Antes, era pior. Hoje, ainda rola, mas sei me defender. Sempre tem um que manda uma letrinha.<\/p>\n<p>Carol reage quando a cantada \u00e9 mais agressiva:<\/p>\n<p>\u2014 A gente n\u00e3o \u00e9 obrigada a aceitar o cara falando uma besteira. Se me sinto ofendida, eu respondo mesmo.<\/p>\n<p>No in\u00edcio da carreira (1992), at\u00e9 em vesti\u00e1rio masculino Glenda entrou em nome da boa apura\u00e7\u00e3o.<\/p>\n<p>\u2014 Era s\u00f3 homem cobrindo futebol, mas eu ia ficar l\u00e1 fora esperando? Claro que n\u00e3o. Entrava mesmo. Na \u00e9poca, eu tinha 17 anos, vivia na praia, de biqu\u00edni, era surfista (ela foi tetracampe\u00e3 mundial de bodyboard), n\u00e3o estava nem a\u00ed. Tinha jogador mais ousado, mas eu nem ligava. Sou muito brincalhona, mas nunca abri espa\u00e7o para esse tipo de coisa \u2014 lembra.<\/p>\n<figure><img decoding=\"async\" class=\"inline\" src=\"http:\/\/extra.globo.com\/incoming\/19806548-36c-bca\/w448\/glenda.jpg\" alt=\"Glenda Koslowski j\u00e1 cobriu duas Olimp\u00edadas\" \/><figcaption>Glenda Koslowski j\u00e1 cobriu duas Olimp\u00edadas Foto: Rafael Moraes<\/figcaption><\/figure>\n<p>Na categoria vaidade, a ficha de Glenda s\u00f3 caiu aos 40 anos (ela tem 42). Mas sem crise, que fique claro:<\/p>\n<p>\u2014 Fiquei mais feminina. Comecei a usar vestido, me arrumar, fazer sobrancelha, unha&#8230; Eu n\u00e3o voltaria no tempo. N\u00e3o quero ter cara de 20 anos. Vivi todas as minhas fases muito bem.<\/p>\n<p>Depois da gravidez (de Gabriel, de 11 meses) e da separa\u00e7\u00e3o (do empres\u00e1rio Matheus Braga), Fernanda emagreceu tr\u00eas quilos e tem gostado do corpo enxuto.<\/p>\n<p>\u2014 Nunca fui ligada nisso, era at\u00e9 motivo de estresse com a minha m\u00e3e. Mas Deus me fez trabalhar numa \u00e1rea em que tenho que me maquiar e fazer escova todo dia. Imagina a alegria! (risos). Nunca foi minha prioridade, mas as roupas ficam melhores e isso eu quero manter, sem neurose. Nos fins de semana, eu vivo. Tomo meu chopinho, vou ao pagode&#8230;<\/p>\n<p>Morando h\u00e1 um ano longe do marido (o jornalista Bruno C\u00f4rtes, que est\u00e1 em Nova York), Carol garante que a \u00faltima coisa que passa na cabe\u00e7a, agora, \u00e9 namorar:<\/p>\n<p>\u2014 Fico na vontade, n\u00e9? N\u00e3o d\u00e1 nem para pensar nisso com tanto trabalho.<\/p>\n<p>Depois de tantas idas e vindas, Cristiane e o ator Thiago Rodrigues resolveram dividir o mesmo teto:<\/p>\n<p>\u2014 Moramos muito tempo cada um na sua casa. Como a gente ficava separado de vez em quando, era mais f\u00e1cil. Mas, agora, que resolvemos juntar de vez, a rotina do meu filho (Gabriel , de 7 anos) fica melhor \u2014 diz.<\/p>\n<p>Solteira, Fernanda sinaliza o que um homem tem que ter para conquist\u00e1-la:<\/p>\n<p>\u2014 Precisa ser uma pessoa leve. N\u00e3o na balan\u00e7a, mas de esp\u00edrito. N\u00e3o tem que ser sarado, mas gostar de pagodinho e F\u00e1bio Jr. (risos).<\/p>\n<p>Brincadeiras \u00e0 parte, \u201cviver\u201d o luto da separa\u00e7\u00e3o foi fundamental para ela:<\/p>\n<p>\u2014 Ficamos um m\u00eas separados, sem ningu\u00e9m saber. Foi um momento de reflex\u00e3o. A gente foi humilde e corajoso o suficiente de entender que n\u00e3o \u00e9ramos mais felizes. E a gente merece ser. Somos novos, fazemos o bem&#8230; Se n\u00e3o estava sendo t\u00e3o bom, n\u00e3o tinha por que n\u00e3o tomar essa decis\u00e3o.<\/p>\n<figure><img decoding=\"async\" class=\"inline\" src=\"http:\/\/extra.globo.com\/incoming\/19806542-302-39a\/w448\/diversao.jpg\" alt=\"Jornalistas se divertem em ensiao esportivo\" \/><figcaption>Jornalistas se divertem em ensiao esportivo Foto: Rafael Moraes<\/figcaption><\/figure>\n<div id=\"selo-em-artigo\" class=\"facebook\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beleza, neste caso, \u00e9 mero detalhe. Na hora do \u201cvalendo\u201d, o que vai contar mesmo \u00e9 a experi\u00eancia e o talento para sacar a inform<\/p>\n","protected":false},"author":5,"featured_media":142287,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-142286","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/apresentadoras.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/142286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=142286"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/142286\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/142287"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=142286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=142286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=142286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}