{"id":142653,"date":"2016-08-02T08:51:07","date_gmt":"2016-08-02T11:51:07","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=142653"},"modified":"2016-08-02T08:51:07","modified_gmt":"2016-08-02T11:51:07","slug":"vem-ai-o-dossie-de-cunha","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/vem-ai-o-dossie-de-cunha\/","title":{"rendered":"Vem a\u00ed o dossi\u00ea de Cunha"},"content":{"rendered":"<header class=\"entry-header\">\n<h1 class=\"entry-title\" style=\"text-align: justify;\"><em><a href=\"http:\/\/blogs.ne10.uol.com.br\/jamildo\/2016\/08\/02\/eduardo-cunha-prepara-dossie-sobre-seus-aliados-politicos\/\">Ele pretende d\u00e1 reposta aos tra\u00edras<\/a><\/em><\/h1>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" src=\"http:\/\/imagens4.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/2016\/07\/1029823-07072016-img_1544-624x416.jpg\" sizes=\"auto, (max-width: 624px) 100vw, 624px\" srcset=\"http:\/\/imagens4.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/2016\/07\/1029823-07072016-img_1544-580x386.jpg 580w, http:\/\/imagens4.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/2016\/07\/1029823-07072016-img_1544-624x416.jpg 624w, http:\/\/imagens4.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/2016\/07\/1029823-07072016-img_1544.jpg 800w\" alt=\"Bras\u00edlia - O presidente afastado da C\u00e2mara, Eduardo Cunha (PMDB-RJ), renunciou h\u00e1 pouco \u00e0 presid\u00eancia da Casa (Marcelo Camargo\/Ag\u00eancia Brasil)\" width=\"624\" height=\"416\" \/><\/header>\n<div class=\"entry-content\">\n<p style=\"text-align: justify;\"><em>Foto: Marcelo Camargo\/Ag\u00eancia Brasil<\/em><\/p>\n<p style=\"text-align: justify;\">Prestes a ser julgado no plen\u00e1rio, o ex-presidente da C\u00e2mara e deputado afastado Eduardo Cunha (PMDB-RJ) prepara um levantamento aprofundado sobre como ajudou seus aliados nos \u00faltimos anos. O objetivo \u00e9 consolidar o material para uma eventual dela\u00e7\u00e3o premiada na Justi\u00e7a.<\/p>\n<p style=\"text-align: justify;\">Segundo relatos de deputados, o peemedebista vem coletando informa\u00e7\u00f5es sobre financiamento de campanhas eleitorais. Tamb\u00e9m produziu uma \u201cpilha\u201d de documentos com dados sobre distribui\u00e7\u00e3o de cargos e empr\u00e9stimos. Por meio de assessoria, Cunha negou que esteja organizando documentos para dela\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">O peemedebista deve esperar algumas semanas e aguardar o resultado da vota\u00e7\u00e3o da cassa\u00e7\u00e3o no plen\u00e1rio para depois decidir se vai aderir \u00e0 dela\u00e7\u00e3o. A expectativa \u00e9 de que o processo por quebra de decoro parlamentar seja analisado neste m\u00eas.<\/p>\n<p style=\"text-align: justify;\">Grupos ligados a Cunha dizem n\u00e3o ver sa\u00edda para ele e acham que a cassa\u00e7\u00e3o deve ser aprovada no plen\u00e1rio. Por isso, conselheiros de Cunha defendem que ele renuncie ao mandato para demonstrar disposi\u00e7\u00e3o de negociar com a Procuradoria-Geral da Rep\u00fablica.<\/p>\n<p style=\"text-align: justify;\">S\u00f3 o esvaziamento do plen\u00e1rio poderia salv\u00e1-lo da cassa\u00e7\u00e3o, uma vez que seu sucessor, Rodrigo Maia (DEM-RJ), comunicou que s\u00f3 colocar\u00e1 o tema em vota\u00e7\u00e3o se houver qu\u00f3rum superior a 460 deputados. Embora saiba que as perspectivas s\u00e3o negativas, Cunha d\u00e1 sinais de que tem esperan\u00e7a de reverter o cen\u00e1rio. Aos mais pr\u00f3ximos, diz duvidar de que seus pares votem a favor da cassa\u00e7\u00e3o e que ainda pode persuadi-los.<\/p>\n<p style=\"text-align: justify;\"><b>Sucess\u00e3o de derrotas<\/b><\/p>\n<p style=\"text-align: justify;\">Ap\u00f3s a aprova\u00e7\u00e3o do pedido de cassa\u00e7\u00e3o no Conselho de \u00c9tica por 11 a 9, Cunha viu seu recurso contra o processo disciplinar ser rejeitado pela Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ). Por 40 votos a 11, integrantes da CCJ aprovaram um parecer contr\u00e1rio \u00e0s pretens\u00f5es do peemedebista, e a aposta dos parlamentares \u00e9 de que o resultado no plen\u00e1rio seja proporcional ao que foi na comiss\u00e3o. Pelas contas de deputados, Cunha teria hoje apenas 40 votos contra a perda do mandato.<\/p>\n<p style=\"text-align: justify;\">Dono do voto que ajudou a sacramentar o destino do peemedebista no conselho, o deputado Wladimir Costa (SD-PA) disse que est\u00e1 disposto a manter sua posi\u00e7\u00e3o pr\u00f3-cassa\u00e7\u00e3o porque \u201cn\u00e3o tem outra sa\u00edda\u201d. Costa, que pertenceu \u00e0 \u201ctropa de choque\u201d de Cunha, disse que sabe o quanto ele ficou insatisfeito com a mudan\u00e7a de voto na \u00faltima hora, mas que nada o impede de manter sua opini\u00e3o. \u201cN\u00e3o tenho compromisso com Eduardo Cunha, n\u00e3o sou do time do Cunha. Ele nunca me ajudou, n\u00e3o devo nada a ele, nem meu mandato\u201d, afirmou.<\/p>\n<p style=\"text-align: justify;\"><b>Defesa<\/b><\/p>\n<p style=\"text-align: justify;\">Afastado h\u00e1 quase tr\u00eas meses das atividades parlamentares por decis\u00e3o do Supremo Tribunal Federal (STF), Cunha vem preparando um mandado de seguran\u00e7a que deve ser apresentado \u00e0 Corte para tentar impedir que o plen\u00e1rio da C\u00e2mara paute a vota\u00e7\u00e3o. \u00c9 considerada a \u00faltima cartada para atrasar o processo, uma vez que na Casa n\u00e3o h\u00e1 mais manobras regimentais poss\u00edveis. As informa\u00e7\u00f5es s\u00e3o do jornal <b>O Estado de S. Paulo.<\/b><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ele pretende d\u00e1 reposta aos tra\u00edras<\/p>\n","protected":false},"author":5,"featured_media":139249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-142653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/07\/Cunha-CCJ-Foto-Alex-Ferreira-Camara.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/142653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=142653"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/142653\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/139249"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=142653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=142653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=142653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}