{"id":142699,"date":"2016-08-03T03:07:49","date_gmt":"2016-08-03T06:07:49","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=142699"},"modified":"2016-08-03T03:07:49","modified_gmt":"2016-08-03T06:07:49","slug":"juiz-proibe-guarda-municipal-de-abordar-pessoas-e-investigar-crimes","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/juiz-proibe-guarda-municipal-de-abordar-pessoas-e-investigar-crimes\/","title":{"rendered":"Juiz pro\u00edbe Guarda Municipal de abordar pessoas e investigar crimes"},"content":{"rendered":"<h2 class=\"title\"><\/h2>\n<p class=\"authors\"><a href=\"http:\/\/www.conjur.com.br\/2016-ago-02\/juiz-proibe-guarda-municipal-abordar-pessoas-investigar-crimes#author\">Por\u00a0Felipe Luchete<\/a><\/p>\n<div class=\"wysiwyg\">\n<p>Guardas municipais n\u00e3o podem fazer abordagens e revistas em pessoas, pois t\u00eam o papel restrito de proteger bens, servi\u00e7os e instala\u00e7\u00f5es do munic\u00edpio. Assim entendeu o juiz Jos\u00e9 Daniel Dinis Gon\u00e7alves, da Vara da Fazenda P\u00fablica da Ara\u00e7atuba (SP), ao proibir que a Guarda Municipal da cidade execute atividades pr\u00f3prias de pol\u00edcia. Ele tamb\u00e9m declarou inconstitucionais dois dispositivos da <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/_Ato2011-2014\/2014\/Lei\/L13022.htm\" target=\"_blank\">Lei 13.022\/2014<\/a>, que criou um estatuto geral para essas institui\u00e7\u00f5es.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-130171\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/05\/guarda-municipal-173x307.jpg\" alt=\"guarda municipal\" width=\"173\" height=\"307\" \/><\/p>\n<p>A a\u00e7\u00e3o foi movida pelo Minist\u00e9rio P\u00fablico estadual em 2015, depois que o comandante da GM de Ara\u00e7atuba anunciou \u00e0 imprensa o in\u00edcio de novas atividades, como patrulhamento preventivo e abordagens de cidad\u00e3os nas ruas, com base na legisla\u00e7\u00e3o do ano anterior. A prefeitura respondeu que as declara\u00e7\u00f5es foram \u201cepis\u00f3dicas\u201d, sem refletirem a conduta geral dos guardas municipais, mas o MP disse que \u201ch\u00e1 v\u00e1rios anos\u201d vinha registrando reclama\u00e7\u00f5es de desvio de finalidade.<\/p>\n<p>Embora j\u00e1 tramite a\u00e7\u00e3o no Supremo Tribunal Federal questionando a lei federal (ADI 5.156), o Minist\u00e9rio P\u00fablico alegou que moradores de Ara\u00e7atuba n\u00e3o poderiam aguardar o julgamento\u00a0\u201cabandonados \u00e0 pr\u00f3pria sorte, sendo abordados e tendo seus direitos fundamentais violados\u201d.<\/p>\n<p>O juiz determinou que a institui\u00e7\u00e3o \u201cse abstenha de efetuar atividades pr\u00f3prias de pol\u00edcia, tais como investiga\u00e7\u00f5es, dilig\u00eancias para apura\u00e7\u00e3o de crimes, abordagens e revistas em pessoas\u201d, sob pena de multa (cujo valor ainda ser\u00e1 fixado). E, \u201cna hip\u00f3tese de not\u00edcia de ocorr\u00eancia de crime\u201d, deve comunicar autoridades competentes, exceto\u00a0em situa\u00e7\u00e3o de flagrante delito.<\/p>\n<p><strong>Regras inv\u00e1lidas<\/strong><br \/>\nGon\u00e7alves ainda declarou, incidentalmente, a inconstitucionalidade dos incisos XIII e XVII do artigo 5\u00ba da Lei 13.022. O primeiro dispositivo d\u00e1 \u00e0 Guarda Municipal o poder de atender ocorr\u00eancias emergenciais, quando se deparar\u00a0com esse tipo de situa\u00e7\u00e3o. Para o juiz, essa autoriza\u00e7\u00e3o invade atribui\u00e7\u00e3o pr\u00f3pria da Pol\u00edcia Militar ou do Corpo de Bombeiros.<\/p>\n<p>\u201cCom isso, n\u00e3o se quer dizer\u00a0que seja vedado \u00e0 Guarda Municipal prestar socorro a cidad\u00e3o em perigo iminente, por \u00f3bvio, mas se permite n\u00e3o s\u00f3 a ela como a qualquer outro, apenas diante de excepcionalidade que a justifique\u201d, afirmou.<\/p>\n<p>O outro dispositivo libera a atua\u00e7\u00e3o de guardas municipais na seguran\u00e7a de grandes eventos e na prote\u00e7\u00e3o de autoridades. A senten\u00e7a afirma que essa regra \u201cofendeu claramente a destina\u00e7\u00e3o constitucional, pois n\u00e3o h\u00e1 correspond\u00eancia com as atribui\u00e7\u00f5es constitucionais estabelecidas\u201d \u00e0 institui\u00e7\u00e3o.<\/p>\n<p>O promotor <strong>Joel Furlan<\/strong>, autor do pedido, afirma que o juiz de primeiro grau pode declarar a inconstitucionalidade dos dispositivos de forma incidental, valendo apenas para Ara\u00e7atuba. O professor <strong>Pedro Serrano<\/strong>, da \u00e1rea de Direito Constitucional da PUC-SP, tamb\u00e9m considera a medida adequada.<\/p>\n<p>Sobre o m\u00e9rito, Serrano\u00a0diz\u00a0que a GM deve se limitar a cuidar do patrim\u00f4nio p\u00fablico, e n\u00e3o de pessoas, pois as atividades de seguran\u00e7a p\u00fablica s\u00e3o t\u00edpicas dos estados. \u201cSe verificarem algu\u00e9m cometendo um crime em flagrante, como qualquer cidad\u00e3o, t\u00eam direito de dar voz de pris\u00e3o\u201d, aponta o professor.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O juiz determinou que a institui\u00e7\u00e3o \u201cse abstenha de efetuar atividades pr\u00f3prias de pol\u00edcia, tais como investiga\u00e7\u00f5es, dilig\u00eancias para apura\u00e7\u00e3o de <\/p>\n","protected":false},"author":7,"featured_media":130171,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[27,6],"tags":[],"class_list":["post-142699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-justica","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/05\/guarda-municipal.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/142699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=142699"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/142699\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/130171"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=142699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=142699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=142699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}