{"id":142911,"date":"2016-08-04T15:38:47","date_gmt":"2016-08-04T18:38:47","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=142911"},"modified":"2016-08-04T15:52:14","modified_gmt":"2016-08-04T18:52:14","slug":"mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/","title":{"rendered":"Mais de duas mil pessoas comparecem \u00e0 conven\u00e7\u00e3o de Mois\u00e9s Ribeiro em Uau\u00e1; veja as imagens"},"content":{"rendered":"<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><strong>A\u00e7\u00e3o Popular (AP)<\/strong><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: medium;\">Mais de duas mil pessoas prestigiaram ontem (03) a <span class=\"x_il\">conven\u00e7\u00e3o<\/span><span class=\"x_apple-converted-space\">\u00a0que homologou a chapa do pr\u00e9-candidato a prefeito de Uau\u00e1 Mois\u00e9s Ribeiro (PP) e do vice-prefeito Miroval Marques (PT)<\/span>. O evento aconteceu no Gin\u00e1sio de Esportes e contou com as presen\u00e7as do deputado federal, M\u00e1rio Negromonte J\u00fanior (PP), deputada estadual F\u00e1tima Nunes (PT), presidentes de partidos, pr\u00e9-candidatos a vereadores e lideran\u00e7as. Al\u00e9m do PP, PT, a coliga\u00e7\u00e3o conta com o apoio dos partidos PDT, PTN e PSB.<\/span><\/p>\n<p><figure id=\"attachment_142919\" aria-describedby=\"caption-attachment-142919\" style=\"width: 464px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1611546021\/\" rel=\"attachment wp-att-142919\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-142919 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1611546021-464x261.jpg\" alt=\"IMG_20160803_161154602[1]\" width=\"464\" height=\"261\" \/><\/a><figcaption id=\"caption-attachment-142919\" class=\"wp-caption-text\">O espa\u00e7o ficou pequeno para muita gente<\/figcaption><\/figure><figure id=\"attachment_142934\" aria-describedby=\"caption-attachment-142934\" style=\"width: 464px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1642199581\/\" rel=\"attachment wp-att-142934\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-142934 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1642199581-464x261.jpg\" alt=\"IMG_20160803_164219958[1]\" width=\"464\" height=\"261\" \/><\/a><figcaption id=\"caption-attachment-142934\" class=\"wp-caption-text\">Deputado M\u00e1rio Montenegro e Mois\u00e9s<\/figcaption><\/figure><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">&#8220;Mesmo com todas as dificuldades que os munic\u00edpios do pa\u00eds vem passando, inclusive Uau\u00e1, o prefeito Ol\u00edmpio Cardoso vem sabendo conduzir os problemas realizando obras. Ao lado de Ol\u00edmpio, o prefeito contou durante esse tempo com Mois\u00e9s que fez um brilhante trabalho. Ele \u00e9 uma pessoa preparada, conhece os problemas da popula\u00e7\u00e3o e do munic\u00edpio, e eu como deputado vou ajudar no que for poss\u00edvel trazendo emendas e projetos para esta cidade. Al\u00e9m de mim, Mois\u00e9s conta com os apoios do vice-governador Jo\u00e3o Le\u00e3o, do governador Rui Costa, e outras lideran\u00e7as&#8221;, informou M\u00e1rio Negromonte.<\/span><\/p>\n<figure id=\"attachment_142921\" aria-describedby=\"caption-attachment-142921\" style=\"width: 464px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1804156591\/\" rel=\"attachment wp-att-142921\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-142921 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1804156591-464x261.jpg\" alt=\"IMG_20160803_180415659[1]\" width=\"464\" height=\"261\" \/><\/a><figcaption id=\"caption-attachment-142921\" class=\"wp-caption-text\">Deputada estadual, F\u00e1tima Nunes (PT)<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\"><span style=\"color: #333333;\">Por sua vez, a deputada estadual F\u00e1tima Nunes, alertou a popula\u00e7\u00e3o na hora do voto. \u201c\u00c9 na\u00a0pol\u00edtica\u00a0que decidimos se\u00a0a vida da gente na cidade, no campo, nos bairros vai ser de condi\u00e7\u00f5es melhores ou se vamos passar por algum aperto. Eu tenho certeza que o povo de Uau\u00e1 que j\u00e1 viveu nestes quatro anos do Governo Ol\u00edmpio est\u00e1 dizendo a todos que vai querer melhor do que j\u00e1 acontece hoje. Estou aqui hoje para renovar o meu compromisso com voc\u00ea e daqui ningu\u00e9m me tira\u201d.<\/span><\/span><\/p>\n<figure id=\"attachment_142920\" aria-describedby=\"caption-attachment-142920\" style=\"width: 464px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1756430801\/\" rel=\"attachment wp-att-142920\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-142920 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1756430801-464x261.jpg\" alt=\"IMG_20160803_175643080[1]\" width=\"464\" height=\"261\" \/><\/a><figcaption id=\"caption-attachment-142920\" class=\"wp-caption-text\">Prefeito Ol\u00edmpio Cardoso<\/figcaption><\/figure>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: medium;\">Confiante, o prefeito Ol\u00edmpio Cardoso (PDT), falou da sua alegria e agradeceu a presen\u00e7a de todos. \u00a0\u201cVamos vencer as elei\u00e7\u00f5es com mais de mil votos de diferen\u00e7a, obrigado pela presen\u00e7a de voc\u00eas e pelo apoio. Aproveito o espa\u00e7o para dizer a que queria fazer muito mais por Uau\u00e1, infelizmente n\u00e3o temos recursos, mas estamos trabalhando muito e daqui para o final do ano iremos inaugurar v\u00e1rias obras importantes no munic\u00edpio. Acredito muito na gest\u00e3o de Mois\u00e9s e garanto que vai ser melhor do que a minha\u201d. \u00a0<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1812361401\/\" rel=\"attachment wp-att-142929\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-142929 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1812361401-464x261.jpg\" alt=\"IMG_20160803_181236140[1]\" width=\"464\" height=\"261\" \/><\/a><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: medium;\">O candidato a vice-prefeito, Miroval Marques, reafirmou o seu compromisso com a cidade de Uau\u00e1. \u201c<span class=\"x_apple-converted-space\">Queremos fortalecer a equipe de trabalho para eleger o nosso candidato a prefeito Mois\u00e9s. O partido dos trabalhadores foi o partido quem apresentou a melhor condi\u00e7\u00e3o de ajudar em um projeto para contribuir com Uau\u00e1, tanto \u00e9 que \u00e9 o partido que vem sendo mais apedrejado hoje neste munic\u00edpio por conta da coragem e atitude que tomamos de compor um projeto juntamente com Mois\u00e9s, e eu quero agradecer a cada um de voc\u00eas que est\u00e3o no projeto. Estamos juntos para conquistar o poder e continuar trabalhando por Uau\u00e1. Quero dizer a Mois\u00e9s que ele ter\u00e1 um parceiro, companheiro, amigo, e sobre tudo, um colaborador para que os nossos projetos sejam aprovados e conduzidos da melhor forma poss\u00edvel neste munic\u00edpio. Dia 1\u00ba de janeiro iniciaremos uma nova hist\u00f3ria neste munic\u00edpio\u201d, garantiu.<\/span><\/span><\/p>\n<figure id=\"attachment_142916\" aria-describedby=\"caption-attachment-142916\" style=\"width: 464px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1542159981\/\" rel=\"attachment wp-att-142916\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-142916 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1542159981-464x261.jpg\" alt=\"IMG_20160803_154215998[1]\" width=\"464\" height=\"261\" \/><\/a><figcaption id=\"caption-attachment-142916\" class=\"wp-caption-text\">Miroval e Mois\u00e9s s\u00e3o aplaudidos de p\u00e9 no momento em que s\u00e3o chamados para comporem a mesa<\/figcaption><\/figure>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span class=\"x_apple-converted-space\"><span style=\"font-size: medium;\">Marques ainda destacou que mesmo fazendo oposi\u00e7\u00e3o, sempre trabalhou para construir a harmonia. \u201cEst\u00e3o criticando o nosso partido por conta que tomamos essa atitude de caminhar junto com Mois\u00e9s, eu fiz oposi\u00e7\u00e3o e me aliei com o atual governo e muitos acham que eu perdi a coer\u00eancia, a \u00e9tica e minha dignidade, mas n\u00e3o aconteceu isso, vou continuar trabalhando com os mesmos princ\u00edpios e na mesma modalidade que me fiz gente, cidad\u00e3o e pol\u00edtico. Outra coisa que destaco \u00e9 que as pessoas dizem que vice n\u00e3o \u00e9 nada, mas na gest\u00e3o de Mois\u00e9s eu acredito que isso n\u00e3o vai acontecer, eu vou continuar trabalhando e fortalecendo o meu espa\u00e7o\u201d.<\/span><\/span><\/p>\n<figure id=\"attachment_142933\" aria-describedby=\"caption-attachment-142933\" style=\"width: 464px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1833034931\/\" rel=\"attachment wp-att-142933\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-142933 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1833034931-464x261.jpg\" alt=\"IMG_20160803_183303493[1]\" width=\"464\" height=\"261\" \/><\/a><figcaption id=\"caption-attachment-142933\" class=\"wp-caption-text\">Emocionado, Mois\u00e9s Ribeiro se comprometeu em trabalhar mais ainda pelo povo<\/figcaption><\/figure>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: medium;\"><span class=\"x_apple-converted-space\">Com o lema \u2018Juntos somos fortes e unidos venceremos\u2019, <\/span>o pr\u00e9-candidato a prefeito Mois\u00e9s Ribeiro ressaltou as conquistas da gest\u00e3o Ol\u00edmpio e disse que \u00e9 preciso garantir que elas avancem. \u201cAgrade\u00e7o ao prefeito Ol\u00edmpio pelo apoio e digo que a gente ainda vai precisar de voc\u00ea para nos ajudar, fique sabendo que n\u00f3s n\u00e3o iremos deixar voc\u00ea pendurar a chuteira. Vamos administrar o nosso munic\u00edpio com os filhos de Uau\u00e1 e n\u00e3o com pessoas que n\u00e3o residem aqui, quem tem compromisso com voc\u00eas somos n\u00f3s\u201d, alertou.<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1545352061\/\" rel=\"attachment wp-att-142928\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-142928 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1545352061-464x261.jpg\" alt=\"IMG_20160803_154535206[1]\" width=\"464\" height=\"261\" \/><\/a><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: medium;\">Ainda assim, ele lembrou da sua trajet\u00f3ria pol\u00edtica. \u201cEu lutei com honestidade e compet\u00eancia para estar aqui. Todos sabem que\u00a0<\/span><span style=\"font-size: medium;\">tenho servi\u00e7os prestados mesmo antes de ser candidato \u00e0 prefeito ou vereador. A nossa candidatura \u00e9 oriunda de muitos trabalhos prestados, e com isso, acredito que a nossa vit\u00f3ria ser\u00e1 esmagadora no dia 02 de outubro&#8221;. Mois\u00e9s solicitou das pessoas que evite confronto com os opositores. &#8220;<\/span><span style=\"font-size: medium;\">Quero pedir a voc\u00eas que vamos esquecer a oposi\u00e7\u00e3o e mostrar para cada um qual \u00e9 o nosso projeto, n\u00e3o precisamos denegrir ningu\u00e9m, voc\u00eas nos conhecem bastante. Vamos trabalhar para modificar o que n\u00e3o conseguimos nestes \u00faltimos 4 anos, e com apoio de todos vamos fazer a diferen\u00e7a&#8221;, concluiu.<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Na \u00faltima segunda-feira (01) foi realizada a conven\u00e7\u00e3o do PCdoB que homologou o nome de Lindomar Dantas, como pr\u00e9-candidato a prefeito, e Jo\u00e3o Alves (PSC), como vice. Nesta sexta-feira (05) ser\u00e1 a conven\u00e7\u00e3o do PMDB que vai referendar o nome de Jorge Logo como pr\u00e9-candidato a prefeito e Z\u00e9 do Eca como vice (PSC).<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1718582981\/\" rel=\"attachment wp-att-142932\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-142932 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1718582981-464x261.jpg\" alt=\"IMG_20160803_171858298[1]\" width=\"464\" height=\"261\" \/><\/a> <a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1712215971\/\" rel=\"attachment wp-att-142931\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-142931 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1712215971-464x261.jpg\" alt=\"IMG_20160803_171221597[1]\" width=\"464\" height=\"261\" \/><\/a> <a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1628390241\/\" rel=\"attachment wp-att-142930\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-142930 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1628390241-464x261.jpg\" alt=\"IMG_20160803_162839024[1]\" width=\"464\" height=\"261\" \/><\/a> <a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1545157701\/\" rel=\"attachment wp-att-142926\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-142926 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1545157701-464x261.jpg\" alt=\"IMG_20160803_154515770[1]\" width=\"464\" height=\"261\" \/><\/a> <a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1544475571\/\" rel=\"attachment wp-att-142925\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-142925 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1544475571-464x261.jpg\" alt=\"IMG_20160803_154447557[1]\" width=\"464\" height=\"261\" \/><\/a> <a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1501437311\/\" rel=\"attachment wp-att-142922\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-142922 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1501437311-464x261.jpg\" alt=\"IMG_20160803_150143731[1]\" width=\"464\" height=\"261\" \/><\/a> <a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1515427541\/\" rel=\"attachment wp-att-142923\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-142923 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1515427541-464x261.jpg\" alt=\"IMG_20160803_151542754[1]\" width=\"464\" height=\"261\" \/><\/a> <a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1545296141\/\" rel=\"attachment wp-att-142924\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-142924 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1545296141-464x261.jpg\" alt=\"IMG_20160803_154529614[1]\" width=\"464\" height=\"261\" \/><\/a> <a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1543027851\/\" rel=\"attachment wp-att-142917\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-142917 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1543027851-464x261.jpg\" alt=\"IMG_20160803_154302785[1]\" width=\"464\" height=\"261\" \/><\/a> <a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1536025191\/\" rel=\"attachment wp-att-142915\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-142915 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1536025191-464x261.jpg\" alt=\"IMG_20160803_153602519[1]\" width=\"464\" height=\"261\" \/><\/a> <a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1536304321\/\" rel=\"attachment wp-att-142913\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-142913 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1536304321-464x261.jpg\" alt=\"IMG_20160803_153630432[1]\" width=\"464\" height=\"261\" \/><\/a> <a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1539517561\/\" rel=\"attachment wp-att-142914\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-142914 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1539517561-464x261.jpg\" alt=\"IMG_20160803_153951756[1]\" width=\"464\" height=\"261\" \/><\/a> <a href=\"https:\/\/acaopopular.net\/jornal\/mais-de-duas-mil-pessoas-comparecem-a-convencao-de-moises-ribeiro-em-uaua-veja-as-imagens\/img_20160803_1538582251\/\" rel=\"attachment wp-att-142912\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-142912 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1538582251-464x261.jpg\" alt=\"IMG_20160803_153858225[1]\" width=\"464\" height=\"261\" \/><\/a><\/p>\n<p class=\"x_MsoNormal\"><span style=\"font-size: medium;\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Apoios do vice-governador Jo\u00e3o Le\u00e3o, do governador Rui Costa, e outras lideran\u00e7as&#8221;, informou M\u00e1rio Negromonte.<\/p>\n","protected":false},"author":5,"featured_media":142915,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4,6],"tags":[],"class_list":["post-142911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160803_1536025191.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/142911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=142911"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/142911\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/142915"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=142911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=142911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=142911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}