{"id":143130,"date":"2016-08-05T13:54:26","date_gmt":"2016-08-05T16:54:26","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=143130"},"modified":"2016-08-05T14:15:53","modified_gmt":"2016-08-05T17:15:53","slug":"hospital-regional-de-juazeiro-abre-processo-seletivo","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/hospital-regional-de-juazeiro-abre-processo-seletivo\/","title":{"rendered":"Hospital Regional de Juazeiro abre Processo Seletivo"},"content":{"rendered":"<p dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-143132\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/download-1.jpg\" alt=\"download (1)\" width=\"240\" height=\"160\" \/><\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">No per\u00edodo de 08 a 10 de Agosto de 2016, o Hospital Regional de Juazeiro (Gest\u00e3o APMI) abrir\u00e1 inscri\u00e7\u00f5es do processo seletivo, para cadastro reserva, com validade de 06 meses, nas \u00e1reas de Enfermagem, auxiliar administrativo, agente operacional e motorista, conforme requisitos abaixo especificados:<\/p>\n<ul>\n<li dir=\"ltr\">\n<p dir=\"ltr\" style=\"text-align: justify;\">Enfermagem<\/p>\n<\/li>\n<\/ul>\n<p dir=\"ltr\" style=\"text-align: justify;\">Requisitos:<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Ensino Superior Completo (Enfermeiros)<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Curso T\u00e9cnico em Enfermagem (T\u00e9cnico em Enfermagem)<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">M\u00ednimo de 06 meses de experi\u00eancia.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Possuir inscri\u00e7\u00e3o no Conselho Regional de Enfermagem da Bahia, em situa\u00e7\u00e3o regular.<\/p>\n<ul style=\"text-align: justify;\">\n<li dir=\"ltr\">\n<p dir=\"ltr\">Auxiliar Administrativo<\/p>\n<\/li>\n<\/ul>\n<p dir=\"ltr\" style=\"text-align: justify;\">Requisitos:<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Ensino M\u00e9dio Completo<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Inform\u00e1tica B\u00e1sica<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">M\u00ednimo de 06 meses de experi\u00eancia.<\/p>\n<ul style=\"text-align: justify;\">\n<li dir=\"ltr\">\n<p dir=\"ltr\">Agente operacional para \u00e1rea de Higieniza\u00e7\u00e3o Hospitalar\/ Agente de Coleta e lavanderia<\/p>\n<\/li>\n<\/ul>\n<p dir=\"ltr\" style=\"text-align: justify;\">Requisitos:<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Ensino M\u00e9dio Completo.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">M\u00ednimo de 06 meses de experi\u00eancia.<\/p>\n<ul style=\"text-align: justify;\">\n<li dir=\"ltr\">\n<p dir=\"ltr\">Motorista<\/p>\n<\/li>\n<\/ul>\n<p dir=\"ltr\" style=\"text-align: justify;\">Requisitos:<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Ensino M\u00e9dio Completo<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Habilita\u00e7\u00e3o na categoria D;<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Curso de Condutor de ve\u00edculo de Emerg\u00eancia (se para motorista de ambul\u00e2ncia).<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Os candidatos interessados dever\u00e3o entregar o curr\u00edculo na recep\u00e7\u00e3o Central do Hospital Regional de Juazeiro. \u00c9 de suma import\u00e2ncia que o candidato esteja com seus dados atualizados, principalmente n\u00famero de telefone, pois todos os contatos ser\u00e3o realizados exclusivamente por este meio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No per\u00edodo de 08 a 10 de Agosto de 2016, o Hospital Regional de Juazeiro (Gest\u00e3o APMI) abrir\u00e1 inscri\u00e7\u00f5es do processo seletivo, para cadastro reserva, com validade de 06 meses, nas \u00e1reas de Enfermagem, auxiliar administrativo, agente operacional e motorista, conforme requisitos abaixo especificados: Enfermagem Requisitos: Ensino Superior Completo (Enfermeiros) Curso T\u00e9cnico em Enfermagem (T\u00e9cnico [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":143144,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4,6],"tags":[],"class_list":["post-143130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/download-1-1.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/143130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=143130"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/143130\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/143144"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=143130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=143130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=143130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}