{"id":143319,"date":"2016-08-06T17:17:02","date_gmt":"2016-08-06T20:17:02","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=143319"},"modified":"2016-08-06T17:28:17","modified_gmt":"2016-08-06T20:28:17","slug":"durante-convencao-vereadores-e-liderancas-politicas-de-sobradinho-declaram-apoio-ao-pre-candidato-a-prefeito-tiziu","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/durante-convencao-vereadores-e-liderancas-politicas-de-sobradinho-declaram-apoio-ao-pre-candidato-a-prefeito-tiziu\/","title":{"rendered":"Durante conven\u00e7\u00e3o, vereadores e lideran\u00e7as pol\u00edticas de Sobradinho declaram apoio ao pr\u00e9-candidato \u00e0 prefeito Tiziu"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>A\u00e7\u00e3o Popular (AP)<\/strong><\/p>\n<p style=\"text-align: justify;\">Durante a conven\u00e7\u00e3o realizada na noite de ontem (05), em Sobradinho, os vereadores e lideran\u00e7as pol\u00edticas do munic\u00edpio declararam apoio a pr\u00e9-candidatura de Ademilson da Rocha, o popular Tiziu (PT) e o seu vice, Paulo Balbino (PRB). O evento aconteceu no Terminal Pesqueiro e contou com a presen\u00e7a do presidente do PDT Municipal, Evaristo J\u00fanior, o ex-prefeito de Cura\u00e7\u00e1 Salvador Lopes (PT), Luciano Rocha (PSOL) &#8211; que desistiu da sua pr\u00e9-candidatura para apoiar Tiziu -, o ex-prefeito de Sobradinho Genilson Silva (PT), popula\u00e7\u00e3o e demais lideran\u00e7as pol\u00edticas.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/durante-convencao-vereadores-e-liderancas-politicas-de-sobradinho-declaram-apoio-ao-pre-candidato-a-prefeito-tiziu\/convencao12\/\" rel=\"attachment wp-att-143346\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-143346 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/convencao12-464x261.jpg\" alt=\"convencao12\" width=\"464\" height=\"261\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">O vereador C\u00edcero de Lima, conhecido como Batata (PSB), afirmou que a melhor op\u00e7\u00e3o para a cidade de Sobradinho \u00e9 Tiziu. \u201cAgrade\u00e7o a oportunidade de estarmos reunido aqui mais uma vez, quero dizer a voc\u00eas que a melhor op\u00e7\u00e3o para melhorar a nossa cidade \u00e9 o nosso amigo Tiziu, ele tem habilidade e vai trazer muitas conquistas para o nosso munic\u00edpio\u201d. Concorrendo a reelei\u00e7\u00e3o, o pr\u00e9-candidato a vereador Francisco Canind\u00e9 (PRP), disse que Sobradinho vive um novo momento. \u201cEstou muito feliz e temos muito o que comemorar, este evento \u00e9 uma largada rumo a vit\u00f3ria e contamos com o apoio de todos voc\u00eas no dia 02 de outubro\u201d.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/durante-convencao-vereadores-e-liderancas-politicas-de-sobradinho-declaram-apoio-ao-pre-candidato-a-prefeito-tiziu\/convencao8\/\" rel=\"attachment wp-att-143342\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-143342 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/convencao8-464x261.jpg\" alt=\"convencao8\" width=\"464\" height=\"261\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Por sua vez, o vereador Manoel Messias (PV), reformou as palavras de Canind\u00e9 e disse que Sobradinho vive a era da liberta\u00e7\u00e3o. \u201cHoje \u00e9 a festa da liberta\u00e7\u00e3o do povo de Sobradinho e tamb\u00e9m da reconstru\u00e7\u00e3o, vamos rumo a nossa vit\u00f3ria e a nossa resposta ser\u00e1 dada nas urnas\u201d, avisou.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/durante-convencao-vereadores-e-liderancas-politicas-de-sobradinho-declaram-apoio-ao-pre-candidato-a-prefeito-tiziu\/convencao5-2\/\" rel=\"attachment wp-att-143339\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-143339 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/convencao5-464x261.jpg\" alt=\"convencao5\" width=\"464\" height=\"261\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Confiante, o presidente do PDT Evaristo, disse que est\u00e1 na hora da popula\u00e7\u00e3o de Sobradinho se libertar da fam\u00edlia Berti. \u201cContamos com o apoio de diversos partidos e de voc\u00eas tamb\u00e9m, a fam\u00edlia Berti enganou a popula\u00e7\u00e3o durante 12 anos e essa nova chapa de Tiziu e Paulo vem para ganhar as elei\u00e7\u00f5es e para trazer melhorias para a nossa cidade. Esse coronel Saru\u00ea que vem administrando a nossa cidade n\u00e3o pode enganar voc\u00eas por mais 4 anos\u201d, alfinetou.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/durante-convencao-vereadores-e-liderancas-politicas-de-sobradinho-declaram-apoio-ao-pre-candidato-a-prefeito-tiziu\/convencao4-3\/\" rel=\"attachment wp-att-143338\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-143338 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/convencao4-464x261.jpg\" alt=\"convencao4\" width=\"464\" height=\"261\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Ovacionado pelo p\u00fablico presente, o Doutor Luciano, falou sobre a desist\u00eancia da sua pr\u00e9-candidatura e os motivos que o levaram apoiar Tiziu. \u201cObrigado gente pelo apoio, n\u00e3o podemos mais dar oportunidade a essa fam\u00edlia que vem administrado Sobradinho. Eu vim para o grupo de Tiziu para fortalecer mais ainda e por que sei que ele tem o melhor projeto para Sobradinho e digo a voc\u00eas eu agora sou 13\u201d.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/durante-convencao-vereadores-e-liderancas-politicas-de-sobradinho-declaram-apoio-ao-pre-candidato-a-prefeito-tiziu\/convencao11\/\" rel=\"attachment wp-att-143345\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-143345 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/convencao11-464x261.jpg\" alt=\"convencao11\" width=\"464\" height=\"261\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Presente no evento, a ex-primeira Dama Marizalva Ribeiro, disse que acredita nos projetos de Tiziu. \u201cEstamos vivendo um novo tempo de mudan\u00e7as, Tiziu eu quero que voc\u00ea der continuidade as pol\u00edticas p\u00fablicas e traga melhorias para a nossa cidade\u201d. O ex-prefeito de Sobradinho Gilberto de Balbino disse que chegou a hora de resgatar o munic\u00edpio. \u201c\u00c9 com muito prazer e alegria que estamos com esta chapa. Vamos resgatar a nossa cidade e dar novos rumos\u201d.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/durante-convencao-vereadores-e-liderancas-politicas-de-sobradinho-declaram-apoio-ao-pre-candidato-a-prefeito-tiziu\/convencao3-4\/\" rel=\"attachment wp-att-143337\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-143337 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/convencao3-464x261.jpg\" alt=\"convencao3\" width=\"464\" height=\"261\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Por outro lado, o ex-prefeito de Sobradinho Genilson Silva, falou da sua emo\u00e7\u00e3o e da uni\u00e3o das fam\u00edlias Balbino e Silva. \u201cOs nossos pais devem est\u00e1 bastante felizes com essa uni\u00e3o e n\u00f3s tamb\u00e9m estamos porque queremos o melhor para Sobradinho. Tiziu \u00e9 um jovem de 36 anos e que tem compromisso de resgatar a hist\u00f3ria de Sobradinho\u201d. O pr\u00e9-candidato a vice-prefeito Paulo disse que a sua chapa conta com as duas fam\u00edlias que mais trabalharam pela cidade. \u201c\u00c9 um grande sonho que estamos realizando, conseguimos juntar em nosso palanque as duas fam\u00edlias que mais trabalharam pela nossa cidade e isso j\u00e1 foi comprovado. Agora precisamos unir mais ainda e darmos a resposta no dia 2 de outubro\u201d.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/durante-convencao-vereadores-e-liderancas-politicas-de-sobradinho-declaram-apoio-ao-pre-candidato-a-prefeito-tiziu\/convencao10\/\" rel=\"attachment wp-att-143344\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-143344 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/convencao10-464x261.jpg\" alt=\"convencao10\" width=\"464\" height=\"261\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Confiante, o pr\u00e9-candidato a prefeito Tiziu agradeceu a Deus e a presen\u00e7a de todos. \u201cAgrade\u00e7o a Deus e a voc\u00eas pela oportunidade de fazermos este debate, \u00e9 aqui que iremos construir os nossos projetos e contamos com o apoio de todos voc\u00eas. Vamos administrar o nosso munic\u00edpio com a\u00e7\u00f5es voltadas para voc\u00eas\u201d, concluiu.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/acaopopular.net\/jornal\/durante-convencao-vereadores-e-liderancas-politicas-de-sobradinho-declaram-apoio-ao-pre-candidato-a-prefeito-tiziu\/convencao1-5\/\" rel=\"attachment wp-att-143335\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-143335 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/convencao1-464x261.jpg\" alt=\"convencao1\" width=\"464\" height=\"261\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Tiziu conta com os apoios do PRB, PDT, PTC, PV, PCdoB, PRB, PPS, PRP, PRTB, DEM e PEN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante a conven\u00e7\u00e3o realizada na noite de ontem (05), em Sobradinho, os vereadores e lideran\u00e7as pol\u00edticas do munic\u00edpio declararam apoio a pr\u00e9-candidatura de Ademi<\/p>\n","protected":false},"author":5,"featured_media":143343,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4,6,1],"tags":[],"class_list":["post-143319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-municipios","category-sem-categoria"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/convencao9.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/143319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=143319"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/143319\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/143343"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=143319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=143319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=143319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}