{"id":143388,"date":"2016-08-07T14:55:52","date_gmt":"2016-08-07T17:55:52","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=143388"},"modified":"2016-08-07T14:55:54","modified_gmt":"2016-08-07T17:55:54","slug":"miguel-defende-programa-habitacional-na-zona-rural","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/miguel-defende-programa-habitacional-na-zona-rural\/","title":{"rendered":"Miguel defende programa habitacional na zona rural"},"content":{"rendered":"<div class=\"x_gmail_default\"><\/div>\n<div class=\"x_gmail_quote\">\n<div><\/div>\n<div>A inexist\u00eancia de um programa de habita\u00e7\u00e3o popular no interior de Petrolina foi um dos principais pontos discutidos no encontro de Miguel Coelho com os colonos do Projeto Nilo Coelho. A reuni\u00e3o ocorrida, neste s\u00e1bado (05), contou tamb\u00e9m com a presen\u00e7a da pr\u00e9-candidata a vice Luska Portela, do deputado Guilherme Coelho e do senador Fernando Bezerra.<\/div>\n<div><a href=\"https:\/\/acaopopular.net\/jornal\/miguel-defende-programa-habitacional-na-zona-rural\/miguel-promessa\/\" rel=\"attachment wp-att-143389\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-143389\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/miguel-promessa-300x200.jpeg\" alt=\"miguel promessa\" width=\"300\" height=\"200\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/miguel-promessa-300x200.jpeg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/miguel-promessa-768x512.jpeg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/miguel-promessa-620x414.jpeg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/miguel-promessa-1024x683.jpeg 1024w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/miguel-promessa-160x106.jpeg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/miguel-promessa.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/div>\n<div>Na conversa com Miguel, os moradores afirmaram que existe uma car\u00eancia de 5 mil moradias na zona rural petrolinense. Apesar disso, a comunidade alega que nos \u00faltimos sete anos nenhuma casa foi constru\u00edda por meio de pol\u00edticas p\u00fablicas de habita\u00e7\u00e3o. &#8220;O Governo Federal fez mais de 9 mil casas na \u00e1rea urbana e nenhuma na zona rural. Isso ocorreu porque um ex-secret\u00e1rio da atual gest\u00e3o fez uma portaria que pro\u00edbe o Minha Casa, Minha Vida no interior. Todos n\u00f3s somos filhos da mesma cidade, ent\u00e3o, porque o tratamento diferente?&#8221;, criticou Miguel Coelho.<\/div>\n<div><\/div>\n<div>O pr\u00e9-candidato a prefeito\u00a0destacou que isso pode ser transformado atrav\u00e9s de uma mudan\u00e7a de prioridades e com a ajuda do alinhamento de seu grupo pol\u00edtico. &#8220;Hoje, n\u00f3s temos tr\u00eas ministros, um senador e deputados federais ao nosso lado. Toda essa for\u00e7a pol\u00edtica pode ser decisiva para atra\u00e7\u00e3o de mais investimentos. Mas acima disso, \u00e9 preciso a vontade pol\u00edtica para que o programa Minha Casa Minha Vida, Minha Vida atenda tamb\u00e9m o morador do interior de Petrolina&#8221;, defendeu Miguel.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A inexist\u00eancia de um programa de habita\u00e7\u00e3o popular no interior de Petrolina foi um dos principais pontos discutidos no encontro de Miguel Coelho com os colonos do<\/p>\n","protected":false},"author":5,"featured_media":143389,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4,6],"tags":[],"class_list":["post-143388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/miguel-promessa.jpeg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/143388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=143388"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/143388\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/143389"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=143388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=143388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=143388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}