{"id":143419,"date":"2016-08-07T17:04:07","date_gmt":"2016-08-07T20:04:07","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=143419"},"modified":"2016-08-07T17:04:07","modified_gmt":"2016-08-07T20:04:07","slug":"paralimpicos-do-rio","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/paralimpicos-do-rio\/","title":{"rendered":"Paral\u00edmpicos do Rio"},"content":{"rendered":"<header class=\"article-header\">\n<h1 class=\"article-title\"><\/h1>\n<h2 class=\"article-subtitle\"><em>Toda a delega\u00e7\u00e3o paral\u00edmpica do pa\u00eds est\u00e1 proibida de competir<\/em><\/h2>\n<div class=\"article-author\"><\/div>\n<\/header>\n<section class=\"article-content\">\n<div class=\"featured-image\">\n<div class=\"image\"><img decoding=\"async\" class=\"attachment-featured-image size-featured-image wp-post-image lazyloaded\" title=\"Vista de um bon\u00e9 da R\u00fassia na praia Pepe, no Rio de Janeiro - 26\/07\/2016\" src=\"http:\/\/abrilveja.files.wordpress.com\/2016\/07\/bone-russia-praia-rio-de-janeiro.jpg?quality=70&amp;strip=all&amp;w=680&amp;h=453&amp;crop=1\" alt=\"Vista de um bon\u00e9 da R\u00fassia na praia Pepe, no Rio de Janeiro - 26\/07\/2016\" data-src=\"http:\/\/abrilveja.files.wordpress.com\/2016\/07\/bone-russia-praia-rio-de-janeiro.jpg?quality=70&amp;strip=all&amp;w=680&amp;h=453&amp;crop=1\" data-srcset=\"\" data-sizes=\"\" \/><\/div>\n<p class=\"caption\">Delega\u00e7\u00e3o paral\u00edmpica da R\u00fassia foi banida dos Jogos do Rio. (Yasuyoshi Chiba\/AFP)<\/p>\n<\/div>\n<p>Nenhum atleta paral\u00edmpico da R\u00fassia vir\u00e1 aos Jogos do Rio de Janeiro por causa do esc\u00e2ndalo de doping no pa\u00eds, decidiu neste domingo o Comit\u00ea Paral\u00edmpico Internacional (IPC). A R\u00fassia j\u00e1 estava temporariamente\u00a0suspensa desde a divulga\u00e7\u00e3o do relat\u00f3rio McLaren, que revelou um esquema de doping patrocinado pelo governo.<\/p>\n<p>A decis\u00e3o un\u00e2nime do IPC foi mais r\u00edgida do que a do Comit\u00ea Ol\u00edmpico Internacional (COI), que\u00a0liberou quase 300 atletas russos\u00a0sem hist\u00f3rico de dopagem. \u201cO sistema antidoping na R\u00fassia \u00e9 falho, corrupto e totalmente comprometido\u201d, explicou o presidente do IPC\u00a0Philip Craven.<\/p>\n<p>O IPC tamb\u00e9m argumenta que o Comit\u00ea Paral\u00edmpico da R\u00fassia\u00a0n\u00e3o cumpriu diversas\u00a0responsabilidades e obriga\u00e7\u00f5es \u2014 principalmente\u00a0com o C\u00f3digo Antidoping do IPC e com o C\u00f3digo Antidoping Mundial, do qual a R\u00fassia tamb\u00e9m \u00e9 signat\u00e1ria.<\/p>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Toda a delega\u00e7\u00e3o paral\u00edmpica do pa\u00eds est\u00e1 proibida de competir<\/p>\n","protected":false},"author":5,"featured_media":143420,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4,6],"tags":[],"class_list":["post-143419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/bone-russia-praia-rio-de-janeiro.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/143419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=143419"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/143419\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/143420"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=143419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=143419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=143419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}