{"id":143603,"date":"2016-08-08T15:06:29","date_gmt":"2016-08-08T18:06:29","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=143603"},"modified":"2016-08-08T15:06:29","modified_gmt":"2016-08-08T18:06:29","slug":"no-mesmo-dia-em-que-tentaram-tirar-a-vida-do-presidente-do-pt-de-uaua-dois-homens-andavam-com-mala-cheia-de-dinheiro-comprando-votos-no-interior","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/no-mesmo-dia-em-que-tentaram-tirar-a-vida-do-presidente-do-pt-de-uaua-dois-homens-andavam-com-mala-cheia-de-dinheiro-comprando-votos-no-interior\/","title":{"rendered":"No mesmo dia em que tentaram tirar a vida do presidente do PT de Uau\u00e1, dois homens andavam com mala cheia de dinheiro comprando votos no interior"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>A\u00e7\u00e3o Popular (AP)<\/strong><\/p>\n<p style=\"text-align: justify;\">No \u00faltimo s\u00e1bado (06) quando dois homens em uma moto tentavam tirar a vida do presidente do Diret\u00f3rio Municipal do Partido dos Trabalhadores (PT), em Uau\u00e1, Carlos Sebasti\u00e3o, outras duas pessoas provavelmente de Juazeiro &#8211; mas com resid\u00eancias fixas em Uau\u00e1 &#8211; andavam em localidades da zona rural do munic\u00edpio com uma mala cheia de dinheiro comprando votos de lideran\u00e7as para seu pr\u00e9-candidato a prefeito.<\/p>\n<figure id=\"attachment_37107\" aria-describedby=\"caption-attachment-37107\" style=\"width: 464px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/acaopopular.net\/jornal\/policia-federal-apreende-mala-com-r-449-mil-em-foz-do-iguacu\/mala-dinheiro\/\" rel=\"attachment wp-att-37107\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37107 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2014\/01\/mala-dinheiro-464x304.jpg\" alt=\"mala-dinheiro\" width=\"464\" height=\"304\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2014\/01\/mala-dinheiro-464x304.jpg 464w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2014\/01\/mala-dinheiro-300x197.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2014\/01\/mala-dinheiro-160x106.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2014\/01\/mala-dinheiro.jpg 595w\" sizes=\"auto, (max-width: 464px) 100vw, 464px\" \/><\/a><figcaption id=\"caption-attachment-37107\" class=\"wp-caption-text\">Ilustra\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">A den\u00fancia partiu dos pr\u00f3prios moradores que se mostraram chateados com a maneira inescrupulosa dos dois meliantes. &#8220;Eles procuram at\u00e9 pessoas apaixonadas pelos dois grupos pol\u00edticos, os quais s\u00e3o seus advers\u00e1rios&#8221;, informou uma das fontes.<\/p>\n<p style=\"text-align: justify;\">&#8220;Essas duas pe\u00e7as s\u00e3o velhas conhecidas aqui em nossa cidade. Elas se\u00a0socaram nos lugares mais vulner\u00e1veis no interior do munic\u00edpio nesse \u00faltimo final de semana para cometerem o crime abertamente. J\u00e1 estamos com todas as provas e vamos solicitar da justi\u00e7a a pris\u00e3o dos dois meliantes, e ainda, \u00a0a puni\u00e7\u00e3o para o candidato deles e todas as pessoas envolvidas&#8221;,\u00a0informou o advogado das v\u00edtimas.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Essas duas pe\u00e7as s\u00e3o velhas conhecidas aqui em nossa cidade. Elas se socaram nos lugares mais vulner\u00e1veis no interior do munic\u00edpio nesse \u00faltimo fin<\/p>\n","protected":false},"author":5,"featured_media":37107,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4,6],"tags":[],"class_list":["post-143603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2014\/01\/mala-dinheiro.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/143603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=143603"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/143603\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/37107"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=143603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=143603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=143603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}