{"id":143750,"date":"2016-08-09T08:48:36","date_gmt":"2016-08-09T11:48:36","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=143750"},"modified":"2016-08-09T08:48:37","modified_gmt":"2016-08-09T11:48:37","slug":"remanso-durante-convencao-eulalio-braga-diz-que-municipio-esta-ao-deus-dara","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/remanso-durante-convencao-eulalio-braga-diz-que-municipio-esta-ao-deus-dara\/","title":{"rendered":"Remanso: Durante conven\u00e7\u00e3o, Eul\u00e1lio Braga diz que munic\u00edpio est\u00e1 ao &#8216;deus dar\u00e1&#8217;"},"content":{"rendered":"<div class=\"_rp_h\" tabindex=\"0\">\n<div class=\"ms-font-color-neutralPrimary ms-font-weight-light ms-font-xxl _rp_i\" style=\"text-align: justify;\"><img decoding=\"async\" class=\"_pe_D _pe_12\" draggable=\"false\" src=\"https:\/\/outlook.live.com\/owa\/service.svc\/s\/GetPersonaPhoto?email=thalitajornalista%40hotmail.com&amp;UA=0&amp;size=HR96x96\" \/><\/div>\n<\/div>\n<div tabindex=\"-1\">\n<div tabindex=\"-1\">\n<div tabindex=\"0\">\n<div class=\"_rp_15\" tabindex=\"-1\">\n<div class=\"_rp_J4 ms-border-color-neutralLight ShowReferenceAttachmentsLinks\" tabindex=\"-1\">\n<div class=\"_rp_V4\">\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div>\n<div id=\"Item.MessagePartBody\" class=\"_rp_L4\">\n<div id=\"Item.MessageUniqueBody\" class=\"_rp_M4 ms-font-weight-regular ms-font-color-neutralDark rpHighlightAllClass rpHighlightBodyClass\" tabindex=\"0\">\n<div class=\"rps_df2\">\n<div>\n<div class=\"x_hmmessage\">\n<div dir=\"ltr\">\n<div><strong>A\u00e7\u00e3o Popular (AP)<\/strong><\/p>\n<div dir=\"ltr\">\n<p class=\"x_ecxMsoNormal\" style=\"text-align: justify;\">O presidente do PR em Remanso e pr\u00e9-candidato a vereador, Eul\u00e1lio Braga, durante a homologa\u00e7\u00e3o<span class=\"x_ecxapple-converted-space\">\u00a0da chapa do candidato a prefeito de Remanso <\/span>Marcos Palmeira (PCdoB) e do seu vice-prefeito Fl\u00e1vio da UNIFAN (PRTB), na \u00faltima sexta-feira (05), reafirmou o seu apoio \u00e0 chapa de Marcos e disse que acredita na sua candidatura.<\/p>\n<figure id=\"attachment_143751\" aria-describedby=\"caption-attachment-143751\" style=\"width: 464px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/acaopopular.net\/jornal\/remanso-durante-convencao-eulalio-braga-diz-que-municipio-esta-ao-deus-dara\/img_20160805_145028893\/\" rel=\"attachment wp-att-143751\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-143751 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160805_145028893-464x261.jpg\" alt=\"IMG_20160805_145028893\" width=\"464\" height=\"261\" \/><\/a><figcaption id=\"caption-attachment-143751\" class=\"wp-caption-text\">Eul\u00e1lio Braga mostra ser um pulso forte para as pr\u00f3ximas elei\u00e7\u00f5es<\/figcaption><\/figure>\n<p class=\"x_ecxMsoNormal\" style=\"text-align: justify;\">\u201cEsta \u00e9 a maior conven\u00e7\u00e3o de todos os tempos que participo na minha terra, n\u00f3s vamos tirar Remanso da lista negra de Bras\u00edlia. Esta chapa representa o sonho de todos remansenses, ela vai resgatar a auto-estima e com isso iremos ter dias melhores no nosso munic\u00edpio que atualmente encontra-se a \u2018deus dar\u00e1\u2019. Contamos com a ajuda de voc\u00eas no dia 02 de outubro\u201d, discursou.<\/p>\n<figure id=\"attachment_143752\" aria-describedby=\"caption-attachment-143752\" style=\"width: 464px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/acaopopular.net\/jornal\/remanso-durante-convencao-eulalio-braga-diz-que-municipio-esta-ao-deus-dara\/img_20160805_144659946\/\" rel=\"attachment wp-att-143752\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-143752 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160805_144659946-464x261.jpg\" alt=\"IMG_20160805_144659946\" width=\"464\" height=\"261\" \/><\/a><figcaption id=\"caption-attachment-143752\" class=\"wp-caption-text\">Multid\u00e3o aplaudiu discurso<\/figcaption><\/figure>\n<p class=\"x_ecxMsoNormal\" style=\"text-align: justify;\">Ainda assim, ele disse que quer ser a voz dos remansenses na c\u00e2mara. \u201cQuero somar junto com os outros companheiros e com isso colocar a nossa cidade no progresso\u201d, concluiu.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tirar Remanso da lista negra de Bras\u00edlia. Esta chapa representa o sonho de todos remansenses, ela vai resgatar a auto-estima e com isso iremos ter dias melhores no nosso munic\u00edpio que atualmente encontra-se a \u2018deus dar\u00e1\u2019. Contamos com a <\/p>\n","protected":false},"author":5,"featured_media":143751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4,6],"tags":[],"class_list":["post-143750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/IMG_20160805_145028893.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/143750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=143750"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/143750\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/143751"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=143750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=143750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=143750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}