{"id":144407,"date":"2016-08-12T11:32:34","date_gmt":"2016-08-12T14:32:34","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=144407"},"modified":"2016-08-12T11:32:34","modified_gmt":"2016-08-12T14:32:34","slug":"agricultores-de-curaca-poderao-solicitar-titulo-de-terra","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/agricultores-de-curaca-poderao-solicitar-titulo-de-terra\/","title":{"rendered":"Agricultores de Cura\u00e7\u00e1 poder\u00e3o solicitar t\u00edtulo de terra"},"content":{"rendered":"<p style=\"text-align: justify;\">Entre os dias 16 e 19 de agosto, os agricultores que desejam regularizar seu im\u00f3vel rural poder\u00e3o requerer seu t\u00edtulo de terra na modalidade doa\u00e7\u00e3o, de forma gratuita, junto \u00e0 equipe do Cons\u00f3rcio Sustent\u00e1vel do Territ\u00f3rio do S\u00e3o Francisco (Constesf), comparecendo \u00e0 Secretaria de Agricultura do munic\u00edpio.<\/p>\n<p style=\"text-align: justify;\">Para solicitar o t\u00edtulo, o produtor ter\u00e1 que atender a alguns crit\u00e9rios, como nunca ter recebido um t\u00edtulo de terra e possuir uma \u00e1rea abaixo de 100 hectares. Ser\u00e3o atendidas apenas as seguintes comunidades: Fazenda Ic\u00f3 de Cima, Ic\u00f3 de Baixo, Primavera, Vajota, Macambira, Mucambo, Buticudo, Umbuzeiro, Boa Esperan\u00e7a, Jib\u00f3ia, Campinas, Po\u00e7o do Gato, Mandim, Salgado, Fonseca, Riacho do Ic\u00f3, Lajedo, Barro de Vermelho, Laminha, S\u00e3o Jo\u00e3o, Cara\u00edba dos Gomes, Jaquinic\u00f3 I e II, S\u00e3o Bento, Barra do Brejo, Pedra Preta, Brejo, Frade, Logradouro, Jatob\u00e1, Saco da Canoa, Riacho Seco.<\/p>\n<p style=\"text-align: justify;\">O projeto de regulariza\u00e7\u00e3o fundi\u00e1ria \u00e9 uma a\u00e7\u00e3o do Constesf, atrav\u00e9s da Coordena\u00e7\u00e3o de Desenvolvimento Agr\u00e1rio do Estado da Bahia (CDA), da Secretaria de Desenvolvimento Rural (SDR) e tem o objetivo de proporcionar aos agricultores a regulariza\u00e7\u00e3o do seu im\u00f3vel rural atrav\u00e9s do t\u00edtulo de terra na modalidade doa\u00e7\u00e3o. Cada munic\u00edpio do territ\u00f3rio do S\u00e3o Francisco ser\u00e1 atendido com 200 t\u00edtulos de terra, totalizando duas mil fam\u00edlias beneficiadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre os dias 16 e 19 de agosto, os agricultores que desejam regularizar seu im\u00f3vel rural poder\u00e3o requerer seu t\u00edtulo de terra na modalidade doa\u00e7\u00e3o, de forma gratuita, junto \u00e0 equipe do Cons\u00f3rcio Sustent\u00e1vel do Territ\u00f3rio do S\u00e3o Francisco (Constesf), comparecendo \u00e0 Secretaria de Agricultura do munic\u00edpio. Para solicitar o t\u00edtulo, o produtor ter\u00e1 que [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":144408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4,6],"tags":[],"class_list":["post-144407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/agricultores.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/144407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=144407"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/144407\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/144408"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=144407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=144407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=144407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}