{"id":237087,"date":"2018-03-15T03:57:34","date_gmt":"2018-03-15T06:57:34","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=237087"},"modified":"2018-03-15T03:57:34","modified_gmt":"2018-03-15T06:57:34","slug":"mega-sena-acumula-e-premio-pode-chegar-a-r-60-milhoes-no-sabado","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/mega-sena-acumula-e-premio-pode-chegar-a-r-60-milhoes-no-sabado\/","title":{"rendered":"Mega-Sena acumula e pr\u00eamio pode chegar a R$ 60 milh\u00f5es no s\u00e1bado"},"content":{"rendered":"<section class=\"bg-gray-extra\">\n<div class=\"container container-full-width\">\n<div class=\"row\">\n<div class=\"col-sm-10 col-sm-offset-1\">\n<h1 class=\"txt-serif\"><\/h1>\n<h4 class=\"txt-gray mb-0\">A aposta m\u00ednima, de 6 n\u00fameros, custa R$ 3,50. Quanto mais n\u00fameros marcar, maior o pre\u00e7o da aposta e maiores as chances de faturar o pr\u00eamio mais cobi\u00e7ado do pa\u00eds<\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section>\n<div class=\"container container-full-width mt-20 mb-20\">\n<div class=\"row divider-wrapper\">\n<div id=\"esquerda_8_12_1\" class=\"col-sm-10 col-sm-offset-1 col-md-6 mb-35 js-tools-fixed-parent\">\n<article>\n<nav class=\"nav-fix hidden-print js-tools-fixed mb-xs-10 active\" data-id=\"call-action\">\n<div class=\"nav-fix__highlight\"><\/div>\n<\/nav>\n<div><\/div>\n<div id=\"rs_read_this2\" class=\"txt-serif js-article-box article-box article-box-capitalize mt-15\">\n<div class=\"img-mobile-full mb-20\">\n<figure><picture class=\"img-wrapper-img-responsive img-wrapper-center-block\"><source srcset=\"https:\/\/i.em.com.br\/AxxGv3YOGuoQ2rsv4mSVxCFO7DI=\/360x0\/smart\/imgsapp.em.com.br\/app\/noticia_127983242361\/2018\/03\/14\/944195\/20180314212901132461e.jpg 360w\" media=\"(max-width: 767px)\" \/><source srcset=\"https:\/\/i.em.com.br\/j6WIHay4FYXYFfqujRtejj6E1P8=\/675x0\/smart\/imgsapp.em.com.br\/app\/noticia_127983242361\/2018\/03\/14\/944195\/20180314212901132461e.jpg 675w\" media=\"(max-width: 1365px)\" \/><source srcset=\"https:\/\/i.em.com.br\/v_Y6a9Mmc4Ni43kHLltHJreqO3c=\/820x0\/smart\/imgsapp.em.com.br\/app\/noticia_127983242361\/2018\/03\/14\/944195\/20180314212901132461e.jpg 820w\" media=\"(min-width: 1366px)\" \/><source srcset=\"https:\/\/i.em.com.br\/vU0XVFKvrgI1OYdKXyOexEWq7Mg=\/332x0\/smart\/imgsapp.em.com.br\/app\/noticia_127983242361\/2018\/03\/14\/944195\/20180314212901132461e.jpg\" \/><img decoding=\"async\" class=\"initial loading\" title=\"(foto: Reprodu\u00e7\u00e3o\/Internet\/EBC)\" src=\"https:\/\/i.em.com.br\/23SSHh4V0aIwmE5C4GTjfXL1Pn0=\/675x\/smart\/imgsapp.em.com.br\/app\/noticia_127983242361\/2018\/03\/14\/944195\/20180314212901132461e.jpg\" alt=\"(foto: Reprodu\u00e7\u00e3o\/Internet\/EBC)\" data-was-processed=\"true\" \/><\/picture><figcaption class=\"mt-25 pl-40 lenged-with-icon photo\"><small class=\"d-block txt-no-serif txt-gray-base\">(foto: Reprodu\u00e7\u00e3o\/Internet\/EBC)<\/small><\/figcaption><\/figure>\n<\/div>\n<p>A mega-sena acumulou de novo e poder\u00e1 pagar R$ 60 milh\u00f5es j\u00e1 no pr\u00f3ximo s\u00e1bado (17). Segundo a Caixa, os n\u00fameros sorteados na noite desta quarta-feira foram: 04-28-45-48-52-60.<br \/>\nNo sorteio de hoje, concurso 2022, 79 apostas acertaram cinco pontos e v\u00e3o levar a quantia de R$ 47.183,15 cada. Mais de 6 mil apostas fizeram a quadra e recebem R$ 839,50.<br \/>\nPara realizar o sonho de ser o pr\u00f3ximo milion\u00e1rio, voc\u00ea deve marcar de 6 a 15 n\u00fameros do volante, podendo deixar que o sistema escolha os n\u00fameros para voc\u00ea (Surpresinha) e\/ou concorrer com a mesma aposta por 2, 4 ou 8 concursos consecutivos (Teimosinha).<\/p>\n<p>A aposta m\u00ednima, de 6 n\u00fameros, custa R$ 3,50. Quanto mais n\u00fameros marcar, maior o pre\u00e7o da aposta e maiores as chances de faturar o pr\u00eamio mais cobi\u00e7ado do pa\u00eds.<\/p>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>A aposta m\u00ednima, de 6 n\u00fameros, custa R$ 3,50. Quanto mais n\u00fameros marcar, maior o pre\u00e7o da aposta e maiores as chances de faturar o pr\u00eamio mais cobi\u00e7ado do pa\u00eds (foto: Reprodu\u00e7\u00e3o\/Internet\/EBC) A mega-sena acumulou de novo e poder\u00e1 pagar R$ 60 milh\u00f5es j\u00e1 no pr\u00f3ximo s\u00e1bado (17). Segundo a Caixa, os n\u00fameros sorteados na [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":196086,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-237087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/05\/mega-sena-cartao.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/237087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=237087"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/237087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/196086"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=237087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=237087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=237087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}