{"id":237097,"date":"2018-03-15T06:12:24","date_gmt":"2018-03-15T09:12:24","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=237097"},"modified":"2018-03-15T06:12:40","modified_gmt":"2018-03-15T09:12:40","slug":"a-caminho-de-uma-fulminante-derrota","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/a-caminho-de-uma-fulminante-derrota\/","title":{"rendered":"A caminho de uma fulminante derrota"},"content":{"rendered":"<figure id=\"attachment_235266\" aria-describedby=\"caption-attachment-235266\" style=\"width: 620px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-235266 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/02\/adalberto-cavalcanti-de-cara-620x413.jpg\" alt=\"\" width=\"620\" height=\"413\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/02\/adalberto-cavalcanti-de-cara-620x413.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/02\/adalberto-cavalcanti-de-cara-300x200.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/02\/adalberto-cavalcanti-de-cara.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/02\/adalberto-cavalcanti-de-cara-160x106.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/02\/adalberto-cavalcanti-de-cara-450x300.jpg 450w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/02\/adalberto-cavalcanti-de-cara-640x427.jpg 640w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-235266\" class=\"wp-caption-text\">Ele \u00e9 at\u00e9 caridoso, mas o trabalhador n\u00e3o perdoa quem votou a favor de projeto retirando direitos<\/figcaption><\/figure>\n<p>Correligion\u00e1rios do deputado federal Adalberto Cavalcanti (Avante) dizem em Petrolina que ele reexamina a hip\u00f3tese de n\u00e3o se candidatar \u00e0 reelei\u00e7\u00e3o, e sim a deputado estadual, pela impossibilidade de repetir a vota\u00e7\u00e3o obtida em 2014: 99.912 votos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Correligion\u00e1rios do deputado federal Adalberto Cavalcanti (Avante) dizem em Petrolina que ele reexamina a hip\u00f3tese de n\u00e3o se candidatar \u00e0 reelei\u00e7\u00e3o, e sim a deputado estadual, pela impossibilidade de repetir a vota\u00e7\u00e3o obtida em 2014: 99.912 votos.<\/p>\n","protected":false},"author":5,"featured_media":167022,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-237097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/12\/adalberto-e-fernandinho.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/237097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=237097"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/237097\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/167022"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=237097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=237097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=237097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}