{"id":237136,"date":"2018-03-15T08:34:57","date_gmt":"2018-03-15T11:34:57","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=237136"},"modified":"2018-03-15T08:34:57","modified_gmt":"2018-03-15T11:34:57","slug":"projeto-de-prefeito-de-teofilandia-que-tira-direitos-de-professores-e-aprovado-na-camara","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/projeto-de-prefeito-de-teofilandia-que-tira-direitos-de-professores-e-aprovado-na-camara\/","title":{"rendered":"Projeto de prefeito de Teofil\u00e2ndia que tira direitos de professores \u00e9 aprovado na C\u00e2mara"},"content":{"rendered":"<div class=\"pubTopoCentro\"><\/div>\n<div class=\"postsTimeline\">\n<div class=\"post\">\n<div class=\"boxSocial\">\n<div class=\"addthis_toolbox addthis_default_style addthis_32x32_style\">\n<div class=\"atclear\"><\/div>\n<\/div>\n<\/div>\n<div class=\"thecontent\">\n<div id=\"attachment_76753\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-76753\" src=\"http:\/\/www.avozdocampo.com\/wp-content\/uploads\/2018\/03\/Screenshot_2-7-300x170.jpg?x38946\" sizes=\"auto, (max-width: 549px) 100vw, 549px\" srcset=\"http:\/\/www.avozdocampo.com\/wp-content\/uploads\/2018\/03\/Screenshot_2-7-300x170.jpg 300w, http:\/\/www.avozdocampo.com\/wp-content\/uploads\/2018\/03\/Screenshot_2-7-701x398.jpg 701w, http:\/\/www.avozdocampo.com\/wp-content\/uploads\/2018\/03\/Screenshot_2-7.jpg 703w\" alt=\"\" width=\"549\" height=\"311\" \/><\/p>\n<p class=\"wp-caption-text\">Foto: Leitor A Voz do Campo<\/p>\n<\/div>\n<p>Ocorreu da \u00faltima\u00a0 ter\u00e7a-feira (13), a vota\u00e7\u00e3o do\u00a0PL 001\/2018, de autoria do prefeito T\u00e9rcio Nunes, prefeito de Teofil\u00e2ndia (BA). O projeto, na pr\u00e1tica, configura-se como a redu\u00e7\u00e3o dos rendimentos dos professores da rede municipal de Teofil\u00e2ndia. Esta foi a terceira vez que o projeto foi para vota\u00e7\u00e3o na C\u00e2mara de Vereadores de Teofil\u00e2ndia. Nas duas primeiras vezes, a sess\u00e3o foi suspensa.\u00a0A vota\u00e7\u00e3o teve aparato policial e os vereadores da situa\u00e7\u00e3o que votaram a favor do projeto sa\u00edram escoltados pela pol\u00edcia. O projeto foi aprovado pela maioria e segue para san\u00e7\u00e3o do prefeito.<\/p>\n<p><strong>Votos:<\/strong><\/p>\n<p><strong>Votaram a favor do projeto do prefeito T\u00e9rcio Nunes<\/strong><br \/>\nAlles do Setor<br \/>\nF\u00e1bio de Z\u00e9 de Dinda<br \/>\nZ\u00e9 Nilton do Ferro Velho<br \/>\nRaimundo de Lourinho<br \/>\nJoj\u00f4<br \/>\nRonaldo do Baix\u00e3o<\/p>\n<p><strong>Votaram a favor dos professores<\/strong><br \/>\nDiego do G\u00e1s<br \/>\nRog\u00e9rio da Cachacinha<br \/>\nIsa\u00edas do PT<br \/>\nCarlinhos de D\u00e3ozinho<\/p>\n<p>Este \u00e9 o principal assunto de Teofil\u00e2ndia nos \u00faltimos meses. Segundo enquete do site A Voz do Campo, 93% da popula\u00e7\u00e3o \u00e9 contra este projeto. Como em todas as cidades de pequeno porte,\u00a0a classe dos professores aquece a economia e o com\u00e9rcio local. Segundo relatos ao site, diversos ser\u00e3o os educadores que ter\u00e3o seus sal\u00e1rios reduzidos em 30% ou at\u00e9 50%, o que representar\u00e1 uma diminui\u00e7\u00e3o no poder de compra dessas fam\u00edlias.\u00a0\u00a0O\u00a0prefeito T\u00e9rcio Nunes n\u00e3o se pronunciou em nota sobre o caso.\u00a0Interlocutores do prefeito dizem que\u00a0a folha de pagamento do munic\u00edpio\u00a0n\u00e3o suporta os valores pagos atualmente para os educadores e por isso o projeto.\u00a0O Sindicato dos Professores de\u00a0Teofil\u00e2ndia contesta a posi\u00e7\u00e3o do prefeito e est\u00e1 convidando toda a popula\u00e7\u00e3o para a sess\u00e3o.\u00a0Segundo o sindicato, os dados mostram que a Prefeitura Municipal tem condi\u00e7\u00f5es de manter os direitos adquiridos pela categoria e documentos mostram isso.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Leitor A Voz do Campo Ocorreu da \u00faltima\u00a0 ter\u00e7a-feira (13), a vota\u00e7\u00e3o do\u00a0PL 001\/2018, de autoria do prefeito T\u00e9rcio Nunes, prefeito de Teofil\u00e2ndia (BA). O projeto, na pr\u00e1tica, configura-se como a redu\u00e7\u00e3o dos rendimentos dos professores da rede municipal de Teofil\u00e2ndia. Esta foi a terceira vez que o projeto foi para vota\u00e7\u00e3o na C\u00e2mara [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":237137,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-237136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/policia-na-camara.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/237136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=237136"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/237136\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/237137"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=237136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=237136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=237136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}