{"id":237402,"date":"2018-03-18T11:08:06","date_gmt":"2018-03-18T14:08:06","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=237402"},"modified":"2018-03-18T11:08:06","modified_gmt":"2018-03-18T14:08:06","slug":"homem-estupra-agride-e-mata-mulher-porque-ela-se-negou-a-fazer-sexo","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/homem-estupra-agride-e-mata-mulher-porque-ela-se-negou-a-fazer-sexo\/","title":{"rendered":"Homem estupra, agride e mata mulher porque ela se negou a fazer sexo"},"content":{"rendered":"<div id=\"container\">\n<section id=\"header_post\">\n<div class=\"wrap\">\n<div class=\"box-title-single wrap img_sup\">\n<h1 class=\"wrap\"><\/h1>\n<p>A jovem, de 24 anos, tinha sa\u00eddo com amigas para comemorar o Dia Internacional da Mulher<\/p>\n<\/div>\n<div class=\"wrap img_sup\">\n<div class=\"imgPinWrap\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-840-577 size-840-577 wp-post-image\" src=\"https:\/\/uploads.metropoles.com\/wp-content\/uploads\/2018\/03\/16185606\/ingrid-840x560.jpg\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" srcset=\"https:\/\/uploads.metropoles.com\/wp-content\/uploads\/2018\/03\/16185606\/ingrid.jpg 840w, https:\/\/uploads.metropoles.com\/wp-content\/uploads\/2018\/03\/16185606\/ingrid-300x200.jpg 300w, https:\/\/uploads.metropoles.com\/wp-content\/uploads\/2018\/03\/16185606\/ingrid-212x142.jpg 212w\" alt=\"Reprodu\u00e7\u00e3o\/ Facebook\" width=\"840\" height=\"560\" \/><\/div>\n<section id=\"authors_sec\"><\/section>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<section id=\"body_post\" class=\"wrap entry-content \">\n<div class=\"d-3of4 t-all\">\n<div class=\"d-1of4 t-all column_social\">\n<div id=\"sticky-wrapper\" class=\"sticky-wrapper is-sticky\">\n<div class=\"share-internal\">\n<div class=\"box_share_int\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"content_post\" class=\"d-3of4 t-all\">\n<div class=\"mc-column content-text active-extra-styles active-capital-letter\" data-block-type=\"unstyled\" data-block-weight=\"38\" data-block-id=\"1\">\n<p class=\"content-text__container theme-color-primary-first-letter\" data-track-category=\"Link no Texto\" data-track-links=\"\">O corpo de uma jovem desaparecida desde o dia 8 de mar\u00e7o foi encontrado na \u00faltima quinta-feira (15\/3) em avan\u00e7ado\u00a0estado de decomposi\u00e7\u00e3o em Cabo Frio, Rio de Janeiro. O principal suspeito do crime afirmou \u00e0 pol\u00edcia que matou\u00a0Ingrid Veridiane Ferreira, 24 anos, porque ela se negou a fazer sexo com ele.\u00a0A v\u00edtima foi estuprada e agredida antes de morrer.\u00a0Ela tinha sa\u00eddo com amigas para comemorar o Dia Internacional da Mulher. De acordo com o depoimento do acusado, eles se conheceram em um bar e sa\u00edram juntos j\u00e1 na madrugada de sexta-feira (9).<\/p>\n<p class=\"content-text__container theme-color-primary-first-letter\" data-track-category=\"Link no Texto\" data-track-links=\"\">\u201cOs dois estavam em um bar, uma pizzaria. Ela estava com um pessoal e ele tamb\u00e9m na companhia\u00a0de amigos. Depois, juntaram as mesas e ficaram conversando. Na madrugada, sa\u00edram juntos. Ficaram [se beijaram] e foram para o local pr\u00f3ximo, onde ela foi encontrada. Eles foram de bicicleta, com Ingrid na garupa, e ficaram namorando. Mas, ele quis fazer sexo e ela negou, porque tinha acabado de conhec\u00ea-lo\u201d, disse o delegado Marcelo Braga, que investiga o crime.<\/p>\n<div class=\"relatedposts\">\n<article class=\"notice_gen_img_g\">&nbsp;<\/p>\n<\/article>\n<\/div>\n<p>O suspeito confessou que deu aproximadamente 10 socos no rosto de Ingrid e depois a levou para dentro do\u00a0mangue de um local conhecido como Dormit\u00f3rio das Gar\u00e7as. \u201cA jovem j\u00e1 estava desfalecida com os socos e ele percebeu isso em um momento que o corpo dela estava virado. Se j\u00e1 n\u00e3o estava morta, morreu afogada ali\u201d, conta o delegado. Com as informa\u00e7\u00f5es dadas pelo criminoso, o corpo dela foi achado. A fam\u00edlia s\u00f3 a reconheceu por conta das tatuagens dela. As informa\u00e7\u00f5es s\u00e3o do G1.<\/p><\/div>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>A jovem, de 24 anos, tinha sa\u00eddo com amigas para comemorar o Dia Internacional da Mulher O corpo de uma jovem desaparecida desde o dia 8 de mar\u00e7o foi encontrado na \u00faltima quinta-feira (15\/3) em avan\u00e7ado\u00a0estado de decomposi\u00e7\u00e3o em Cabo Frio, Rio de Janeiro. O principal suspeito do crime afirmou \u00e0 pol\u00edcia que matou\u00a0Ingrid Veridiane [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":237403,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-237402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/ingrid.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/237402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=237402"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/237402\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/237403"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=237402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=237402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=237402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}