{"id":237442,"date":"2018-03-19T05:28:18","date_gmt":"2018-03-19T08:28:18","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=237442"},"modified":"2018-03-19T05:28:18","modified_gmt":"2018-03-19T08:28:18","slug":"final-de-semana-violento-em-pernambuco","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/final-de-semana-violento-em-pernambuco\/","title":{"rendered":"Final de semana violento em Pernambuco"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Nas \u00faltimas 24 horas foram assassinadas no Estado de Pernambuco 24 pessoas, sendo 19 no interior e 5 na regi\u00e3o metropolitana da grande Recife. O mais assustador que na cidade de Petrolina, seis morreram. No interior do estado houve ainda tr\u00eas duplos homic\u00eddios.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-171399\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/01\/homic\u00eddio1-282x300.jpg\" alt=\"\" width=\"282\" height=\"300\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/01\/homic\u00eddio1-282x300.jpg 282w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/01\/homic\u00eddio1-470x500.jpg 470w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/01\/homic\u00eddio1-160x170.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/01\/homic\u00eddio1.jpg 520w\" sizes=\"auto, (max-width: 282px) 100vw, 282px\" \/><\/p>\n<p>Neste ano j\u00e1 s\u00e3o 1100 pessoas assassinadas em Pernambuco.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Nas \u00faltimas 24 horas foram assassinadas no Estado de Pernambuco 24 pessoas, sendo 19 no interior e 5 na regi\u00e3o metropolitana da grande Recife. O mais assustador que na cidade de Petrolina, seis morreram. No interior do estado houve ainda tr\u00eas duplos homic\u00eddios. Neste ano j\u00e1 s\u00e3o 1100 pessoas assassinadas em Pernambuco. &nbsp;<\/p>\n","protected":false},"author":5,"featured_media":66444,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-237442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/06\/homicidio_tobias_04032015.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/237442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=237442"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/237442\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/66444"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=237442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=237442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=237442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}