{"id":237642,"date":"2018-03-20T09:15:18","date_gmt":"2018-03-20T12:15:18","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=237642"},"modified":"2018-03-20T09:15:18","modified_gmt":"2018-03-20T12:15:18","slug":"ronda-maria-da-penha-promove-ciclo-de-palestra","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/ronda-maria-da-penha-promove-ciclo-de-palestra\/","title":{"rendered":"Ronda Maria da Penha promove ciclo de palestra"},"content":{"rendered":"<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">O Comando de Policiamento da Regi\u00e3o Norte (CPRN) atrav\u00e9s da Opera\u00e7\u00e3o Ronda Maria da Penha de Juazeiro realizou na tarde de ontem (19) um ciclo de palestras de sensibiliza\u00e7\u00e3o no enfrentamento a viol\u00eancia contra a mulher, no Centro de Cultura Jo\u00e3o Gilberto.<\/div>\n<div dir=\"auto\">\n<figure id=\"attachment_177227\" aria-describedby=\"caption-attachment-177227\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-177227 size-medium\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/02\/cpm-Palestra-anivers\u00e1rio-PMBA2-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/02\/cpm-Palestra-anivers\u00e1rio-PMBA2-300x169.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/02\/cpm-Palestra-anivers\u00e1rio-PMBA2-768x432.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/02\/cpm-Palestra-anivers\u00e1rio-PMBA2-620x349.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/02\/cpm-Palestra-anivers\u00e1rio-PMBA2-160x90.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/02\/cpm-Palestra-anivers\u00e1rio-PMBA2-480x270.jpg 480w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/02\/cpm-Palestra-anivers\u00e1rio-PMBA2-640x360.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/02\/cpm-Palestra-anivers\u00e1rio-PMBA2.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-177227\" class=\"wp-caption-text\">Ilustra\u00e7\u00e3o<\/figcaption><\/figure>\n<\/div>\n<div dir=\"auto\">Como frisou a capit\u00e3 Paula Cruso\u00e9, comandante da Opera\u00e7\u00e3o Ronda Maria da Penha (ORMP) em Juazeiro, o evento teve como objeto esclarecer, conscientizar e sensibilizar sobre a tem\u00e1tica da viol\u00eancia contra a mulher, problema multifatorial que afeta grande parte da popula\u00e7\u00e3o, vitimando centenas de mulheres por ano no Brasil. O p\u00fablico alvo do ciclo de palestras foram os policiais militares e integrantes de outros \u00f3rg\u00e3os que tamb\u00e9m atendem as v\u00edtimas da viol\u00eancia contra a mulher.<\/div>\n<div dir=\"auto\">Em seu discurso o coronel Anselmo Bispo, comandante do CPRN, elogiou o trabalho da Opera\u00e7\u00e3o Ronda Maria da Penha e tudo que ela, juntamente com os outros \u00f3rg\u00e3os envolvidos, tem feito para melhorar o panorama da viol\u00eancia contra a mulher na Bahia, para ele a\u00e7\u00f5es como a da ORMP, incluindo este ciclo de palestra, tem contribu\u00eddo para empoderar as mulheres e assim elas terem coragem de denunciar.<\/div>\n<div dir=\"auto\">O Juiz titular da Vara de Justi\u00e7a pela Paz em Casa, Dr. Aroldo do Nascimento foi o primeiro palestrante e falou sobre o machismo e suas consequ\u00eancias danosas para a sociedade, ele ressaltou, ainda a import\u00e2ncia de eventos de conscientiza\u00e7\u00e3o e sensibiliza\u00e7\u00e3o pois assim se propicia o debate e uma consequente mudan\u00e7a. Seguindo a Sr\u00aa Francisca Erislene Costa, Coordenadora do Centro Integrado de Atendimento a Mulher (CIAM) trouxe a realidade do CIAM e explicou como funciona o atendimento do \u00f3rg\u00e3o.<\/div>\n<div dir=\"auto\">Finalizando, a major Denice Santiago, comandante da Opera\u00e7\u00e3o Ronda Maria da Penha em Salvador, retomou o assunto do machismo, pontuando o quanto as pessoas o reproduzem muitas vezes sem perceber, e alertando para o quanto as mulheres tem sido prejudicadas em decorr\u00eancia dele; abordou, ainda, a atua\u00e7\u00e3o policial militar nestas ocorr\u00eancias e a import\u00e2ncia do profissional para a prote\u00e7\u00e3o da vida das mulheres.<\/div>\n<div dir=\"auto\">O evento contou, ainda, com a apresenta\u00e7\u00e3o teatral intitulada &#8221; Geni conta sua hist\u00f3ria&#8221; baseada na m\u00fasica Geni e o Zepelim de Chico Buarque, encenada pelas estudantes do Col\u00e9gio Modelo Lu\u00edsa Rebeca e Samara Menezes, al\u00e9m de Ana Terena, ex-aluna do citado Col\u00e9gio.<\/div>\n<p>&nbsp;<\/p>\n<div class=\"x_gmail_extra\" dir=\"auto\">\n<div class=\"x_gmail_quote\"><\/div>\n<div class=\"x_gmail_quote\" dir=\"auto\">Cap PM Bruna gracielle<\/div>\n<div class=\"x_gmail_quote\" dir=\"auto\">ASCOM CPRN<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Comando de Policiamento da Regi\u00e3o Norte (CPRN) atrav\u00e9s da Opera\u00e7\u00e3o Ronda Maria da Penha de Juazeiro realizou na tarde de ontem (19) um ciclo de palestras de sensibiliza\u00e7\u00e3o no enfrentamento a viol\u00eancia contra a mulher, no Centro de Cultura Jo\u00e3o Gilberto. Como frisou a capit\u00e3 Paula Cruso\u00e9, comandante da Opera\u00e7\u00e3o Ronda Maria da Penha [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":177227,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-237642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/02\/cpm-Palestra-anivers\u00e1rio-PMBA2.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/237642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=237642"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/237642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/177227"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=237642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=237642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=237642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}