{"id":237669,"date":"2018-03-20T15:47:20","date_gmt":"2018-03-20T18:47:20","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=237669"},"modified":"2018-03-21T12:48:54","modified_gmt":"2018-03-21T15:48:54","slug":"assinada-ordem-de-servico-para-a-pavimentacao-de-sete-ruas-do-bairro-alto-da-alianca","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/assinada-ordem-de-servico-para-a-pavimentacao-de-sete-ruas-do-bairro-alto-da-alianca\/","title":{"rendered":"Assinada ordem de servi\u00e7o para a pavimenta\u00e7\u00e3o de sete ruas do bairro Alto da Alian\u00e7a"},"content":{"rendered":"<p style=\"text-align: justify;\">Na manh\u00e3 desta ter\u00e7a-feira (20), o prefeito Paulo Bomfim assinou a ordem de servi\u00e7o para uma grande obra de pavimenta\u00e7\u00e3o que vai beneficiar os moradores do bairro Alto da Alian\u00e7a com sete ruas ao total de 2.049 m\u00b2 pavimentados.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-237670 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/ordem-de-servi\u00e7o-620x413.jpg\" alt=\"\" width=\"620\" height=\"413\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/ordem-de-servi\u00e7o-620x413.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/ordem-de-servi\u00e7o-300x200.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/ordem-de-servi\u00e7o-768x512.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/ordem-de-servi\u00e7o-160x106.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/ordem-de-servi\u00e7o-450x300.jpg 450w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/ordem-de-servi\u00e7o-640x427.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/ordem-de-servi\u00e7o.jpg 1280w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p style=\"text-align: justify;\">As ruas ir\u00e3o receber o servi\u00e7o da empresa construtora Ven\u00e2ncio que em contrato com a prefeitura de Juazeiro ir\u00e1 realizar a pavimenta\u00e7\u00e3o asf\u00e1ltica, paralelos gran\u00edticos, macrodrenagem e microdrenagem de \u00e1guas pluviais. Acompanhado do secret\u00e1rio de Obras e Desenvolvimento Urbano, Anderson Alves, vereadores, servidores municipais e moradores do bairro, o prefeito assinou a ordem de servi\u00e7o e percorreu toda a rua ouvindo os moradores que estavam satisfeitos pelas obras iniciadas na comunidade.<\/p>\n<p style=\"text-align: justify;\">De acordo com o prefeito Paulo Bomfim a expectativa \u00e9 que dentro do programa \u2018Pavimenta Mais\u2019 cerca de 12 bairros ir\u00e3o receber pavimenta\u00e7\u00e3o. \u201cEstamos mudando\u00a0a cara da nossa cidade levando mais qualidade de vida aos moradores de diversos bairros com a pavimenta\u00e7\u00e3o das ruas e avenidas. Estamos dando seguimento ao projeto do ex-prefeito Isaac Carvalho e com muito trabalho j\u00e1 conseguimos entregar mais 30 ruas pavimentadas com habita\u00e7\u00e3o, drenagem, entre outros. Temos o compromisso com o povo juazeirense em melhorar a infraestrutura da nossa cidade\u201d, declarou Bomfim.<\/p>\n<p style=\"text-align: justify;\">O comerciante Ant\u00f4nio Ismael, que mora h\u00e1 mais de 18 anos na Rua Bento Gon\u00e7alves, destacou a import\u00e2ncia da pavimenta\u00e7\u00e3o das ruas na comunidade. \u201c\u00c9 uma alegria receber o in\u00edcio da obra de pavimenta\u00e7\u00e3o nas ruas aqui do bairro. Meu com\u00e9rcio com toda certeza ser\u00e1 mais valorizado e s\u00f3 temos a agradecer ao prefeito Paulo Bomfim\u201d, comemorou.<\/p>\n<p style=\"text-align: justify;\">O presidente da Associa\u00e7\u00e3o do bairro, Juranildo Araujo, o popular Ticou, tamb\u00e9m agradeceu ao prefeito pelo inicio da obra e ressaltou que a popula\u00e7\u00e3o do bairro estava ansiosa por esse projeto. \u201cAgradecemos imensamente ao ex prefeito Isaac Carvalho que iniciou esse projeto aqui no bairro e ao prefeito Paulo Bomfim por dar continuidade e fazer nosso sonho virar realidade\u201d, disse.<\/p>\n<p style=\"text-align: justify;\">As pavimenta\u00e7\u00f5es das sete ruas integram o conjunto de obras do \u2018Pavimenta Mais\u2019 que ir\u00e1 beneficiar 12 bairros com pavimenta\u00e7\u00e3o, recapeamento do corredor de \u00f4nibus da Poligonal, revitaliza\u00e7\u00e3o do Canal da Malhada da Areia (dando origem a duas avenidas paralelas), revitaliza\u00e7\u00e3o do\u00a0 Canal CAIC (dando origem a uma nova avenida), e a pavimenta\u00e7\u00e3o de v\u00e1rias avenidas.<\/p>\n<p style=\"text-align: justify;\">De acordo com o titular da SEDUR, Anderson Alves em breve essas ruas estar\u00e3o sendo entregues totalmente pavimentadas. \u00a0\u201cAntes de receberem a pavimenta\u00e7\u00e3o, as ruas s\u00e3o preparadas com obras de infraestrutura e drenagem, como galerias de \u00e1guas pluviais, guias e sarjetas no sentido de garantir que, durante as chuvas, as \u00e1guas sejam escoadas de forma correta, evitando transtornos aos motoristas, como alagamentos e garantindo maior durabilidade ao pavimento. O nosso projeto \u00e9 reestruturar as vias e ruas dos bairros de Juazeiro\u201d, concluiu.<\/p>\n<p style=\"text-align: justify;\">A ordem de servi\u00e7o beneficiou as ruas Bento Gon\u00e7alves, G, Padre Vicente Caminha, Eurico Gaspar, Mauricio Nassau, Freire Fernandes e Henrique Dias.<\/p>\n<p style=\"text-align: justify;\">Daniela Duarte\/SEDUR<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acordo com o prefeito Paulo Bomfim a expectativa \u00e9 que dentro do programa \u2018Pavimenta Mais\u2019 cerca de 12 bairros ir\u00e3o receber pavimenta\u00e7\u00e3o. \u201cEstamos mudando\u00a0a cara da nossa cidade levando mais qualidade de vida aos moradores de diversos bairros com a pavimen<\/p>\n","protected":false},"author":5,"featured_media":237670,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-237669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/ordem-de-servi\u00e7o.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/237669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=237669"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/237669\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/237670"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=237669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=237669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=237669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}