{"id":237769,"date":"2018-03-22T03:31:52","date_gmt":"2018-03-22T06:31:52","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=237769"},"modified":"2018-03-22T03:31:52","modified_gmt":"2018-03-22T06:31:52","slug":"tiros-em-petrolina","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/tiros-em-petrolina\/","title":{"rendered":"Tiros em Petrolina"},"content":{"rendered":"<p>Acabou de chegar a noticia na reda\u00e7\u00e3o do AP, que provavelmente tenha acontecido um homic\u00eddio na noite desta quarta-feira (21) por tr\u00e1s do Supermercado G Barbosa, na Vila Eduardo, em Petrolina. Um carro de marca Parati com uma pessoa dentro, foi alvejada com v\u00e1rios disparos de arma de fogo, pr\u00f3ximo \u00e0 igreja eterna alian\u00e7a.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-237770 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/marca-de-tiro1-620x465.jpg\" alt=\"\" width=\"620\" height=\"465\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/marca-de-tiro1-620x465.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/marca-de-tiro1-300x225.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/marca-de-tiro1-768x576.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/marca-de-tiro1-80x60.jpg 80w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/marca-de-tiro1-118x88.jpg 118w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/marca-de-tiro1-160x120.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/marca-de-tiro1-640x480.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/marca-de-tiro1.jpg 1280w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-237771 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/marca-de-tiro2-375x500.jpg\" alt=\"\" width=\"375\" height=\"500\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/marca-de-tiro2-375x500.jpg 375w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/marca-de-tiro2-225x300.jpg 225w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/marca-de-tiro2-768x1024.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/marca-de-tiro2-160x213.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/marca-de-tiro2-640x853.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/marca-de-tiro2.jpg 960w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acabou de chegar a noticia na reda\u00e7\u00e3o do AP, que provavelmente tenha acontecido um homic\u00eddio na noite desta quarta-feira (21) por tr\u00e1s do Supermercado G Barbosa, na Vila Eduardo, em Petrolina. Um carro de marca Parati com uma pessoa dentro, foi alvejada com v\u00e1rios disparos de arma de fogo, pr\u00f3ximo \u00e0 igreja eterna alian\u00e7a.<\/p>\n","protected":false},"author":5,"featured_media":237770,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-237769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/marca-de-tiro1.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/237769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=237769"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/237769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/237770"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=237769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=237769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=237769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}