{"id":237983,"date":"2018-03-23T12:11:58","date_gmt":"2018-03-23T15:11:58","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=237983"},"modified":"2018-03-23T12:11:58","modified_gmt":"2018-03-23T15:11:58","slug":"nova-eleicao-em-jeremoabo","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/nova-eleicao-em-jeremoabo\/","title":{"rendered":"Nova elei\u00e7\u00e3o em Jeremoabo"},"content":{"rendered":"<div class=\"box-title\">\n<div class=\"data\"><\/div>\n<\/div>\n<div class=\"box-body\">\n<div class=\"text-center\"><\/div>\n<div class=\"text-descricao\">\n<p>Ainda sem prefeito, ap\u00f3s a postulante mais votada em 2016, Anabel de Tista (PSD), ter a candidatura indeferida, a cidade de Jeremoabo, no nordeste baiano, vai escolher o pr\u00f3ximo gestor, e vice, no dia 3 de junho. Devido ao novo processo, o Tribunal Regional Eleitoral (TRE-BA) divulgou a agenda de prazos para os postulantes e eleitores atenderem \u00e0s exig\u00eancias eleitorais.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-232408\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/01\/Urna-Eletr\u00f4nica-jos\u00e9-cruz-ag\u00eancia-brasil-300x164.jpg\" alt=\"\" width=\"300\" height=\"164\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/01\/Urna-Eletr\u00f4nica-jos\u00e9-cruz-ag\u00eancia-brasil-300x164.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/01\/Urna-Eletr\u00f4nica-jos\u00e9-cruz-ag\u00eancia-brasil-620x340.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/01\/Urna-Eletr\u00f4nica-jos\u00e9-cruz-ag\u00eancia-brasil-93x50.jpg 93w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/01\/Urna-Eletr\u00f4nica-jos\u00e9-cruz-ag\u00eancia-brasil-160x88.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/01\/Urna-Eletr\u00f4nica-jos\u00e9-cruz-ag\u00eancia-brasil-225x123.jpg 225w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/01\/Urna-Eletr\u00f4nica-jos\u00e9-cruz-ag\u00eancia-brasil-640x351.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/01\/Urna-Eletr\u00f4nica-jos\u00e9-cruz-ag\u00eancia-brasil.jpg 748w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Conforme o TRE-BA, eleitores da cidade que estejam irregulares com a Justi\u00e7a Eleitoral n\u00e3o poder\u00e3o participar da nova elei\u00e7\u00e3o. Isso porque, para o pleito em Jeremoabo, o cadastro foi fechado desde o \u00faltimo dia 8 de mar\u00e7o. Partidos e coliga\u00e7\u00f5es poder\u00e3o solicitar \u00e0 Justi\u00e7a Eleitoral o registro de seus candidatos at\u00e9 as 19 horas do dia 14 de abril de 2018, no Ju\u00edzo da 51\u00aa Zona Eleitoral. Em Jeremoabo, a propaganda eleitoral ser\u00e1 encerrada em 2 de junho. No dia, os candidatos ter\u00e3o direito at\u00e9 as 22 horas para distribuir material gr\u00e1fico e fazer caminhada, carreata, passeata ou carro de som que transite pela cidade divulgando jingles ou mensagens de candidatos.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ainda sem prefeito, ap\u00f3s a postulante mais votada em 2016, Anabel de Tista (PSD), ter a candidatura indeferida, a cidade de Jeremoabo, no nordeste baiano, vai escolher o pr\u00f3ximo gestor, e vice, no dia 3 de junho. Devido ao novo processo, o Tribunal Regional Eleitoral (TRE-BA) divulgou a agenda de prazos para os postulantes e [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":169070,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-237983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/01\/urna-boa.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/237983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=237983"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/237983\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/169070"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=237983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=237983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=237983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}