{"id":238617,"date":"2018-03-29T16:57:40","date_gmt":"2018-03-29T19:57:40","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=238617"},"modified":"2018-03-29T16:57:40","modified_gmt":"2018-03-29T19:57:40","slug":"policial-militar-e-baleado-na-cabeca-apos-assalto-em-pedagio-de-candeias","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/policial-militar-e-baleado-na-cabeca-apos-assalto-em-pedagio-de-candeias\/","title":{"rendered":"Policial Militar \u00e9 baleado na cabe\u00e7a ap\u00f3s assalto em ped\u00e1gio de Candeias"},"content":{"rendered":"<div class=\"box-title\" style=\"text-align: justify;\">\n<div class=\"data\"><\/div>\n<\/div>\n<div class=\"box-body\" style=\"text-align: justify;\">\n<div class=\"text-center\">\n<div class=\"box-img\"><img decoding=\"async\" class=\"img-center img-responsive\" src=\"https:\/\/www.bahianoticias.com.br\/fotos\/principal_noticias\/220177\/IMAGEM_NOTICIA_5.jpg?checksum=1522350110\" alt=\"Policial Militar \u00e9 baleado na cabe\u00e7a ap\u00f3s assalto em ped\u00e1gio de Candeias\" \/><\/p>\n<div class=\"img-legenda\">Foto: Reprodu\u00e7\u00e3o \/ Redes Sociais<\/div>\n<\/div>\n<\/div>\n<div class=\"text-descricao\">\n<p>Suspeitos balearam um policial militar na cabe\u00e7a nesta quarta-feira (28) ap\u00f3s o assaltarem na pra\u00e7a de ped\u00e1gio da BA-524, em Candeias, Regi\u00e3o Metropolitana de Salvador. Segundo o Correio, tr\u00eas pessoas participaram do crime que teria ocorrido por volta das 20h. No momento do assalto, o PM Cristiano Ramos Pinto estava acompanhado de outros dois colegas que o socorreram imediatamente para o Hospital Geral de Cama\u00e7ari (HGC). &#8220;Os policiais contaram que tinham acabado de sair do servi\u00e7o e seguiam em dire\u00e7\u00e3o a Feira de Santana, munic\u00edpio onde moram. Eles aguardavam na fila do ped\u00e1gio, quando um grupo de criminosos passou a saquear as cabines de cobran\u00e7a e os motoristas que aguardavam o atendimento. Ao se aproximar dos PMs, os criminosos efetuaram disparos de arma de fogo e houve troca de tiros, mas eles conseguiram fugir&#8221;, informou a PM em nota.<\/p>\n<p>Ap\u00f3s os primeiros socorros no HGC, o policial ferido foi transferido para o Hospital da Bahia, onde est\u00e1 internado na Unidade de Terapia Intensiva (UTI). No Boletim M\u00e9dico consta que Cristiano apresentava um quadro de hematoma intracerebral extenso e edema cerebral, e que foi submetido a uma craniectomia descompressiva. Ele est\u00e1 internado em estado grave na Unidade de terapia Intensiva ( UTI) com ventila\u00e7\u00e3o mec\u00e2nica e seda\u00e7\u00e3o. Ao Correio, a Concession\u00e1ria Bahia Norte, empresa que gere a via, informou que os suspeitos renderam a equipe de vigil\u00e2ncia por volta de 19h50 e assaltaram os motoristas e as cabines da pra\u00e7a de ped\u00e1gio localizada no Km 11 da rodovia Canal de Tr\u00e1fego. &#8220;Durante a a\u00e7\u00e3o, um motorista teve o ve\u00edculo tomado de assalto e acabou sendo atropelado e morto pelos bandidos, que fugiram em outro carro de passeio.<\/p>\n<p>A Bahia Norte est\u00e1 colaborando com as autoridades competentes que atuam na investiga\u00e7\u00e3o do caso&#8221;, informou a nota da Concession\u00e1ria Bahia Norte. Nenhum suspeito foi encontrado at\u00e9 o momento e a Pol\u00edcia Civil investiga o caso. Veja v\u00eddeo da c\u00e2mera de seguran\u00e7a:<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?href=https%3A%2F%2Fwww.facebook.com%2Fcorreio24horas%2Fvideos%2F2144873582193789%2F&amp;show_text=0&amp;width=560\" width=\"560\" height=\"316\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p>(BN)<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Reprodu\u00e7\u00e3o \/ Redes Sociais Suspeitos balearam um policial militar na cabe\u00e7a nesta quarta-feira (28) ap\u00f3s o assaltarem na pra\u00e7a de ped\u00e1gio da BA-524, em Candeias, Regi\u00e3o Metropolitana de Salvador. Segundo o Correio, tr\u00eas pessoas participaram do crime que teria ocorrido por volta das 20h. No momento do assalto, o PM Cristiano Ramos Pinto estava [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":238645,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-238617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/policial-baleado.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/238617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=238617"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/238617\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/238645"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=238617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=238617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=238617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}