{"id":238985,"date":"2018-04-02T08:39:17","date_gmt":"2018-04-02T11:39:17","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=238985"},"modified":"2018-04-02T08:39:17","modified_gmt":"2018-04-02T11:39:17","slug":"casal-faz-sexo-em-frente-a-camara-de-vereadores-de-teixeira-de-freitas-em-protesto-contra-politicos","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/casal-faz-sexo-em-frente-a-camara-de-vereadores-de-teixeira-de-freitas-em-protesto-contra-politicos\/","title":{"rendered":"Casal faz sexo em frente \u00e0 C\u00e2mara de Vereadores de Teixeira de Freitas em protesto contra pol\u00edticos"},"content":{"rendered":"<div class=\"title-noticia\" style=\"text-align: justify;\">\n<h2><\/h2>\n<\/div>\n<div class=\"col-esq\" style=\"text-align: justify;\">\n<div class=\"noticia-interna\">\n<div class=\"share share-fx\">\n<div class=\"cont-share\"><\/div>\n<div class=\"cont-share\"><\/div>\n<div class=\"cont-share\"><\/div>\n<div class=\"cont-more\">\n<div class=\"cont-share\"><\/div>\n<div class=\"cont-share\"><\/div>\n<\/div>\n<\/div>\n<article>\n<figure><img decoding=\"async\" class=\"animated fadeIn\" title=\"Casal faz sexo em frente \u00e0 C\u00e2mara de Vereadores de Teixeira de Freitas em protesto contra pol\u00edticos\" src=\"https:\/\/www.bocaonews.com.br\/fotos\/bocao_noticias\/202122\/IMAGEM_NOTICIA_0.jpg\" alt=\"[Casal faz sexo em frente \u00e0 C\u00e2mara de Vereadores de Teixeira de Freitas em protesto contra pol\u00edticos]\" data-load-image=\"\/fotos\/bocao_noticias\/202122\/IMAGEM_NOTICIA_0.jpg\" \/><\/figure>\n<div class=\"desc\">\n<div class=\"desc-noticia\">\n<p>Um casal encontrou uma forma inustitada de protestar contra os pol\u00edticos da cidade de Teixeira de Freitas. Na noite deste domingo (1), come\u00e7ou a circular nas redes sociais e sites locais um v\u00eddeo em que o casal aparece fazendo sexo em frente \u00e0 C\u00e2mara de Vereadores.<\/p>\n<p>Enquanto pratica o ato, o homem narra: &#8220;Estou aqui em frente \u00e0 C\u00e2mara de Vereadores de Teixeira de Freitas reinvindicando saneamento b\u00e1sico, asfaltamento, emprego. Essa \u00e9 uma maneira de reivindicar os direitos de todos nesssa cidade defasada onde pol\u00edticos s\u00f3 sabem ganhar dinheiro&#8221;.<\/p>\n<p>De acordo com o site Bahia Extremo Sul, o casal j\u00e1 \u00e9 conhecido pela pr\u00e1tica de sexo ao ar livre na cidade.<\/p>\n<p>Ap\u00f3s a divulga\u00e7\u00e3o, o presidente do Legislativo do munic\u00edpio, vereador Agnaldo da Sa\u00fade, emitiu uma nota de rep\u00fadio. &#8220;Nesta segunda-feira (02\/03), a presid\u00eancia da C\u00e2mara Municipal tomar\u00e1 todas \u00e0s providencias jur\u00eddicas cab\u00edveis: primeiro registrando um boletim de ocorr\u00eancia na Pol\u00edcia Civil para que a pol\u00edcia judici\u00e1ria instaure um procedimento de investiga\u00e7\u00e3o contra este cidad\u00e3o e lhe enquadre nos termos do artigo 233 do C\u00f3digo Penal Brasileiro, por atos obscenos ou importuna\u00e7\u00e3o ofensiva ao pudor, pelo afronto direto ao um Poder Constitu\u00eddo, em que seu papel maior \u00e9 representar legitimamente a sociedade&#8221;, diz um trecho da nota.<\/p>\n<p>&#8220;Uma representa\u00e7\u00e3o tamb\u00e9m estar\u00e1 sendo protocolada na 1\u00aa Promotoria Criminal da Comarca, sugerindo ao Minist\u00e9rio P\u00fablico Estadual, na qualidade de \u00f3rg\u00e3o guardi\u00e3o da sociedade, que denuncie os part\u00edcipes desta cena, tendo em vista que esta n\u00e3o \u00e9 a primeira vez que este indiv\u00edduo arma cen\u00e1rio desta esp\u00e9cie em afronta a sociedade teixeirense, gravando e postando seus atos sexuais com suas companheiras, assumindo e provocando as autoridades com seus atos de express\u00e3o imoral e desrespeitoso, caracterizando claramente o crime de ato obsceno&#8221;, promete o presidente.<\/p>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Um casal encontrou uma forma inustitada de protestar contra os pol\u00edticos da cidade de Teixeira de Freitas. Na noite deste domingo (1), come\u00e7ou a circular nas redes sociais e sites locais um v\u00eddeo em que o casal aparece fazendo sexo em frente \u00e0 C\u00e2mara de Vereadores. Enquanto pratica o ato, o homem narra: &#8220;Estou aqui [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":238986,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-238985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/camara-de-conquista.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/238985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=238985"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/238985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/238986"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=238985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=238985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=238985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}