{"id":239035,"date":"2018-04-03T05:33:53","date_gmt":"2018-04-03T08:33:53","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=239035"},"modified":"2018-04-03T05:33:53","modified_gmt":"2018-04-03T08:33:53","slug":"aplb-de-uaua-de-alma-lavada","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/aplb-de-uaua-de-alma-lavada\/","title":{"rendered":"APLB de Uau\u00e1 de alma lavada"},"content":{"rendered":"<p>APLB-UAU\u00c1 COMEMORA A ADES\u00c3O DE 11 NOVOS S\u00d3CIOS NO M\u00caS DE MAR\u00c7O<\/p>\n<p>O m\u00eas de Mar\u00e7o de 2018, a diretoria da APLB-UAU\u00c1 recebeu com grande alegria a ades\u00e3o de mais 11 novos s\u00f3cios que sentiram vontade de apoiar \u00e0 luta que a APLB-UAU\u00c1 trava por melhores condi\u00e7\u00f5es de trabalho, valoriza\u00e7\u00e3o profissional e educa\u00e7\u00e3o de qualidade.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-222948\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/11\/carro-da-aplb-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/11\/carro-da-aplb-300x225.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/11\/carro-da-aplb-768x576.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/11\/carro-da-aplb-620x465.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/11\/carro-da-aplb-80x60.jpg 80w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/11\/carro-da-aplb-118x88.jpg 118w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/11\/carro-da-aplb-160x120.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/11\/carro-da-aplb-640x480.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/11\/carro-da-aplb.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Uma professora, ao entregar a ficha de filia\u00e7\u00e3o, externou:<\/p>\n<p>&#8220;Eu sou professora, tenho de estar no sindicato que me representa e que luta constantemente pela melhoria da minha profiss\u00e3o. E outra, voc\u00eas est\u00e3o lembrando da gente constantemente. Se \u00e9 no Dia do Professor, fazem festa. Se \u00e9 no in\u00edcio do ano letivo, d\u00e3o brindes. Se \u00e9 na P\u00e1scoa, d\u00e3o ovos. Se \u00e9 para vim a uma assembleia, d\u00e3o o transporte. Se \u00e9 em um projeto escolar, d\u00e3o apoio. Ent\u00e3o, n\u00e3o sei o que estava me prendendo que n\u00e3o entrei logo. Espero que continuem assim. Parab\u00e9ns!&#8221;<\/p>\n<p>O coordenador, Francisco-Prolepses, emocionado, disse:<\/p>\n<p>&#8221; \u00c9 isso que nos deixa feliz, ver os nossos colegas felizes. Vamos continuar trabalhando firmes e fortes para sermos dignos\u00a0 do respeito e da credibilidade de voc\u00eas.\u00a0Fiquem \u00e0 vontade! Juntos somos mais fortes! Agradecemos pela prefer\u00eancia.&#8221;<\/p>\n<p>ASCOM: APLB-UAU\u00c1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>APLB-UAU\u00c1 COMEMORA A ADES\u00c3O DE 11 NOVOS S\u00d3CIOS NO M\u00caS DE MAR\u00c7O O m\u00eas de Mar\u00e7o de 2018, a diretoria da APLB-UAU\u00c1 recebeu com grande alegria a ades\u00e3o de mais 11 novos s\u00f3cios que sentiram vontade de apoiar \u00e0 luta que a APLB-UAU\u00c1 trava por melhores condi\u00e7\u00f5es de trabalho, valoriza\u00e7\u00e3o profissional e educa\u00e7\u00e3o de qualidade. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":236925,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-239035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/carro-da-aplb.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/239035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=239035"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/239035\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/236925"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=239035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=239035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=239035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}