{"id":239120,"date":"2018-04-03T15:32:25","date_gmt":"2018-04-03T18:32:25","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=239120"},"modified":"2018-04-04T08:52:19","modified_gmt":"2018-04-04T11:52:19","slug":"policia-de-juazeiro-prende-homem-acusado-de-bater-em-mulher","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/policia-de-juazeiro-prende-homem-acusado-de-bater-em-mulher\/","title":{"rendered":"Policia de Juazeiro prende homem acusado de bater em mulher"},"content":{"rendered":"<p style=\"text-align: justify;\">Hoje (03\/04), por volta de 01h, Policiais Militares da 75\u00aa Companhia Independente de Pol\u00edcia Militar prenderam um homem por viol\u00eancia dom\u00e9stica no bairro Itaberaba em Juazeiro-BA.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-218420\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/09\/agressao-a-mulher-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/09\/agressao-a-mulher-300x169.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/09\/agressao-a-mulher-768x433.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/09\/agressao-a-mulher-620x350.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/09\/agressao-a-mulher-160x90.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/09\/agressao-a-mulher-480x270.jpg 480w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/09\/agressao-a-mulher-640x361.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/09\/agressao-a-mulher.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: justify;\">Durante rondas ostensivas, os militares receberam den\u00fancia do CICOM(Centro Integrado de Comunica\u00e7\u00f5es) informando sobre uma ocorr\u00eancia de viol\u00eancia dom\u00e9stica no bairro Itaberaba. De imediato os referidos policiais militares deslocaram at\u00e9 o local informado e observaram que a v\u00edtima teria sido agredido. Ao indagar sobre o paradeiro do acusado, testemunhas no local disseram que ele teria se evadido. Com base na vida pregressa do acusado e em ato continuado, os policiais militares iniciaram dilig\u00eancia no intuito de captur\u00e1-lo, ao encontrarem pr\u00f3ximo de sua resid\u00eancia, realizaram busca pessoal e nada de il\u00edcito foi encontrado com o mesmo.<\/p>\n<p style=\"text-align: justify;\">O acusado e a v\u00edtima foram apresentados \u00e0 Delegacia de Pol\u00edcia Civil para serem tomadas as medidas cab\u00edveis. A policia n\u00e3o revelou os nomes dos envolvidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje (03\/04), por volta de 01h, Policiais Militares da 75\u00aa Companhia Independente de Pol\u00edcia Militar prenderam um homem por viol\u00eancia dom\u00e9stica no bairro Itaberaba em Juazeiro-BA. Durante rondas ostensivas, os militares receberam den\u00fancia do CICOM(Centro Integrado de Comunica\u00e7\u00f5es) informando sobre uma ocorr\u00eancia de viol\u00eancia dom\u00e9stica no bairro Itaberaba. De imediato os referidos policiais militares deslocaram [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":215226,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-239120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/09\/agressao-boa.jpeg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/239120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=239120"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/239120\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/215226"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=239120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=239120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=239120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}