{"id":239187,"date":"2018-04-04T09:09:23","date_gmt":"2018-04-04T12:09:23","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=239187"},"modified":"2018-04-04T09:09:23","modified_gmt":"2018-04-04T12:09:23","slug":"o-politico-nao-e-desonesto-o-eleitor-que-e-corrupto-veja-video","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/o-politico-nao-e-desonesto-o-eleitor-que-e-corrupto-veja-video\/","title":{"rendered":"O pol\u00edtico n\u00e3o \u00e9 desonesto, o eleitor que \u00e9 corrupto; veja v\u00eddeo"},"content":{"rendered":"<p>A pol\u00edtica no Brasil se transformou na mais verdadeira vergonha para muitas pessoas. Quem pensa que os culpados s\u00e3o apenas os pr\u00f3prios pol\u00edticos pelo que est\u00e1 acontecendo de ruim na sa\u00fade, educa\u00e7\u00e3o, infraestrutura, e outros, est\u00e1 enganado. Ainda assim, existem casos de corrup\u00e7\u00e3o, forma\u00e7\u00e3o de quadrilha, lavagem de dinheiro, etc., mas os principais culpados s\u00e3o os pr\u00f3prios eleitores, que na hora do voto extorqui o pol\u00edtico em dinheiro, material de constru\u00e7\u00e3o, exig\u00eancia de empregos para ele e a fam\u00edlia, e assim vai&#8230;<\/p>\n<p>Veja este exemplo no v\u00eddeo:<\/p>\n<p><iframe loading=\"lazy\" title=\"Pol\u00edtico n\u00e3o \u00e9 desonesto, o eleitor que \u00e9 corrupto\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/xt8HUXCjBKo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pol\u00edtica no Brasil se transformou na mais verdadeira vergonha para muitas pessoas. Quem pensa que os culpados s\u00e3o apenas os pr\u00f3prios pol\u00edticos pelo que est\u00e1 acontecendo de ruim na sa\u00fade, educa\u00e7\u00e3o, infraestrutura, e outros, est\u00e1 enganado. Ainda assim, existem casos de corrup\u00e7\u00e3o, forma\u00e7\u00e3o de quadrilha, lavagem de dinheiro, etc., mas os principais culpados s\u00e3o [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":189440,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-239187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/04\/reeleicao-comprada.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/239187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=239187"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/239187\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/189440"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=239187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=239187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=239187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}