{"id":239374,"date":"2018-04-06T05:50:02","date_gmt":"2018-04-06T08:50:02","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=239374"},"modified":"2018-04-06T05:50:02","modified_gmt":"2018-04-06T08:50:02","slug":"acidente-em-casa-nova","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/acidente-em-casa-nova\/","title":{"rendered":"Acidente em Casa Nova"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-239375\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/acidente-em-casa-nova-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/acidente-em-casa-nova-300x300.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/acidente-em-casa-nova-150x150.jpg 150w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/acidente-em-casa-nova-768x768.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/acidente-em-casa-nova-500x500.jpg 500w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/acidente-em-casa-nova-160x160.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/acidente-em-casa-nova-640x640.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/acidente-em-casa-nova-30x30.jpg 30w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/acidente-em-casa-nova-266x266.jpg 266w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/acidente-em-casa-nova.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>por volta das 18:30h desta quinta-feira (05) aconteceu um acidente defronta as Casinha no Distrito de santana do Sobrado, zona rural de Casa Nova. Um ve\u00edculo de passeio e uma moto se colidiram tendo como v\u00edtimas as pessoas de pr\u00e9-nomes Gleidimar e \u00cdtalo.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>por volta das 18:30h desta quinta-feira (05) aconteceu um acidente defronta as Casinha no Distrito de santana do Sobrado, zona rural de Casa Nova. Um ve\u00edculo de passeio e uma moto se colidiram tendo como v\u00edtimas as pessoas de pr\u00e9-nomes Gleidimar e \u00cdtalo. &nbsp;<\/p>\n","protected":false},"author":5,"featured_media":239375,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-239374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/acidente-em-casa-nova.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/239374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=239374"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/239374\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/239375"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=239374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=239374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=239374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}