{"id":239415,"date":"2018-04-06T08:00:55","date_gmt":"2018-04-06T11:00:55","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=239415"},"modified":"2018-04-06T08:00:55","modified_gmt":"2018-04-06T11:00:55","slug":"medico-acusado-de-estupro-e-investigado-por-mais-10-crimes","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/medico-acusado-de-estupro-e-investigado-por-mais-10-crimes\/","title":{"rendered":"M\u00e9dico acusado de estupro \u00e9 investigado por mais 10 crimes"},"content":{"rendered":"<header>\n<h1 class=\"titulo-noticia\"><\/h1>\n<p>Por\u00a0<strong>Raphael Guerra<\/strong>\u00a0<\/header>\n<div id=\"texto-noticia\" style=\"text-align: justify;\">\n<figure><\/figure>\n<figure id=\"attachment_4162\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4162 img-responsive \" src=\"http:\/\/imagens2.ne10.uol.com.br\/blogsjconline\/rondajc\/\/2018\/03\/kid.jpg\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" srcset=\"http:\/\/imagens2.ne10.uol.com.br\/blogsjconline\/rondajc\/2018\/03\/kid.jpg 700w, http:\/\/imagens2.ne10.uol.com.br\/blogsjconline\/rondajc\/2018\/03\/kid-300x182.jpg 300w, http:\/\/imagens2.ne10.uol.com.br\/blogsjconline\/rondajc\/2018\/03\/kid-675x410.jpg 675w\" alt=\"\" width=\"700\" height=\"425\" \/><figcaption>O m\u00e9dico ortopedista Kid N\u00e9lio est\u00e1 preso no Cotel. Foto: Cremepe\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p>A Pol\u00edcia Civil de Pernambuco confirmou que encaminhou \u00e0 Justi\u00e7a, na tarde dessa quarta-feira (04), a conclus\u00e3o do segundo inqu\u00e9rito que investigou den\u00fancia de abuso sexual praticada pelo\u00a0m\u00e9dico ortopedista e traumatologista Kid N\u00e9lio Souza de Melo, de 35 anos. Outros dez inqu\u00e9ritos continuam sob investiga\u00e7\u00e3o, todos relacionados a supostos crimes sexuais praticados pelo suspeito durante atendimentos na\u00a0Unidade de Pronto Atendimento (UPA) da Imbiribeira e em um hospital particular no Recife.<\/p>\n<p>O primeiro inqu\u00e9rito, conclu\u00eddo na semana passada, \u00e9 referente \u00e0 den\u00fancia de uma mulher de 18 anos que disse ter sido estuprada por Kid N\u00e9lio durante a consulta na UPA em 21 de fevereiro deste ano. A v\u00edtima, inclusive, afirmou \u00e0 pol\u00edcia que houve a conjun\u00e7\u00e3o carnal.\u00a0<a href=\"http:\/\/jc.ne10.uol.com.br\/blogs\/rondajc\/2018\/04\/03\/medico-acusado-de-estupros-de-pacientes-vai-para-o-banco-dos-reus\/\" target=\"_blank\" rel=\"noopener\">A Justi\u00e7a j\u00e1 acatou den\u00fancia do Minist\u00e9rio P\u00fablico de Pernambuco contra o m\u00e9dico.<\/a>\u00a0O processo est\u00e1 na 17\u00aa Vara Criminal da Capital. A informa\u00e7\u00e3o foi publicada em primeira m\u00e3o pelo\u00a0<strong>Ronda JC<\/strong>.<\/p>\n<p>Essa foi a primeira queixa contra o m\u00e9dico registrada na Delegacia da Mulher. A partir dela, outras 11 supostas v\u00edtimas procuraram a pol\u00edcia para denunci\u00e1-lo. Sete teriam sido abusadas sexualmente na UPA da Imbiribeira e quatro num hospital particular. A Pol\u00edcia Civil explicou que um inqu\u00e9rito foi aberto para cada queixa registrada.<\/p>\n<p>O m\u00e9dico est\u00e1 preso preventivamente no Centro de Observa\u00e7\u00e3o e Triagem (Cotel), em Abreu e Lima, desde o dia 02 de mar\u00e7o.<\/p>\n<p><strong>AS DEN\u00daNCIAS<\/strong><\/p>\n<p>As mulheres afirmaram \u00e0 pol\u00edcia que, durante os atendimentos, o m\u00e9dico pedia para que elas ficassem nuas \u2013 mesmo que, em algumas situa\u00e7\u00f5es, elas apresentassem problemas simples nos punhos ou nos p\u00e9s, por exemplo. Era nesse momento que os abusos eram praticados.\u00a0\u201cElas relatam que ficaram t\u00e3o mal, que n\u00e3o conseguiram gritar. Estavam travadas\u201d, afirmou a delegada Ana Elisa Sobreira, no dia da pris\u00e3o do acusado, h\u00e1 um m\u00eas. Segundo a Pol\u00edcia Civil, o acusado afirmou em depoimento que teve rela\u00e7\u00e3o sexual consentida com duas pacientes. Tamb\u00e9m negou que tenha estuprado as outras mulheres que o denunciaram.<\/p>\n<div id=\"smartIntxt\" class=\"publicidade-entre-texto\"><\/div>\n<p>O\u00a0<strong>Ronda JC<\/strong>\u00a0n\u00e3o conseguiu contato com a defesa do acusado.<\/p>\n<p><strong>PERFIL<\/strong><\/p>\n<p>Kid N\u00e9lio \u00e9 m\u00e9dico h\u00e1 nove anos. Ele se formou pela Universidade do Rio Grande do Norte e especializou-se na \u00e1rea de ortopedia e traumatologia, com \u00eanfase em cirurgias. Al\u00e9m da UPA da Imbiribeira, ele tamb\u00e9m trabalhava em cl\u00ednicas particulares.\u00a0O Conselho Regional de Medicina (Cremepe) abriu sindic\u00e2ncia para investigar a conduta do profissional, que pode perder o direito de exercer a profiss\u00e3o.<\/p>\n<p><strong>ESTAT\u00cdSTICAS<\/strong><\/p>\n<p>Entre os anos de 2007 e 2017, a Pol\u00edcia Civil de Pernambuco investigou 21 m\u00e9dicos suspeitos de crimes de estupro, no exerc\u00edcio da profiss\u00e3o. Do total de casos, seis foram registrados no Recife.\u00a0Dos 21 m\u00e9dicos investigados por estupro, tr\u00eas foram considerados como suspeitos pela pol\u00edcia. Os outros profissionais foram apontados como autores do crime. Outro dado que chama a aten\u00e7\u00e3o \u00e9 que, do total de m\u00e9dicos, quatro foram investigados por estupro de vulner\u00e1vel (quando as v\u00edtimas s\u00e3o menores de 14 anos ou, por qualquer outra causa, eram pessoas que n\u00e3o podiam oferecer resist\u00eancia).<\/p>\n<p>Somente no ano passado, tr\u00eas m\u00e9dicos foram denunciados \u00e0 pol\u00edcia por abuso sexual. Um dos casos ocorreu em fevereiro, no munic\u00edpio de Calumbi, no Sert\u00e3o do Estado. Os outros dois foram na Regi\u00e3o Metropolitana do Recife: um em Olinda e outro em Jaboat\u00e3o dos Guararapes.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por\u00a0Raphael Guerra\u00a0 O m\u00e9dico ortopedista Kid N\u00e9lio est\u00e1 preso no Cotel. Foto: Cremepe\/Divulga\u00e7\u00e3o A Pol\u00edcia Civil de Pernambuco confirmou que encaminhou \u00e0 Justi\u00e7a, na tarde dessa quarta-feira (04), a conclus\u00e3o do segundo inqu\u00e9rito que investigou den\u00fancia de abuso sexual praticada pelo\u00a0m\u00e9dico ortopedista e traumatologista Kid N\u00e9lio Souza de Melo, de 35 anos. Outros dez inqu\u00e9ritos [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":239416,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-239415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/kid.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/239415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=239415"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/239415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/239416"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=239415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=239415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=239415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}