{"id":239586,"date":"2018-04-08T08:55:57","date_gmt":"2018-04-08T11:55:57","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=239586"},"modified":"2018-04-08T08:59:09","modified_gmt":"2018-04-08T11:59:09","slug":"neocomunistas-comemoram-prisao-de-lula-em-uaua","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/neocomunistas-comemoram-prisao-de-lula-em-uaua\/","title":{"rendered":"Neocomunistas comemoram pris\u00e3o de Lula em Uau\u00e1"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-65077 size-full\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/06\/microfone.jpg\" alt=\"\" width=\"259\" height=\"194\" \/><\/p>\n<p>&#8220;Hoje em dia aparece cada comunista com cara de cominisso que d\u00e1 nojo a qualquer militante hist\u00f3rico. Aqui em Uau\u00e1, por exemplo, tem um rapazinho que se diz publicit\u00e1rio que cospe constantemente os microfones da R\u00e1dio Comunit\u00e1ria Luz do Sert\u00e3o, pois o mesmo ficou invocado com uma mat\u00e9ria que foi publicada nas redes sociais que falava sobre a desist\u00eancia de ACM Neto de ser candidato ao Governo da Bahia. Ele chegou a chamar a pessoa que publicou a mat\u00e9ria de &#8216;canalha&#8217;. Em outro epis\u00f3dio inusitado, ele e seu parceiro clandestino, no dia de ontem (07), usaram os meios de comunica\u00e7\u00f5es para comemorarem a pris\u00e3o do ex-presidente Lula. Este ato deixou muitas pessoas indignadas, inclusive lideran\u00e7as filiadas ao PT, mas parece que o prefeito da &#8216;mudan\u00e7a&#8217;, filiado ao PCdoB, se sentiu satisfeito porque ainda mant\u00e9m estas pessoas ligadas \u00e0 administra\u00e7\u00e3o cometendo tais atos. Caso fosse em Juazeiro, o prefeito Paulo Bomfim (PCdoB), j\u00e1 teria tomado uma decis\u00e3o no primeiro minuto. Outro fato \u00e9 a pr\u00e9-candidata \u00e0 presid\u00eancia rep\u00fablica, Manuela D&#8217;\u00c1vila do PCdoB ter feito parte do palanque de Lula ontem, sendo cortejado por ele, e ao mesmo tempo ela emocionada o beijou retribuindo suas manifesta\u00e7\u00f5es, e os neocomunistas de Uau\u00e1 ainda se comportarem dessa maneira lament\u00e1vel &#8220;. (Dondinha)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Hoje em dia aparece cada comunista com cara de cominisso que d\u00e1 nojo a qualquer militante hist\u00f3rico. Aqui em Uau\u00e1, por exemplo, tem um rapazinho que se diz publicit\u00e1rio que cospe constantemente os microfones da R\u00e1dio Comunit\u00e1ria Luz do Sert\u00e3o, pois o mesmo ficou invocado com uma mat\u00e9ria que foi publicada nas redes sociais que [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":65077,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-239586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/06\/microfone.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/239586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=239586"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/239586\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/65077"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=239586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=239586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=239586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}