{"id":239743,"date":"2018-04-09T08:37:46","date_gmt":"2018-04-09T11:37:46","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=239743"},"modified":"2018-04-09T08:37:46","modified_gmt":"2018-04-09T11:37:46","slug":"congestionamento-na-ponte","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/congestionamento-na-ponte\/","title":{"rendered":"Congestionamento na ponte"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-239744 size-full\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/congestionamento.jpg\" alt=\"\" width=\"956\" height=\"1280\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/congestionamento.jpg 956w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/congestionamento-224x300.jpg 224w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/congestionamento-768x1028.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/congestionamento-373x500.jpg 373w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/congestionamento-160x214.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/congestionamento-640x857.jpg 640w\" sizes=\"auto, (max-width: 956px) 100vw, 956px\" \/><\/p>\n<p>Um caminh\u00e3o est\u00e1 quebrado na Ponte Presidente Dutra no sentido Petrolina \u00e0 Juazeiro. Neste momento \u00e9 grande o congesionamento<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um caminh\u00e3o est\u00e1 quebrado na Ponte Presidente Dutra no sentido Petrolina \u00e0 Juazeiro. Neste momento \u00e9 grande o congesionamento<\/p>\n","protected":false},"author":5,"featured_media":239744,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-239743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/congestionamento.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/239743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=239743"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/239743\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/239744"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=239743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=239743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=239743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}