{"id":239848,"date":"2018-04-10T09:05:15","date_gmt":"2018-04-10T12:05:15","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=239848"},"modified":"2018-04-10T09:05:32","modified_gmt":"2018-04-10T12:05:32","slug":"senhor-do-bonfim-abandonada","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/senhor-do-bonfim-abandonada\/","title":{"rendered":"Senhor do Bonfim abandonada"},"content":{"rendered":"<p style=\"text-align: justify;\">Segundo o Blog al\u00f4 al\u00f4 Bonfim.com, os moradores algumas ruas do munic\u00edpio de Senhor do Bonfim est\u00e3o abandonadas, as escuras.\u00a0Moradores do Alto da Rainha est\u00e3o sofrendo, mas a conta de energia com a CIP (contribui\u00e7\u00e3o de ilumina\u00e7\u00e3o p\u00fablica) chega sempre todos os meses. Eles ainda alegam que,\u00a0 a Prefeitura n\u00e3o est\u00e1 trocando as lampadas dos postes.<\/p>\n<div id=\"box-info2\" style=\"text-align: justify;\">\n<div id=\"pos-autor\"><\/div>\n<div id=\"pos-bt-social\">\n<div class=\"a2a_kit a2a_kit_size_32 a2a_default_style\">\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"pos-text\" style=\"text-align: justify;\">\n<div class=\"figura\">\n<p><img decoding=\"async\" title=\"Senhor do Bonfim: Moradores do Alto da Rainha est\u00e3o com ruas as escuras, mas a conta de energia com a CIP (contribui\u00e7\u00e3o de ilumina\u00e7\u00e3o p\u00fablica) chega sempre.\" src=\"http:\/\/www.aloalobonfim.com\/thumbs.php?w=400&amp;h=h=250&amp;imagem=images\/noticias\/321\/WhatsApp%20Image%202018-04-05%20at%2018.13.21.jpeg\" width=\"400\" \/><\/p>\n<\/div>\n<p>Com isso, os moradores est\u00e3o com medo de sa\u00edrem a noite de suas casas. Outro local que se encontra abandonado pela administra\u00e7\u00e3o petista, segundo os pr\u00f3prios moradores, \u00e9 no bairro do Derba.<\/p>\n<\/div>\n<div style=\"text-align: justify;\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Segundo o Blog al\u00f4 al\u00f4 Bonfim.com, os moradores algumas ruas do munic\u00edpio de Senhor do Bonfim est\u00e3o abandonadas, as escuras.\u00a0Moradores do Alto da Rainha est\u00e3o sofrendo, mas a conta de energia com a CIP (contribui\u00e7\u00e3o de ilumina\u00e7\u00e3o p\u00fablica) chega sempre todos os meses. Eles ainda alegam que,\u00a0 a Prefeitura n\u00e3o est\u00e1 trocando as lampadas dos [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":239849,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-239848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/bonfim-escuro.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/239848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=239848"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/239848\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/239849"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=239848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=239848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=239848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}