{"id":239997,"date":"2018-04-11T17:26:46","date_gmt":"2018-04-11T20:26:46","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=239997"},"modified":"2018-04-11T17:26:46","modified_gmt":"2018-04-11T20:26:46","slug":"saae-comunica-falta-de-agua-em-alguns-bairros","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/saae-comunica-falta-de-agua-em-alguns-bairros\/","title":{"rendered":"SAAE comunica falta de \u00e1gua em alguns bairros\u00a0"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-72998\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/07\/agua-na-torneira2-300x170.jpg\" alt=\"\" width=\"300\" height=\"170\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/07\/agua-na-torneira2-300x170.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/07\/agua-na-torneira2-620x351.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/07\/agua-na-torneira2-1024x579.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>O Servi\u00e7o de \u00c1gua e Saneamento Ambiental &#8211; SAAE\/Juazeiro informa aos usu\u00e1rios dos bairros Santo Ant\u00f4nio, Maring\u00e1, Penha, Country Clube, Lomanto Junior, Alto da Maravilha e Jardim Vit\u00f3ria que o fornecimento de \u00e1gua nessas comunidades ser\u00e1 interrompido na pr\u00f3xima quinta feira (12) das 9h \u00e0s 15h. A paralisa\u00e7\u00e3o \u00e9 para a troca do rolamento da bomba 03 que fornece \u00e1gua para estes bairros.\u00a0Caso o servi\u00e7o seja conclu\u00eddo antes do tempo previsto abastecimento voltar\u00e1 \u00e0 normalidade.<\/p>\n<p>Ascom\/SAAE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Servi\u00e7o de \u00c1gua e Saneamento Ambiental &#8211; SAAE\/Juazeiro informa aos usu\u00e1rios dos bairros Santo Ant\u00f4nio, Maring\u00e1, Penha, Country Clube, Lomanto Junior, Alto da Maravilha e Jardim Vit\u00f3ria que o fornecimento de \u00e1gua nessas comunidades ser\u00e1 interrompido na pr\u00f3xima quinta feira (12) das 9h \u00e0s 15h. A paralisa\u00e7\u00e3o \u00e9 para a troca do rolamento da [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":75772,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-239997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/08\/saae-agua-torneira.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/239997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=239997"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/239997\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/75772"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=239997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=239997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=239997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}