{"id":240105,"date":"2018-04-12T12:14:12","date_gmt":"2018-04-12T15:14:12","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=240105"},"modified":"2018-04-12T12:14:12","modified_gmt":"2018-04-12T15:14:12","slug":"dois-corpos-encontrados-sem-vida-no-salitre","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/dois-corpos-encontrados-sem-vida-no-salitre\/","title":{"rendered":"Dois corpos encontrados sem vida no Salitre"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-223026\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/11\/iml-viatura-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/11\/iml-viatura-300x169.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/11\/iml-viatura-768x431.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/11\/iml-viatura-620x348.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/11\/iml-viatura-160x90.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/11\/iml-viatura-480x270.jpg 480w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/11\/iml-viatura-640x360.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/11\/iml-viatura.jpg 890w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Viol\u00eancia est\u00e1 campeando no Vale do S\u00e3o Francisco, ainda \u00e1 pouco dois corpos foram encontrados sem os sinais vitais, na localidade do S\u00e3o Gon\u00e7alo &#8211; Salitre, rabec\u00e3o a caminho.<\/p>\n<p>Fonte: IML<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viol\u00eancia est\u00e1 campeando no Vale do S\u00e3o Francisco, ainda \u00e1 pouco dois corpos foram encontrados sem os sinais vitais, na localidade do S\u00e3o Gon\u00e7alo &#8211; Salitre, rabec\u00e3o a caminho. Fonte: IML<\/p>\n","protected":false},"author":5,"featured_media":223026,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-240105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/11\/iml-viatura.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/240105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=240105"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/240105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/223026"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=240105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=240105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=240105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}