{"id":240295,"date":"2018-04-14T11:48:59","date_gmt":"2018-04-14T14:48:59","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=240295"},"modified":"2018-04-14T11:48:59","modified_gmt":"2018-04-14T14:48:59","slug":"rui-costa-e-seu-grupo-temeroso-com-reeleicao","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/rui-costa-e-seu-grupo-temeroso-com-reeleicao\/","title":{"rendered":"Rui Costa e seu grupo temeroso com reelei\u00e7\u00e3o"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-93632 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/11\/roberto-e-olimpio1-620x258.jpg\" alt=\"\" width=\"620\" height=\"258\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/11\/roberto-e-olimpio1-620x258.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/11\/roberto-e-olimpio1-300x125.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/11\/roberto-e-olimpio1-1024x426.jpg 1024w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>O governador Rui Costa foi limitado em n\u00e3o comemorar a relei\u00e7\u00e3o antes da hora depois da desist\u00eancia de ACM Neto (DEM). Depois que Z\u00e9 Ronaldo (DEM) pegou no bast\u00e3o, os cacos est\u00e3o come\u00e7ando a se juntarem &#8211; mas em parte -,\u00a0 isso porque o PSDB continua magoado e n\u00e3o aceita servir de escada para os Democratas. Se a situa\u00e7\u00e3o ficou ruim para os candidatos de oposi\u00e7\u00e3o, pior para os da situa\u00e7\u00e3o que n\u00e3o ter\u00e3o o mesmo poder de for\u00e7a para conseguir ajuda t\u00e3o esperada.<\/p>\n<p>Em Juazeiro, segundo pesquisas de controle interno, ACM Neto estava bem colocado nas pesquisas. Em outros munic\u00edpios da regi\u00e3o a exemplo de Uau\u00e1 a coisa caminha na mesma dire\u00e7\u00e3o devido aos constantes trope\u00e7os da administra\u00e7\u00e3o municipal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Rui Costa foi limitado em n\u00e3o comemorar a relei\u00e7\u00e3o antes da hora depois da desist\u00eancia de ACM Neto (DEM). Depois que Z\u00e9 Ronaldo (DEM) pegou no bast\u00e3o, os cacos est\u00e3o come\u00e7ando a se juntarem &#8211; mas em parte -,\u00a0 isso porque o PSDB continua magoado e n\u00e3o aceita servir de escada para os [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":93632,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-240295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/11\/roberto-e-olimpio1.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/240295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=240295"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/240295\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/93632"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=240295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=240295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=240295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}