{"id":240302,"date":"2018-04-14T13:01:57","date_gmt":"2018-04-14T16:01:57","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=240302"},"modified":"2018-04-15T14:09:42","modified_gmt":"2018-04-15T17:09:42","slug":"banco-do-nordeste-regulariza-r-17-bilhao-em-dividas-com-produtores-rurais-em-2018","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/banco-do-nordeste-regulariza-r-17-bilhao-em-dividas-com-produtores-rurais-em-2018\/","title":{"rendered":"Banco do Nordeste regulariza R$ 1,7 bilh\u00e3o em d\u00edvidas com produtores rurais em 2018"},"content":{"rendered":"<div class=\"content-banner-principal\" style=\"text-align: justify;\">\n<div class=\"container publicidade\">\n<div class=\"col-md-12\">\n<div id=\"div-gpt-ad-1502987812182-0\" data-google-query-id=\"CMDBj6KRutoCFdQlHwodWFwArQ\">\n<div id=\"div-gpt-ad-1502987812182-0_ad_container\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row main\" style=\"text-align: justify;\">\n<div class=\"container\">\n<section class=\"col-md-8 col-sm-8\">\n<article id=\"post-196145\" class=\"box-noticias box-interna\">\n<header>\n<figure><img decoding=\"async\" class=\"img-responsive\" title=\"\" src=\"http:\/\/imagens3.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/\/2017\/11\/bnb1-748x410.jpg\" alt=\"\" \/><\/figure>\n<\/header>\n<div class=\"content-noticia\">\n<div id=\"texto-noticia\">\n<p>O Banco do Nordeste regularizou, em 2018, mais de 18,4 mil opera\u00e7\u00f5es de d\u00edvidas rurais com base na Lei 13.340\/2016, em sua \u00e1rea de atua\u00e7\u00e3o (Regi\u00e3o Nordeste e norte dos Estados de Minas Gerais e Esp\u00edrito Santo).<\/p>\n<p>Entre liquida\u00e7\u00f5es e repactua\u00e7\u00f5es, o montante supera R$ 1,7 bilh\u00e3o. Os clientes beneficiados podem voltar a obter novos cr\u00e9ditos e realizar investimentos em suas propriedades.<\/p>\n<p>Segundo o banco, o instrumento permite que agricultores recebam descontos de at\u00e9 95% em d\u00edvidas contratadas at\u00e9 2011, podendo renegociar suas opera\u00e7\u00f5es para pagamento at\u00e9 o ano de 2030, com parcelas a partir de 2021. Os juros da renegocia\u00e7\u00e3o variam de 0,5% ao ano, para agricultores familiares, a 3,5% ao ano, para grandes produtores.<\/p>\n<div id=\"smartIntxt\" class=\"fixed_intext_sc_v1\"><\/div>\n<p>\u201cEsse \u00e9 o instrumento legal de regulariza\u00e7\u00e3o de d\u00edvidas mais abrangente nos \u00faltimos anos. O Banco tem feito todo o esfor\u00e7o necess\u00e1rio para mobilizar o maior n\u00famero de produtores beneficiados, efetivar as negocia\u00e7\u00f5es e contribuir, diretamente, para o fortalecimento das atividades econ\u00f4micas rurais, desde os pequenos at\u00e9 os grandes produtores da Regi\u00e3o\u201d, diz a gest\u00e3o.<\/p>\n<p>Em 2017, com base na Lei n\u00ba 13.340\/2016 e Resolu\u00e7\u00e3o CMN n\u00ba 4.591\/2017, o Banco regularizou 295.466 opera\u00e7\u00f5es. Desse total, 271.408 utilizaram recursos do FNE, num total de R$ 7,94 bilh\u00f5es em recupera\u00e7\u00e3o, que beneficiou cerca de 1 milh\u00e3o de pessoas.<\/p>\n<p>At\u00e9 o final do ano, o BNB espera superar o resultado obtido no exerc\u00edcio passado.<\/p>\n<\/div>\n<\/div>\n<\/article>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Banco do Nordeste regularizou, em 2018, mais de 18,4 mil opera\u00e7\u00f5es de d\u00edvidas rurais com base na Lei 13.340\/2016, em sua \u00e1rea de atua\u00e7\u00e3o (Regi\u00e3o Nordeste e norte dos Estados de Minas Gerais e Esp\u00edrito Santo).<\/p>\n<p>Entre liquida\u00e7\u00f5es e repactua\u00e7\u00f5es, o montante sup<\/p>\n","protected":false},"author":5,"featured_media":144408,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-240302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2016\/08\/agricultores.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/240302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=240302"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/240302\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/144408"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=240302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=240302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=240302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}