{"id":240766,"date":"2018-04-19T05:40:46","date_gmt":"2018-04-19T08:40:46","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=240766"},"modified":"2018-04-19T05:40:46","modified_gmt":"2018-04-19T08:40:46","slug":"coisa-estranha-2","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/coisa-estranha-2\/","title":{"rendered":"Coisa estranha"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-54996\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2014\/04\/Joaquim-Barbosa1-300x231-300x231.jpg\" alt=\"\" width=\"300\" height=\"231\" \/><\/p>\n<p>S\u00f3 no Brasil acontece isto. Joaquim Barbosa (ex-STF) foi atra\u00eddo para o PSB para ser candidato a presidente da Rep\u00fablica, mas n\u00e3o conhece sequer todos os membros da dire\u00e7\u00e3o do partido. Vai haver reuni\u00e3o espec\u00edfica para que ele seja \u201capresentado\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00f3 no Brasil acontece isto. Joaquim Barbosa (ex-STF) foi atra\u00eddo para o PSB para ser candidato a presidente da Rep\u00fablica, mas n\u00e3o conhece sequer todos os membros da dire\u00e7\u00e3o do partido. Vai haver reuni\u00e3o espec\u00edfica para que ele seja \u201capresentado\u201d.<\/p>\n","protected":false},"author":5,"featured_media":17089,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-240766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2013\/09\/joaquim-barbosa1.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/240766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=240766"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/240766\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/17089"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=240766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=240766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=240766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}